{"id":100043,"date":"2026-02-24T15:29:28","date_gmt":"2026-02-24T19:29:28","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=100043"},"modified":"2026-02-24T15:29:28","modified_gmt":"2026-02-24T19:29:28","slug":"parceria-do-governo-de-mt-representa-um-novo-momento-para-juina-afirma-prefeito","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/parceria-do-governo-de-mt-representa-um-novo-momento-para-juina-afirma-prefeito\/","title":{"rendered":"&#8220;Parceria do Governo de MT representa um novo momento para Ju\u00edna&#8221;, afirma prefeito"},"content":{"rendered":"<p>O prefeito de Ju\u00edna, Paulo Veronese, afirmou que a parceria com o Governo de Mato Grosso representa um novo momento de desenvolvimento para a cidade e a regi\u00e3o Noroeste. A afirma\u00e7\u00e3o foi feita nesta ter\u00e7a-feira (24.2), durante agenda da comitiva do Estado, com entregas e an\u00fancio de mais de R$ 55,3 milh\u00f5es em novos investimentos para o munic\u00edpio.<\/p>\n<p>\u201cA popula\u00e7\u00e3o de Ju\u00edna reconhece os feitos da gest\u00e3o estadual. Se hoje a cidade consegue crescer, \u00e9 porque o Estado firmou parcerias para desenvolver a nossa cidade. Como gestor, sempre fui atendido pelo Estado nas demandas do munic\u00edpio. Hoje, o Estado \u00e9 um exemplo para os prefeitos, pela diferen\u00e7a que tem feito em Ju\u00edna e na regi\u00e3o. Somos gratos por tudo que j\u00e1 foi feito. Ju\u00edna cresceu e se desenvolveu com as parcerias do governo\u201d, destacou.<\/p>\n<p>Nos \u00faltimos sete anos, o munic\u00edpio de Ju\u00edna recebeu mais de R$ 511,5 milh\u00f5es em obras e a\u00e7\u00f5es com recursos do Estado.<\/p>\n<p>\u201cGovernar um Estado t\u00e3o grande, com tantas demandas e desafios, n\u00e3o \u00e9 simples. A gest\u00e3o enfrentou dificuldades e tomou decis\u00f5es dif\u00edceis de serem tomadas, mas necess\u00e1rias, porque n\u00e3o existe rem\u00e9dio f\u00e1cil. Estamos devolvendo uma parte desse dinheiro para os munic\u00edpios e estamos vendo o resultado em pouco tempo: coisas inimagin\u00e1veis come\u00e7aram a acontecer no Estado\u201d, afirmou o governador Mauro Mendes.<\/p>\n<figure class=\"image\"><picture data-fileentryid=\"77535791\"><source srcset=\"\/o\/adaptive-media\/image\/77535791\/Thumbnail-1024x1024\/WhatsApp+Image+2026-02-24+at+10.42.35.jpeg?t=1771959051619\" media=\"(max-width:1024px)\" \/><img decoding=\"async\" src=\"https:\/\/www.secom.mt.gov.br\/documents\/d\/mt\/whatsapp-image-2026-02-24-at-10-42-35-jpeg?imageThumbnail=3\" alt=\"\" height=\"267\" \/><\/picture><figcaption><sup>Foto: Tonico Pinheiro\/Secom-MT<\/sup><\/figcaption><\/figure>\n<p>O secret\u00e1rio-chefe da Casa Civil, F\u00e1bio Garcia, ressaltou que os investimentos representam a supera\u00e7\u00e3o de um hist\u00f3rico de car\u00eancias na regi\u00e3o.<\/p>\n<p>\u201cViver em Ju\u00edna era um desafio. Ap\u00f3s d\u00e9cadas de abandono e falta de investimentos, o atual governo paga uma d\u00edvida hist\u00f3rica com essas obras e entregas, sonhadas por muito tempo pela popula\u00e7\u00e3o. Essa gest\u00e3o est\u00e1 devolvendo o Estado para cada mato-grossense e, com isso, essa regi\u00e3o vai ser uma das mais promissoras do Estado\u201d, declarou.<\/p>\n<p><strong>Entregas e novas obras para Ju\u00edna<\/strong><\/p>\n<p>Durante a agenda em Ju\u00edna, a comitiva estadual, liderada pelo governador Mauro Mendes, vistoriou as obras do Hospital Regional de Ju\u00edna, anunciou investimentos para habita\u00e7\u00e3o, educa\u00e7\u00e3o, agricultura familiar e infraestrutura.<\/p>\n<figure class=\"image\"><picture data-fileentryid=\"77536055\"><source srcset=\"\/o\/adaptive-media\/image\/77536055\/Thumbnail-1024x1024\/WhatsApp+Image+2026-02-22+at+10.04.04.jpeg?t=1771959247311\" media=\"(max-width:1024px)\" \/><img decoding=\"async\" src=\"https:\/\/www.secom.mt.gov.br\/documents\/d\/mt\/whatsapp-image-2026-02-22-at-10-04-04-jpeg?imageThumbnail=3\" alt=\"\" height=\"267\" \/><\/picture><figcaption><sup>Obras do Hospital Regional de Ju\u00edna. Foto: Tonico Pinheiro\/Secom-MT<\/sup><\/figcaption><\/figure>\n<p>O maior deles ser\u00e1 para a constru\u00e7\u00e3o de duas unidades do Col\u00e9gio Estadual Integrado (CEI). Uma delas, que receber\u00e1 o nome de CEI Tiradentes Padre Ezequiel Ramin, contar\u00e1 com investimento de R$ 22,2 milh\u00f5es. A outra unidade ser\u00e1 constru\u00edda no bairro Flamboyant, com aporte de R$ 21,5 milh\u00f5es.<\/p>\n<p>Tamb\u00e9m foi assinada ordem de servi\u00e7o para a constru\u00e7\u00e3o de uma ponte de concreto sobre o rio Perdido, obra or\u00e7ada em R$ 5,2 milh\u00f5es, que deve melhorar a mobilidade na zona rural.<\/p>\n<p>O Governo concedeu ainda subs\u00eddio para 202 fam\u00edlias que ir\u00e3o adquirir im\u00f3veis nos residenciais Diamante I, Santo Anast\u00e1cio I e II, em um investimento de R$ 5,05 milh\u00f5es, pelo programa SER Fam\u00edlia Habita\u00e7\u00e3o.<\/p>\n<p>Na \u00e1rea rural, foram entregues m\u00e1quinas para fortalecer a agricultura familiar, com investimento de R$ 1,1 milh\u00e3o, al\u00e9m da entrega de 226 t\u00edtulos definitivos de casa pr\u00f3pria a fam\u00edlias do munic\u00edpio.<\/p>\n<p>\u201cO governo tem investido n\u00e3o s\u00f3 na regi\u00e3o noroeste, mas em todo o Estado de Mato Grosso. S\u00e3o grandes investimentos que colocaram o Estado como o que mais tem se desenvolvido no pa\u00eds. O governo ser\u00e1 uma refer\u00eancia internacional nos pr\u00f3ximos anos pela aplica\u00e7\u00e3o transparente e eficiente de seus recursos\u201d, pontuou o deputado estadual Chico Guarnieri.<\/p>\n<figure class=\"image\"><picture data-fileentryid=\"77536044\"><source srcset=\"\/o\/adaptive-media\/image\/77536044\/Thumbnail-1024x1024\/WhatsApp+Image+2026-02-24+at+12.17.01.jpeg?t=1771959154357\" media=\"(max-width:1024px)\" \/><img decoding=\"async\" src=\"https:\/\/www.secom.mt.gov.br\/documents\/d\/mt\/whatsapp-image-2026-02-24-at-12-17-01-jpeg?imageThumbnail=3\" alt=\"\" height=\"267\" \/><\/picture><figcaption><sup>Entrega de t\u00edtulos da casa pr\u00f3pria. Foto: Tonico Pinheiro\/Secom-MT<\/sup><\/figcaption><\/figure>\n<p><strong>Dispositivo<\/strong><\/p>\n<p>Participaram da solenidade em Ju\u00edna os deputados estaduais Dilmar Dal Bosco, Beto Dois a Um, Paulo Ara\u00fajo, Valmir Moretto, Diego Guimar\u00e3es e Sebasti\u00e3o Rezende; os secret\u00e1rios estaduais coronel PM C\u00e9sar Roveri (Seguran\u00e7a P\u00fablica) e Jordan Esp\u00edndola (Governadoria); o presidente do Instituto de Terras de Mato Grosso, Francisco Serafim; o presidente da MT Participa\u00e7\u00f5es e Projetos (MT Par), Wener Santos, al\u00e9m de vereadores e autoridades de Castanheira e regi\u00e3o noroeste.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 \u00a0|\u00a0 Foto:\u00a0 Tonico Pinheiro\/Secom-MT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Ju\u00edna, Paulo Veronese, afirmou que a parceria com o Governo de Mato &hellip;<\/p>\n","protected":false},"author":4,"featured_media":100044,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-100043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Munic\u00edpio recebeu entregas de a\u00e7\u00f5es e an\u00fancio de mais de R$ 55,3 milh\u00f5es em novos investimentos nesta ter\u00e7a-feira (23)","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/100043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=100043"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/100043\/revisions"}],"predecessor-version":[{"id":100045,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/100043\/revisions\/100045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/100044"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=100043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=100043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=100043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}