{"id":100068,"date":"2026-02-25T09:21:05","date_gmt":"2026-02-25T13:21:05","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=100068"},"modified":"2026-02-25T09:21:05","modified_gmt":"2026-02-25T13:21:05","slug":"policia-militar-realiza-entrega-de-homenagens-e-promove-palestra-de-saude-mental","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/policia-militar-realiza-entrega-de-homenagens-e-promove-palestra-de-saude-mental\/","title":{"rendered":"Pol\u00edcia Militar realiza entrega de homenagens e promove palestra de sa\u00fade mental"},"content":{"rendered":"<p>A Pol\u00edcia Militar de Mato Grosso, por meio do 3\u00ba Batalh\u00e3o, realizou, na manh\u00e3 desta ter\u00e7a-feira (24.2), a entrega de quatorze certificados de Honra ao M\u00e9rito para policiais militares que atuaram de forma r\u00e1pida em duas a\u00e7\u00f5es de policiamento t\u00e1tico e ostensivo no combate \u00e0 criminalidade, em Cuiab\u00e1.<\/p>\n<p>No dia 11 de fevereiro, policiais militares do 3\u00ba e 24\u00ba Batalh\u00e3o conduziram cinco homens e um adolescente \u00e0 delegacia, suspeitos de tentativa de roubo, sequestro e c\u00e1rcere privado contra uma fam\u00edlia, no bairro Santa Cruz II. Com eles, foram recolhidos dois rev\u00f3lveres e 12 muni\u00e7\u00f5es. As equipes ainda recuperaram R$ 7.684 em esp\u00e9cie.<\/p>\n<p>J\u00e1 no dia 16, a PMMT localizou e identificou um suspeito de feminic\u00eddio no bairro Liberdade, em Cuiab\u00e1. Ap\u00f3s o crime, as equipes receberam informa\u00e7\u00f5es de que ele foi at\u00e9 a resid\u00eancia da filha, com a inten\u00e7\u00e3o de cometer uma nova a\u00e7\u00e3o criminosa. Ao ser localizado, durante uma tentativa de abordagem, o suspeito morreu em confronto com um militar da Rotam. Com ele, foi apreendido um rev\u00f3lver calibre .38 e muni\u00e7\u00f5es.<\/p>\n<p>O comandante-geral da Pol\u00edcia Militar de Mato Grosso, coronel Cl\u00e1udio Fernando Carneiro Tinoco, destacou que a a\u00e7\u00e3o \u00e1gil das equipes foi fundamental para garantir a integridade das v\u00edtimas e restabelecer a ordem p\u00fablica.<\/p>\n<p>&#8220;A resposta imediata da corpora\u00e7\u00e3o demonstra o comprometimento com a seguran\u00e7a e o enfrentamento firme \u00e0 criminalidade. Nossos policiais agiram com t\u00e9cnica, estrat\u00e9gia e rapidez, evitando que a situa\u00e7\u00e3o tivesse consequ\u00eancias ainda mais graves. Esse resultado refor\u00e7a a import\u00e2ncia do policiamento ostensivo e da pronta resposta \u00e0s ocorr\u00eancias. Esta \u00e9 apenas uma homenagem para demonstrar nosso total respeito e admira\u00e7\u00e3o aos policiais.&#8221;<\/p>\n<p>Na solenidade desta ter\u00e7a, houve ainda uma palestra com o pastor Douglas Mariano Faria de Souza, representante do programa Universal nas For\u00e7as Policiais (UFP) de Mato Grosso, com o tema &#8220;Emo\u00e7\u00e3o versus raz\u00e3o: o que influencia na vida de uma pessoa?&#8221;. O grupo atua oferecendo assist\u00eancia espiritual, social e valoriza\u00e7\u00e3o humana a integrantes das for\u00e7as de seguran\u00e7a, For\u00e7as Armadas e seus familiares.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Militar de Mato Grosso, por meio do 3\u00ba Batalh\u00e3o, realizou, na manh\u00e3 desta &hellip;<\/p>\n","protected":false},"author":4,"featured_media":100069,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-100068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Militares foram reconhecimentos com certificados de Honra ao M\u00e9rito","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/100068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=100068"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/100068\/revisions"}],"predecessor-version":[{"id":100070,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/100068\/revisions\/100070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/100069"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=100068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=100068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=100068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}