{"id":100163,"date":"2026-03-04T14:36:42","date_gmt":"2026-03-04T18:36:42","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=100163"},"modified":"2026-03-04T14:36:42","modified_gmt":"2026-03-04T18:36:42","slug":"governador-convoca-1-122-novos-agentes-para-a-seguranca-publica","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/governador-convoca-1-122-novos-agentes-para-a-seguranca-publica\/","title":{"rendered":"Governador convoca 1.122 novos agentes para a Seguran\u00e7a P\u00fablica"},"content":{"rendered":"<p>O governador Mauro Mendes anunciou a convoca\u00e7\u00e3o de 1.122 novos profissionais para refor\u00e7ar as for\u00e7as de Seguran\u00e7a P\u00fablica de Mato Grosso.<\/p>\n<p>A decis\u00e3o foi oficializada nesta quarta-feira (04\/03), ap\u00f3s reuni\u00e3o com o vice-governador Otaviano Pivetta e a c\u00fapula da Seguran\u00e7a P\u00fablica.<\/p>\n<p>Do total de convocados, 369 s\u00e3o para a Pol\u00edcia Militar, 235 para a Pol\u00edcia Civil, 349 para o Corpo de Bombeiros, 141 para a Per\u00edcia Oficial e Identifica\u00e7\u00e3o T\u00e9cnica (Politec), 22 para a Secretaria de Seguran\u00e7a P\u00fablica (Sesp), 5 para o Centro Integrado de Opera\u00e7\u00f5es de Seguran\u00e7a P\u00fablica (Ciosp) e 1 para o Centro Integrado de Opera\u00e7\u00f5es A\u00e9reas (Ciopaer).<\/p>\n<p>Com o novo chamamento, o total de servidores incorporados \u00e0s for\u00e7as de seguran\u00e7a desde 2019 chegar\u00e1 a mais de 4.200 profissionais.<\/p>\n<p>Para o governador Mauro Mendes, a convoca\u00e7\u00e3o representa mais um passo para tornar Mato Grosso um estado cada vez mais seguro e com toler\u00e2ncia zero contra o crime.<\/p>\n<p>\u201cEstamos ampliando o n\u00famero de profissionais que ser\u00e3o chamados nos concursos j\u00e1 realizados. Eles v\u00e3o passar por treinamento e qualifica\u00e7\u00e3o para somar com os homens e mulheres que j\u00e1 atuam nas institui\u00e7\u00f5es e oferecer um servi\u00e7o de seguran\u00e7a p\u00fablica com mais qualidade e efetividade para todos os mato-grossenses. Mais uma a\u00e7\u00e3o para apertar o cerco contra a bandidagem\u201d, destacou.<\/p>\n<p>O vice-governador Otaviano Pivetta ressaltou que a medida refor\u00e7a a estrutura das for\u00e7as de seguran\u00e7a e amplia a qualidade dos servi\u00e7os prestados \u00e0 popula\u00e7\u00e3o.<\/p>\n<p>\u201c\u00c9 um momento de comemora\u00e7\u00e3o dessa decis\u00e3o importante que ajuda Mato Grosso a continuar se desenvolvendo e trazendo mais seguran\u00e7a para as fam\u00edlias de todos os cantos do estado\u201d, afirmou.<\/p>\n<p>Segundo o secret\u00e1rio de Estado de Seguran\u00e7a P\u00fablica, coronel C\u00e9sar Roveri, a convoca\u00e7\u00e3o faz parte de um esfor\u00e7o cont\u00ednuo da atual gest\u00e3o para estruturar as for\u00e7as de seguran\u00e7a e ampliar a presen\u00e7a do Estado em todas as regi\u00f5es, especialmente no interior.<\/p>\n<p>\u201cJ\u00e1 chamamos cerca de 3 mil servidores desde 2019 e, com esse novo chamamento, vamos chegar perto de 4 mil profissionais incorporados \u00e0 Seguran\u00e7a P\u00fablica. Esse refor\u00e7o \u00e9 importante para suprir defici\u00eancias em alguns munic\u00edpios e tamb\u00e9m para ampliar servi\u00e7os como as novas unidades do Corpo de Bombeiros e da Politec no interior\u201d, afirmou.<\/p>\n<p>Na Pol\u00edcia Militar, os novos profissionais ir\u00e3o refor\u00e7ar o policiamento ostensivo e contribuir para ampliar a capacidade operacional da corpora\u00e7\u00e3o nos munic\u00edpios.<\/p>\n<p>\u201cMuitos deles ir\u00e3o refor\u00e7ar o interior e tamb\u00e9m compor unidades especializadas, fortalecendo o combate firme \u00e0s fac\u00e7\u00f5es criminosas no estado\u201d, destacou o comandante-geral da PM, coronel Fernando Tinoco.<\/p>\n<p>A Pol\u00edcia Civil tamb\u00e9m deve direcionar parte do novo efetivo para cidades do interior, com foco na amplia\u00e7\u00e3o das investiga\u00e7\u00f5es e no fortalecimento de estruturas especializadas.<\/p>\n<p>\u201cEsses novos policiais ser\u00e3o lotados prioritariamente no interior e v\u00e3o refor\u00e7ar o combate \u00e0s fac\u00e7\u00f5es criminosas. Tamb\u00e9m v\u00e3o fortalecer nossas unidades de atendimento \u00e0s mulheres, especialmente nas cidades do interior do estado\u201d, explicou a delegada-geral da institui\u00e7\u00e3o, Daniela Maidel.<\/p>\n<p>No Corpo de Bombeiros Militar, o refor\u00e7o permitir\u00e1 acelerar o plano de expans\u00e3o da corpora\u00e7\u00e3o, com a instala\u00e7\u00e3o de novas unidades em munic\u00edpios que ainda n\u00e3o contam com atendimento direto.<\/p>\n<p>\u201cEsse refor\u00e7o no efetivo vai contribuir com o planejamento de expans\u00e3o do Corpo de Bombeiros, com novas unidades no interior. Hoje temos munic\u00edpios muito distantes das unidades existentes e a meta \u00e9 reduzir significativamente essa dist\u00e2ncia, garantindo atendimento mais r\u00e1pido \u00e0 popula\u00e7\u00e3o\u201d, afirmou o comandante-geral adjunto da corpora\u00e7\u00e3o, coronel Rony Barros.<\/p>\n<p>J\u00e1 na Politec, a amplia\u00e7\u00e3o do quadro de servidores permitir\u00e1 levar servi\u00e7os periciais e de medicina legal para novas regi\u00f5es, reduzindo a necessidade de deslocamentos longos para atendimento.<\/p>\n<p>\u201cEsse refor\u00e7o \u00e9 importante para que possamos expandir o servi\u00e7o de medicina legal para novas unidades no interior, levando atendimento mais pr\u00f3ximo da popula\u00e7\u00e3o e especialmente das mulheres v\u00edtimas de viol\u00eancia\u201d, ressaltou o diretor adjunto da Politec, Renato Sim\u00f5es.<\/p>\n<p>Os novos profissionais convocados ser\u00e3o incorporados \u00e0s institui\u00e7\u00f5es conforme o cronograma de forma\u00e7\u00e3o e os tr\u00e2mites administrativos necess\u00e1rios para o ingresso no servi\u00e7o p\u00fablico.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 |\u00a0 Foto:\u00a0 Mayke Toscano\/Secom<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Mauro Mendes anunciou a convoca\u00e7\u00e3o de 1.122 novos profissionais para refor\u00e7ar as for\u00e7as &hellip;<\/p>\n","protected":false},"author":4,"featured_media":100164,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-100163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Com o novo chamamento, ser\u00e3o mais de 4.000 agentes incorporados \u00e0 Seguran\u00e7a desde 2019","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/100163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=100163"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/100163\/revisions"}],"predecessor-version":[{"id":100165,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/100163\/revisions\/100165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/100164"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=100163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=100163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=100163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}