{"id":100211,"date":"2026-03-05T10:14:18","date_gmt":"2026-03-05T14:14:18","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=100211"},"modified":"2026-03-05T10:14:18","modified_gmt":"2026-03-05T14:14:18","slug":"policia-civil-desarticula-nucleo-familiar-envolvido-com-trafico-de-drogas-e-lavagem-de-dinheiro-de-faccao-no-norte-de-mt","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/policia-civil-desarticula-nucleo-familiar-envolvido-com-trafico-de-drogas-e-lavagem-de-dinheiro-de-faccao-no-norte-de-mt\/","title":{"rendered":"Pol\u00edcia Civil desarticula n\u00facleo familiar envolvido com tr\u00e1fico de drogas e lavagem de dinheiro de fac\u00e7\u00e3o no norte de MT"},"content":{"rendered":"<p>A Pol\u00edcia Civil de Mato Grosso deflagrou, na manh\u00e3 desta quinta-feira (5.3), a Opera\u00e7\u00e3o Showdown, para cumprimento de 31 ordens judiciais contra um n\u00facleo familiar ligado a uma fac\u00e7\u00e3o criminosa envolvida com tr\u00e1fico de drogas, lavagem de dinheiro, divulga\u00e7\u00e3o de jogos de azar entre outros crimes na regi\u00e3o norte do Estado.<\/p>\n<p>S\u00e3o cumpridos, na opera\u00e7\u00e3o, quatro mandados de pris\u00e3o, sete mandados de busca e apreens\u00e3o, seis sequestros de ve\u00edculos, quatro sequestros de im\u00f3veis, sete bloqueios de contas banc\u00e1rias e tr\u00eas suspens\u00f5es de pessoa jur\u00eddica, expedidos pela 5\u00aa Vara Criminal de Sinop, nas cidades de Alta Floresta e Nova Bandeirantes.<\/p>\n<picture data-fileentryid=\"77702831\"><source srcset=\"\/o\/adaptive-media\/image\/77702831\/Thumbnail-1024x1024\/WhatsApp+Image+2026-03-05+at+05.40.53.jpeg?t=1772705615749\" media=\"(max-width:898px)\" \/><img decoding=\"async\" src=\"https:\/\/www.pjc.mt.gov.br\/documents\/d\/pjc\/whatsapp-image-2026-03-05-at-05-40-53-jpeg-1?imageThumbnail=3\" alt=\"\" height=\"266\" \/><\/picture>\n<p>As ordens judiciais foram decretadas com base em investiga\u00e7\u00f5es conduzidas em inqu\u00e9rito policial conjunto da Ger\u00eancia de Combate ao Crime Organizado (GCCO), da Delegacia Especializada de Repress\u00e3o ao Crime Organizado (Draco) de Cuiab\u00e1 e da Delegacia de Alta Floresta.<\/p>\n<p>O cumprimento das ordens judiciais conta com o apoio das equipes da Delegacia de Alta Floresta, da Delegacia de Nova Bandeirantes e do Centro Integrado de Opera\u00e7\u00f5es A\u00e9reas (Ciopaer).<\/p>\n<picture data-fileentryid=\"77702853\"><source srcset=\"\/o\/adaptive-media\/image\/77702853\/Thumbnail-1024x1024\/WhatsApp+Image+2026-03-05+at+06.15.35.jpeg?t=1772705825236\" media=\"(max-width:957px)\" \/><img decoding=\"async\" src=\"https:\/\/www.pjc.mt.gov.br\/documents\/d\/pjc\/whatsapp-image-2026-03-05-at-06-15-35-jpeg?imageThumbnail=3\" alt=\"\" height=\"266\" \/><\/picture>\n<p>&nbsp;<\/p>\n<p><strong>N\u00facleo familiar<\/strong><\/p>\n<p>A investiga\u00e7\u00e3o tem como alvo principal uma mulher apontada como lideran\u00e7a de uma fac\u00e7\u00e3o criminosa na cidade de Alta Floresta. Considerada de alta periculosidade, a faccionada est\u00e1 foragida do Sistema Prisional desde agosto de 2025, quando fugiu do Pres\u00eddio Ana Maria do Couto May, em Cuiab\u00e1.<\/p>\n<p>Al\u00e9m dela, familiares pr\u00f3ximos da investigada, como o pai, a filha da foragida e o marido, tamb\u00e9m s\u00e3o alvos da opera\u00e7\u00e3o. Eles s\u00e3o apontados como operadores financeiros do grupo criminoso, atuando na lavagem de dinheiro adquirido com o tr\u00e1fico de drogas administrado pela fac\u00e7\u00e3o criminosa.<\/p>\n<picture data-fileentryid=\"77702842\"><source srcset=\"\/o\/adaptive-media\/image\/77702842\/Thumbnail-1024x1024\/WhatsApp+Image+2026-03-05+at+06.12.54.jpeg?t=1772705694201\" media=\"(max-width:1024px)\" \/><img decoding=\"async\" src=\"https:\/\/www.pjc.mt.gov.br\/documents\/d\/pjc\/whatsapp-image-2026-03-05-at-06-12-54-jpeg?imageThumbnail=3\" alt=\"\" height=\"266\" \/><\/picture>\n<p>&nbsp;<\/p>\n<p>Os alvos s\u00e3o investigados por movimentar valores incompat\u00edveis com a renda declarada e por administrar empresas utilizadas para dar apar\u00eancia l\u00edcita ao dinheiro obtido de forma ilegal.<\/p>\n<p><strong>Lavagem de dinheiro<\/strong><\/p>\n<p>As investiga\u00e7\u00f5es apontaram que, no per\u00edodo de um ano e sete meses, o grupo familiar teria movimentado mais de R$ 20 milh\u00f5es relacionados \u00e0s atividades do tr\u00e1fico, uma vez que os valores s\u00e3o totalmente incompat\u00edveis com a renda declarada.<\/p>\n<p>O grupo utilizava diversos mecanismos para lavagem de dinheiro, como empresas de fachada dos seguintes ramos: cal\u00e7ados, beleza e roupas multimarcas, al\u00e9m do uso de plataformas digitais de jogos de azar on-line, que, posteriormente, eram apresentados como ganhos leg\u00edtimos.<\/p>\n<picture data-fileentryid=\"77702797\"><source srcset=\"\/o\/adaptive-media\/image\/77702797\/Thumbnail-1024x1024\/WhatsApp+Image+2026-03-05+at+06.03.17.jpeg?t=1772705304066\" media=\"(max-width:1024px)\" \/><img decoding=\"async\" src=\"https:\/\/www.pjc.mt.gov.br\/documents\/d\/pjc\/whatsapp-image-2026-03-05-at-06-03-17-jpeg?imageThumbnail=3\" alt=\"\" height=\"266\" \/><\/picture>\n<p>Outro bra\u00e7o do esquema envolveria a explora\u00e7\u00e3o de garimpo irregular na regi\u00e3o de Alta Floresta. Sob comando direto da filha, o pai da l\u00edder da fac\u00e7\u00e3o seria o respons\u00e1vel por gerenciar o garimpo e um bar e prost\u00edbulo pr\u00f3ximo \u00e0 cidade de Nova Bandeirantes.<\/p>\n<p>O local tamb\u00e9m serviria de apoio para extors\u00f5es a garimpeiros e pr\u00e1tica de tr\u00e1fico de drogas. O ouro extra\u00eddo poderia ser utilizado como forma de ocultar e reinserir recursos il\u00edcitos no mercado formal, dificultando o rastreamento financeiro.<\/p>\n<picture data-fileentryid=\"77702808\"><source srcset=\"\/o\/adaptive-media\/image\/77702808\/Thumbnail-1024x1024\/WhatsApp+Image+2026-03-05+at+05.59.08.jpeg?t=1772705340170\" media=\"(max-width:894px)\" \/><img decoding=\"async\" src=\"https:\/\/www.pjc.mt.gov.br\/documents\/d\/pjc\/whatsapp-image-2026-03-05-at-05-59-08-jpeg?imageThumbnail=3\" alt=\"\" height=\"266\" \/><\/picture>\n<p><strong>Vida de luxo<\/strong><\/p>\n<p>A filha e o genro da l\u00edder da fac\u00e7\u00e3o ostentam uma vida extremamente luxuosa, com compras de im\u00f3veis, carros de luxo e viagens internacionais. A jovem possui um perfil no Instagram com mais de 40 mil seguidores, onde compartilha detalhes da sua rotina e suas aquisi\u00e7\u00f5es.<\/p>\n<picture data-fileentryid=\"77702864\"><source srcset=\"\/o\/adaptive-media\/image\/77702864\/Thumbnail-1024x1024\/WhatsApp+Image+2026-03-05+at+06.19.10.jpeg?t=1772705989492\" media=\"(max-width:1024px)\" \/><img decoding=\"async\" src=\"https:\/\/www.pjc.mt.gov.br\/documents\/d\/pjc\/whatsapp-image-2026-03-05-at-06-19-10-jpeg?imageThumbnail=3\" alt=\"\" height=\"266\" \/><\/picture>\n<p><strong>Nome da opera\u00e7\u00e3o<\/strong><\/p>\n<p>O nome faz refer\u00eancia a uma jogada de p\u00f4quer na qual os jogadores mostram as cartas, em alus\u00e3o aos jogos de azar, pr\u00e1tica utilizada pelo n\u00facleo da fac\u00e7\u00e3o para a lavagem de dinheiro.<\/p>\n<p>A opera\u00e7\u00e3o integra os trabalhos do planejamento estrat\u00e9gico da Pol\u00edcia Civil de Mato Grosso para o ano de 2026, por meio da Opera\u00e7\u00e3o Pharus, dentro do Programa Toler\u00e2ncia Zero, voltado ao combate \u00e0s fac\u00e7\u00f5es criminosas em todo o Estado.<\/p>\n<picture data-fileentryid=\"77702886\"><source srcset=\"\/o\/adaptive-media\/image\/77702886\/Thumbnail-1024x1024\/WhatsApp+Image+2026-03-05+at+06.09.35+%281%29.jpeg?t=1772706066432\" media=\"(max-width:947px)\" \/><img decoding=\"async\" src=\"https:\/\/www.pjc.mt.gov.br\/documents\/d\/pjc\/whatsapp-image-2026-03-05-at-06-09-35-1-jpeg?imageThumbnail=3\" alt=\"\" height=\"266\" \/><\/picture>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil de Mato Grosso deflagrou, na manh\u00e3 desta quinta-feira (5.3), a Opera\u00e7\u00e3o Showdown, &hellip;<\/p>\n","protected":false},"author":4,"featured_media":100212,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-100211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Entre os alvos, est\u00e3o a l\u00edder da fac\u00e7\u00e3o em Alta Floresta e regi\u00e3o, al\u00e9m do seu pai, sua filha e o seu genro","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/100211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=100211"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/100211\/revisions"}],"predecessor-version":[{"id":100213,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/100211\/revisions\/100213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/100212"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=100211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=100211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=100211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}