{"id":100348,"date":"2026-03-12T14:48:52","date_gmt":"2026-03-12T18:48:52","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=100348"},"modified":"2026-03-12T14:48:52","modified_gmt":"2026-03-12T18:48:52","slug":"credito-da-desenvolve-mt-viabiliza-expansao-de-pizzaria-cuiabana","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/credito-da-desenvolve-mt-viabiliza-expansao-de-pizzaria-cuiabana\/","title":{"rendered":"Cr\u00e9dito da Desenvolve MT viabiliza expans\u00e3o de pizzaria cuiabana"},"content":{"rendered":"<p>Em meio aos desafios trazidos pela pandemia, os irm\u00e3os Rafael e Vin\u00edcius Moussa decidiram apostar no empreendedorismo para transformar um momento de incertezas em oportunidade. Foi assim que nasceu a pizzaria Nonna Fatia, que come\u00e7ou como uma alternativa para enfrentar aquele per\u00edodo dif\u00edcil e, hoje, se consolida como um neg\u00f3cio em crescimento em Cuiab\u00e1.<\/p>\n<p>Na \u00e9poca, os dois trabalhavam na conveni\u00eancia de um posto de combust\u00edvel da fam\u00edlia. Com o movimento reduzido durante o per\u00edodo de isolamento, surgiu a necessidade de criar um novo produto que pudesse ser vendido principalmente por delivery. A ideia inicial n\u00e3o era abrir uma pizzaria, mas ap\u00f3s analisar o mercado decidiram apostar no segmento.<\/p>\n<p>A inaugura\u00e7\u00e3o da primeira unidade aconteceu em 8 de mar\u00e7o de 2022, depois de meses de planejamento e espera pela chegada de equipamentos. Mesmo assim, a recep\u00e7\u00e3o do p\u00fablico superou as expectativas dos empreendedores.<\/p>\n<p>A proposta da Nonna Fatia \u00e9 unir dois formatos, a pizza tradicional, voltada para e delivery, e a venda em fatias, com uma proposta mais r\u00e1pida, inspirada em experi\u00eancias vividas pelos irm\u00e3os durante interc\u00e2mbios no exterior. O nome do neg\u00f3cio tamb\u00e9m carrega esse conceito: \u201cnonna\u201d, palavra italiana para av\u00f3, faz refer\u00eancia ao cuidado e ao aconchego associados \u00e0 comida caseira, al\u00e9m disso, uma pizza grande tradicional tem 8 peda\u00e7os e unindo o cuidado com a venda de fatias unit\u00e1rias surgiu o nome Nonna Fatia.<\/p>\n<p>Apesar do crescimento r\u00e1pido, o in\u00edcio n\u00e3o foi simples. Rafael conta que abriu a empresa aos 19 anos e precisou aprender muitas etapas da gest\u00e3o na pr\u00e1tica. Um dos maiores desafios, segundo ele, foi montar a equipe e estruturar os processos do neg\u00f3cio. \u201cA gente tinha estrutura, maquin\u00e1rio e produto, mas encontrar e formar as pessoas certas demorou bastante\u201d, afirma.<\/p>\n<picture data-fileentryid=\"77892139\"><source srcset=\"\/o\/adaptive-media\/image\/77892139\/Thumbnail-1024x1024\/FOTO+MEIO+-+NONNA.jpg?t=1773327608900\" media=\"(max-width:1024px)\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.secom.mt.gov.br\/documents\/d\/mt\/foto-meio-nonna?imageThumbnail=3\" alt=\"\" width=\"1080\" height=\"810\" \/><\/picture>\nCom o aumento da demanda, especialmente ap\u00f3s a implementa\u00e7\u00e3o do delivery pr\u00f3prio no final de 2022, os empreendedores perceberam que havia espa\u00e7o para expandir a marca. Atualmente, a empresa opera com alta ocupa\u00e7\u00e3o da capacidade produtiva, principalmente nos finais de semana, quando o volume de pedidos \u00e9 maior.<\/p>\n<p>Para viabilizar a abertura de uma nova unidade, os empres\u00e1rios buscaram cr\u00e9dito e encontraram na Desenvolve MT \u2013 Ag\u00eancia de Fomento do Estado de Mato Grosso, a solu\u00e7\u00e3o mais adequada para o momento do neg\u00f3cio.<\/p>\n<p>Segundo Rafael, o financiamento foi fundamental para a compra de equipamentos e maquin\u00e1rios, como fornos, c\u00e2maras frias, estufas e outros itens essenciais para a produ\u00e7\u00e3o. \u201cO cr\u00e9dito tornou o plano muito mais vi\u00e1vel. Conseguimos investir diretamente nos fornecedores e estruturar a nova unidade com mais seguran\u00e7a\u201d, explica.<\/p>\n<p>A expectativa \u00e9 que a expans\u00e3o aumente significativamente a capacidade produtiva da pizzaria e gere novos empregos diretos, entre pizzaiolos, atendentes, entregadores e outros profissionais. Mais do que crescimento financeiro, os empreendedores enxergam o momento como a valida\u00e7\u00e3o de um sonho que come\u00e7ou de forma simples e ganhou for\u00e7a ao longo dos anos. \u201cA gente quer fazer a marca crescer e chegar a mais lugares. Esse \u00e9 s\u00f3 o primeiro passo de um projeto maior\u201d, afirma Rafael.<\/p>\n<p>A nova unidade da Nonna Fatia est\u00e1 em fase de estrutura\u00e7\u00e3o e representa um novo passo na trajet\u00f3ria da empresa. O espa\u00e7o est\u00e1 sendo preparado para ampliar a opera\u00e7\u00e3o da pizzaria e melhorar a log\u00edstica de produ\u00e7\u00e3o e atendimento. Com a expans\u00e3o, os irm\u00e3os tamb\u00e9m esperam alcan\u00e7ar novos p\u00fablicos e fortalecer a presen\u00e7a da marca em diferentes regi\u00f5es de Cuiab\u00e1.<\/p>\n<p>Para quem pensa em empreender, ele deixa um conselho direto: persist\u00eancia e compromisso com a qualidade. \u201cEmpreender n\u00e3o \u00e9 f\u00e1cil, principalmente no Brasil. Mas quando voc\u00ea tem um bom produto, faz as coisas da maneira correta e entrega qualidade, o resultado aparece.\u201d<\/p>\n<p><em>*Com supervis\u00e3o de Livia Rabani<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 \u00a0|\u00a0 Foto:\u00a0 Paula Luna | Desenvolve MT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em meio aos desafios trazidos pela pandemia, os irm\u00e3os Rafael e Vin\u00edcius Moussa decidiram apostar &hellip;<\/p>\n","protected":false},"author":4,"featured_media":100349,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-100348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Nonna Fatia, empreendimento criado por irm\u00e3os durante a pandemia, financia equipamentos e estrutura para abrir uma nova unidade","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/100348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=100348"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/100348\/revisions"}],"predecessor-version":[{"id":100350,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/100348\/revisions\/100350"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/100349"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=100348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=100348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=100348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}