{"id":101039,"date":"2026-04-15T09:08:27","date_gmt":"2026-04-15T13:08:27","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=101039"},"modified":"2026-04-15T09:08:27","modified_gmt":"2026-04-15T13:08:27","slug":"sema-do-maranhao-vem-a-mt-conhecer-modelo-do-mutirao-de-conciliacao-ambiental","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/sema-do-maranhao-vem-a-mt-conhecer-modelo-do-mutirao-de-conciliacao-ambiental\/","title":{"rendered":"Sema do Maranh\u00e3o vem a MT conhecer modelo do Mutir\u00e3o de Concilia\u00e7\u00e3o Ambiental"},"content":{"rendered":"<p>Em sua oitava edi\u00e7\u00e3o, o Mutir\u00e3o de Concilia\u00e7\u00e3o Ambiental, realizado em Mato Grosso, se tornou refer\u00eancia e continua atraindo a aten\u00e7\u00e3o de outros estados. Ap\u00f3s receber, na edi\u00e7\u00e3o anterior, uma comitiva de procuradores de estados de S\u00e3o Paulo, Mato Grosso do Sul e Par\u00e1, a Secretaria de Estado de Meio Ambiente (Sema-MT) recepcionou nesta segunda e ter\u00e7a-feira (13 e 14.4), representantes do \u00f3rg\u00e3o ambiental do estado do Maranh\u00e3o.<\/p>\n<p>\u201cEstamos aqui para conhecer e realmente fazer essa imers\u00e3o no mutir\u00e3o, nas quest\u00f5es ambientais para que possamos levar a boa pr\u00e1tica para o estado do Maranh\u00e3o. \u00c9 uma iniciativa bastante exitosa que se tornou refer\u00eancia na quest\u00e3o da concilia\u00e7\u00e3o ambiental\u201d, ressaltou a secret\u00e1ria-adjunta de Desenvolvimento Sustent\u00e1vel do Maranh\u00e3o, Karla Lima.<\/p>\n<p>Para a chefe da assessoria jur\u00eddica do \u00f3rg\u00e3o ambiental maranhense, La\u00eds Borges, o fluxo e a integra\u00e7\u00e3o das institui\u00e7\u00f5es que realizam o mutir\u00e3o de concilia\u00e7\u00e3o em Mato Grosso fazem a diferen\u00e7a.<\/p>\n<p>\u201cEu achei o mutir\u00e3o muito bem estruturado, o fluxo \u00e9 perfeito com essa intera\u00e7\u00e3o da Secretaria de Estado de Meio Ambiente, Judici\u00e1rio e Minist\u00e9rio P\u00fablico. Estou realmente impressionada e encantada em viver essa experi\u00eancia aqui e poder acompanhar esse procedimento. O empreendedor j\u00e1 vem com a inten\u00e7\u00e3o de regularizar nos \u00e2mbitos administrativo, c\u00edvel e criminal, isso \u00e9 muito importante. Voc\u00ea poder fazer um acordo nas tr\u00eas esferas ao mesmo tempo \u00e9 maravilhoso do ponto de vista tanto do empreendedor como do ganho ambiental\u201d, afirmou.<\/p>\n<p>Nessa oitava edi\u00e7\u00e3o, 210 processos foram selecionados para o mutir\u00e3o, que come\u00e7ou na segunda e se estender\u00e1 at\u00e9 sexta-feira (17), no Complexo de Juizados de Cuiab\u00e1. Os atendimentos s\u00e3o realizados das 8h30 \u00e0s 18h.<\/p>\n<p>No ano passado, o Governo de Mato Grosso realizou duas edi\u00e7\u00f5es e firmou acordos em 334 processos, que superam R$ 43 milh\u00f5es. Os valores ser\u00e3o revertidos integralmente em a\u00e7\u00f5es para efetiva\u00e7\u00e3o das pol\u00edticas p\u00fablicas ambientais.<\/p>\n<p>O mutir\u00e3o \u00e9 viabilizado por meio de uma parceria entre a Secretaria de Estado de Meio Ambiente (Sema), Procuradoria Geral do Estado (PGE), Pol\u00edcia Judici\u00e1ria Civil, Tribunal de Justi\u00e7a e Minist\u00e9rio P\u00fablico Estadual.<\/p>\n<p>\u201c\u00c9 uma iniciativa exitosa que, inclusive, tem despertado o interesse de v\u00e1rios estados. Nessas edi\u00e7\u00f5es, o percentual de acordo tem variado entre 50 a 60%, o que comprova a efici\u00eancia da iniciativa\u201d, destacou a secret\u00e1ria de Estado de Meio Ambiente, Mauren Lazzaretti.<\/p>\n<p>Conforme a secret\u00e1ria, a concilia\u00e7\u00e3o envolve n\u00e3o apenas a multa administrativa, mas todas as outras san\u00e7\u00f5es relacionadas, como apreens\u00f5es, embargos e outras medidas restritivas de direito. O objetivo do mutir\u00e3o \u00e9 trazer uma solu\u00e7\u00e3o administrativa, civil e criminal para os il\u00edcitos ambientais.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.secom.mt.gov.br\/w\/sema-do-maranh%C3%A3o-vem-a-mt-conhecer-modelo-do-mutir%C3%A3o-de-concilia%C3%A7%C3%A3o-ambiental\">MTGOV<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em sua oitava edi\u00e7\u00e3o, o Mutir\u00e3o de Concilia\u00e7\u00e3o Ambiental, realizado em Mato Grosso, se tornou &hellip;<\/p>\n","protected":false},"author":4,"featured_media":101040,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-101039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Mutir\u00e3o come\u00e7ou na segunda-feira (13) e se estender\u00e1 at\u00e9 sexta-feira (17), no Complexo de Juizados de Cuiab\u00e1","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/101039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=101039"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/101039\/revisions"}],"predecessor-version":[{"id":101041,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/101039\/revisions\/101041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/101040"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=101039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=101039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=101039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}