{"id":101175,"date":"2026-04-24T16:58:09","date_gmt":"2026-04-24T20:58:09","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=101175"},"modified":"2026-04-24T16:58:09","modified_gmt":"2026-04-24T20:58:09","slug":"regularizacao-fundiaria-beneficia-moradores-do-dom-bosco-em-cuiaba","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/regularizacao-fundiaria-beneficia-moradores-do-dom-bosco-em-cuiaba\/","title":{"rendered":"Regulariza\u00e7\u00e3o fundi\u00e1ria beneficia moradores do Dom Bosco, em Cuiab\u00e1"},"content":{"rendered":"<p>Teve in\u00edcio nesta quarta-feira (22), em Cuiab\u00e1, o lan\u00e7amento do cadastramento dos moradores do bairro Dom Bosco que ser\u00e3o contemplados com a regulariza\u00e7\u00e3o fundi\u00e1ria e a entrega gratuita das escrituras definitivas de seus im\u00f3veis, devidamente registradas em cart\u00f3rio. A iniciativa representa um passo importante para garantir seguran\u00e7a jur\u00eddica \u00e0s fam\u00edlias e promover dignidade habitacional. Nesta primeira etapa, aproximadamente 720 im\u00f3veis ser\u00e3o contemplados no bairro Dom Bosco. O trabalho t\u00e9cnico de georreferenciamento j\u00e1 foi conclu\u00eddo, com o processamento detalhado das informa\u00e7\u00f5es. Agora, a a\u00e7\u00e3o entra na fase de cadastramento individual dos moradores, etapa fundamental que antecede a entrega dos t\u00edtulos definitivos.<\/p>\n<p>A a\u00e7\u00e3o integra um amplo conv\u00eanio firmado entre a Assembleia Legislativa de Mato Grosso (ALMT), por meio do deputado estadual Eduardo Botelho, e o Governo do Estado, em parceria com o Intermat, o N\u00facleo de Regulariza\u00e7\u00e3o Fundi\u00e1ria (Noreg), o Minist\u00e9rio P\u00fablico, a Corregedoria do Tribunal de Justi\u00e7a e o Cons\u00f3rcio Vale do Rio Cuiab\u00e1. O investimento total soma R$ 15 milh\u00f5es, sendo R$ 7,5 milh\u00f5es destinados pela Assembleia Legislativa e outros R$ 7,5 milh\u00f5es pelo Governo do Estado. A iniciativa refor\u00e7a o compromisso das institui\u00e7\u00f5es envolvidas com a promo\u00e7\u00e3o da cidadania, garantindo o direito \u00e0 propriedade regularizada e contribuindo para o desenvolvimento urbano ordenado de Cuiab\u00e1.<\/p>\n<p>Entre os dias 27 e 30 de maio, as equipes t\u00e9cnicas da empresa Geogis Geotecnologia estar\u00e3o de plant\u00e3o no bairro, nos per\u00edodos da manh\u00e3 e da tarde, para realizar os atendimentos e efetivar os cadastros com base no mapeamento j\u00e1 definido. Ser\u00e3o distribu\u00eddas 49 senhas no per\u00edodo matutino e outras 49 no per\u00edodo vespertino, garantindo organiza\u00e7\u00e3o e agilidade no atendimento \u00e0 popula\u00e7\u00e3o.<\/p>\n<p>O deputado estadual Eduardo Botelho destacou a import\u00e2ncia da iniciativa e o compromisso com a regulariza\u00e7\u00e3o fundi\u00e1ria em Cuiab\u00e1.<\/p>\n<p>\u201cA regulariza\u00e7\u00e3o fundi\u00e1ria \u00e9 uma luta \u00e1rdua, mas extremamente necess\u00e1ria. Tenho me dedicado a isso porque sei o impacto direto na vida das pessoas. J\u00e1 conseguimos avan\u00e7ar em praticamente todos os bairros de Cuiab\u00e1 e vamos continuar. Em breve, entregaremos escrituras no Santa Isabel, no restante do Alvorada e aqui no Dom Bosco. Esse trabalho \u00e9 gratuito, sem custo para a popula\u00e7\u00e3o. Voc\u00eas j\u00e1 t\u00eam o im\u00f3vel e, em breve, ter\u00e3o a escritura em m\u00e3os\u201d, afirmou.<\/p>\n<p>O diretor de Regulariza\u00e7\u00e3o Fundi\u00e1ria Urbana do Intermat, Erivelto Vieira Nunes, ressaltou que a a\u00e7\u00e3o cumpre mais um compromisso do Governo do Estado e destacou a complexidade t\u00e9cnica do projeto.<\/p>\n<p>\u201cEstamos iniciando o cadastramento das fam\u00edlias, que s\u00e3o cerca de 720 nesta primeira etapa. Trata-se de uma regulariza\u00e7\u00e3o mais complexa, especialmente por quest\u00f5es ambientais, j\u00e1 que h\u00e1 uma \u00e1rea de vazante que atravessa o bairro. Por isso, o trabalho ser\u00e1 dividido em duas etapas, sendo esta a primeira. A segunda ainda ser\u00e1 alinhada com os demais \u00f3rg\u00e3os envolvidos, incluindo o munic\u00edpio\u201d, explicou.<\/p>\n<p>De acordo com o assessor de regulariza\u00e7\u00e3o fundi\u00e1ria da Assembleia Legislativa, Euclides dos Santos, o programa prev\u00ea a amplia\u00e7\u00e3o das a\u00e7\u00f5es.<\/p>\n<p>\u201cEsse projeto contempla duas etapas. Nesta primeira, cerca de mil im\u00f3veis, e posteriormente mais mil. Os recursos da Assembleia e do Governo s\u00e3o executados pelo Intermat, por meio de conv\u00eanio com o Cons\u00f3rcio Vale do Rio Cuiab\u00e1. A empresa respons\u00e1vel j\u00e1 iniciou os trabalhos, e os pagamentos seguem conforme a execu\u00e7\u00e3o dos servi\u00e7os\u201d, detalhou.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.al.mt.gov.br\/midia\/texto\/regularizacao-fundiaria-avanca-em-cuiaba-e-beneficia-moradores-do-dom-bosco\/visualizar\">ALMT<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Teve in\u00edcio nesta quarta-feira (22), em Cuiab\u00e1, o lan\u00e7amento do cadastramento dos moradores do bairro &hellip;<\/p>\n","protected":false},"author":4,"featured_media":101176,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-101175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Articulada pelo deputado Botelho, a\u00e7\u00e3o inicia cadastramento de cerca de 720 im\u00f3veis e garante a entrega gratuita das escrituras definitivas, fortalecendo o direito \u00e0 propriedade e a seguran\u00e7a jur\u00eddica das fam\u00edlias","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/101175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=101175"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/101175\/revisions"}],"predecessor-version":[{"id":101177,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/101175\/revisions\/101177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/101176"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=101175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=101175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=101175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}