{"id":101709,"date":"2026-05-13T14:39:04","date_gmt":"2026-05-13T18:39:04","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=101709"},"modified":"2026-05-13T14:39:04","modified_gmt":"2026-05-13T18:39:04","slug":"governador-cobra-construtoras-que-firmam-pacto-para-concluir-faixa-do-brt-do-aeroporto-ao-comando-da-pm-ate-junho","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/governador-cobra-construtoras-que-firmam-pacto-para-concluir-faixa-do-brt-do-aeroporto-ao-comando-da-pm-ate-junho\/","title":{"rendered":"Governador cobra construtoras que firmam pacto para concluir faixa do BRT do Aeroporto ao Comando da PM at\u00e9 junho"},"content":{"rendered":"<p>O governador Otaviano Pivetta cobrou as construtoras respons\u00e1veis pelas obras do Sistema BRT entre Cuiab\u00e1 e V\u00e1rzea Grande. Em resposta, as empresas firmaram, nesta quarta-feira (13.5), um pacto para a conclus\u00e3o da faixa de 14 quil\u00f4metros, entre o Aeroporto Marechal Rondon, em V\u00e1rzea Grande, e o Comando Geral da Pol\u00edcia Militar, em Cuiab\u00e1, at\u00e9 o fim de junho.<\/p>\n<p>\u201cAs empresas assumiram hoje o compromisso de entregar, at\u00e9 o fim de junho, toda essa faixa pronta, sinalizada e liberada. Sabemos o quanto essa obra trouxe transtornos para a popula\u00e7\u00e3o de Cuiab\u00e1 e V\u00e1rzea Grande, mas agora estamos entrando em uma fase definitiva de conclus\u00e3o. Para isso, uma equipe de trabalho vai atuar na fiscaliza\u00e7\u00e3o para garantir que esse cronograma seja cumprido. O povo cuiabano pode ter certeza de que vamos entregar essa faixa funcionando e trazendo mais mobilidade para toda a regi\u00e3o metropolitana\u201d, disse.<\/p>\n<p>O comerciante Valter relatou os impactos enfrentados por quem trabalha e circula diariamente pela regi\u00e3o da Prainha e afirmou acompanhar a situa\u00e7\u00e3o h\u00e1 mais de uma d\u00e9cada.<\/p>\n<p>\u201cEstou assistindo isso desde 2011, 2012. Conhe\u00e7o o trabalho do senhor desde Lucas do Rio Verde e vejo que o senhor est\u00e1 acompanhando de perto. Isso faz a gente n\u00e3o se sentir abandonado\u201d, afirmou.<\/p>\n<picture data-fileentryid=\"79381178\"><source srcset=\"\/o\/adaptive-media\/image\/79381178\/Thumbnail-1024x1024\/4d0811a1-9f81-44f0-b2be-0e5333a637da.jpg?t=1778682154087\" media=\"(max-width:1024px)\" \/><img decoding=\"async\" src=\"https:\/\/www.secom.mt.gov.br\/documents\/d\/mt\/4d0811a1-9f81-44f0-b2be-0e5333a637da-jpg?imageThumbnail=3\" alt=\"\" height=\"267\" \/><\/picture>\n<p>O governador destacou ainda que, ap\u00f3s a conclus\u00e3o deste primeiro trecho, o Estado dar\u00e1 sequ\u00eancia aos demais ramais do sistema. \u201cDepois dessa etapa pronta e funcionando, vamos avan\u00e7ar para os outros ramais que ir\u00e3o interligar o transporte coletivo de Cuiab\u00e1 e V\u00e1rzea Grande\u201d, completou.<\/p>\n<p><strong>Sobre o BRT<\/strong><br \/>\nO Sistema BRT (Bus Rapid Transit) est\u00e1 em implanta\u00e7\u00e3o em Cuiab\u00e1 e V\u00e1rzea Grande para oferecer um transporte coletivo mais r\u00e1pido e eficiente \u00e0 popula\u00e7\u00e3o. O projeto prev\u00ea corredores exclusivos para \u00f4nibus de alta capacidade, esta\u00e7\u00f5es modernas, integra\u00e7\u00e3o com outros modais e melhorias urbanas ao longo do trajeto.<\/p>\n<p>O primeiro corredor liga o Terminal de V\u00e1rzea Grande, pr\u00f3ximo ao Aeroporto Marechal Rondon, at\u00e9 o Terminal do CPA, em Cuiab\u00e1. J\u00e1 o segundo ramal far\u00e1 a liga\u00e7\u00e3o entre a regi\u00e3o do Coxip\u00f3 e o centro da Capital, pela Avenida Fernando Corr\u00eaa da Costa.<\/p>\n<p>Al\u00e9m dos corredores exclusivos, o projeto tamb\u00e9m prev\u00ea requalifica\u00e7\u00e3o urbana, novas cal\u00e7adas, drenagem, paisagismo e implanta\u00e7\u00e3o do Parque Linear na Avenida do CPA.<\/p>\n<picture data-fileentryid=\"79381200\"><source srcset=\"\/o\/adaptive-media\/image\/79381200\/Thumbnail-1024x1024\/fd975bc1-2fd7-4abb-82fb-d00a5504a470.jpg?t=1778682219676\" media=\"(max-width:1024px)\" \/><img decoding=\"async\" src=\"https:\/\/www.secom.mt.gov.br\/documents\/d\/mt\/fd975bc1-2fd7-4abb-82fb-d00a5504a470-jpg?imageThumbnail=3\" alt=\"\" height=\"267\" \/><\/picture>\n&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.secom.mt.gov.br\/w\/governador-cobra-construtoras-que-firmam-pacto-para-concluir-faixa-do-brt-do-aeroporto-ao-comando-da-pm-at%C3%A9-junho\">MTGOV<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Otaviano Pivetta cobrou as construtoras respons\u00e1veis pelas obras do Sistema BRT entre Cuiab\u00e1 &hellip;<\/p>\n","protected":false},"author":4,"featured_media":101710,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-101709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Trecho de 14 quil\u00f4metros dever\u00e1 ser entregue sinalizado e sem obst\u00e1culos para melhorar fluxo entre Cuiab\u00e1 e V\u00e1rzea Grande","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/101709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=101709"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/101709\/revisions"}],"predecessor-version":[{"id":101711,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/101709\/revisions\/101711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/101710"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=101709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=101709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=101709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}