{"id":1252,"date":"2015-08-13T09:46:25","date_gmt":"2015-08-13T09:46:25","guid":{"rendered":"http:\/\/www.correiodafe.gswhost.net\/portal\/?p=1252"},"modified":"2015-12-19T19:18:55","modified_gmt":"2015-12-19T19:18:55","slug":"dilma-se-reune-com-empresarios-para-definir-acordos-com-a-alemanha","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/dilma-se-reune-com-empresarios-para-definir-acordos-com-a-alemanha\/","title":{"rendered":"Dilma se re\u00fane com empres\u00e1rios para definir acordos com a Alemanha"},"content":{"rendered":"<p>A presidente Dilma Rousseff definir\u00e1 nesta quarta-feira (19), durante encontro com empres\u00e1rios brasileiros, os acordos comerciais que ser\u00e3o assinados nesta quinta (20) entre o Brasil e a Alemanha durante a visita oficial da chanceler Angela Merkel ao pa\u00eds.<br \/>\nMerkel desembarcar\u00e1 em Bras\u00edlia nesta quarta e participar\u00e1 \u00e0 noite, acompanhada de ministros de seu pa\u00eds, de jantar oferecido pela presidente Dilma \u00e0 delega\u00e7\u00e3o alem\u00e3 no Pal\u00e1cio da Alvorada, resid\u00eancia oficial da Presid\u00eancia.<br \/>\nEsta \u00e9 a segunda passagem de Merkel pelo Brasil desde junho do ano passado, quando ela esteve no pa\u00eds para assistir ao jogo entre Alemanha e Portugal pela Copa do Mundo, em Salvador (BA). Na ocasi\u00e3o, ela tamb\u00e9m se reuniu com Dilma no Alvorada antes de se dirigir \u00e0 capital baiana.<br \/>\nO G1 procurou a Secretaria de Imprensa para saber quais empres\u00e1rios foram chamados ao Planalto, mas n\u00e3o obteve resposta at\u00e9 a \u00faltima atualiza\u00e7\u00e3o desta reportagem.<br \/>\nDe acordo com o Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores, Brasil e Alemanha articulam para o encontro a assinatura de acordos em \u00e1reas como com\u00e9rcio e investimentos, ci\u00eancia, tecnologia e inova\u00e7\u00e3o e educa\u00e7\u00e3o. O pa\u00eds europeu \u00e9 considerado &#8220;importante parceiro&#8221; do Brasil na \u00e1rea de pesquisa.<br \/>\nAinda segundo o Itamaraty, Dilma pretende apresentar a Merkel o plano de concess\u00f5es na \u00e1rea de infraestrutura e tentar fazer com que empresas da Alemanha participem das obras.<br \/>\nA Alemanha \u00e9 atualmente o quarto maior parceiro comercial do Brasil, atr\u00e1s de China, Estados Unidos e Argentina. De acordo com o Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores, o fluxo comercial entre os pa\u00edses \u2013 soma entre exporta\u00e7\u00f5es e importa\u00e7\u00f5es \u2013 chegou a US$ 20,5 bilh\u00f5es em 2014.<br \/>\nAl\u00e9m das conversas sobre o plano de concess\u00f5es, informou o governo, Dilma abordar\u00e1 na reuni\u00e3o com Merkel no Pal\u00e1cio do Planalto temas como mudan\u00e7a do clima \u2013 os dois pa\u00edses participar\u00e3o de confer\u00eancia das Na\u00e7\u00f5es Unidas sobre o tema em dezembro, em Paris \u2013 e reforma do Conselho de Seguran\u00e7a da ONU.<br \/>\nOutro tema de destaque que ser\u00e1 abordado pela presidente e pela chanceler \u00e9 o da seguran\u00e7a na internet. Brasil e Alemanha se articularam para para aprovar na ONU resolu\u00e7\u00e3o que garante maior privacidade na internet ap\u00f3s den\u00fancias de que l\u00edderes internacionais, como Dilma e Merkel, haviam sido alvo de espionagem do governo dos Estados Unidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A presidente Dilma Rousseff definir\u00e1 nesta quarta-feira (19), durante encontro com empres\u00e1rios brasileiros, os acordos &hellip;<\/p>\n","protected":false},"author":1,"featured_media":1253,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52,59],"tags":[],"class_list":["post-1252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-destaque"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/1252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=1252"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/1252\/revisions"}],"predecessor-version":[{"id":1254,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/1252\/revisions\/1254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/1253"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=1252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=1252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=1252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}