{"id":1316,"date":"2015-09-02T09:33:43","date_gmt":"2015-09-02T09:33:43","guid":{"rendered":"http:\/\/www.correiodafe.gswhost.net\/portal\/?p=1316"},"modified":"2015-10-21T00:45:43","modified_gmt":"2015-10-21T00:45:43","slug":"e-um-dos-mais-extraordinarios-quadros-da-nova-geracao","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/e-um-dos-mais-extraordinarios-quadros-da-nova-geracao\/","title":{"rendered":"\u201c\u00c9 um dos mais extraordin\u00e1rios quadros da nova gera\u00e7\u00e3o\u201d"},"content":{"rendered":"<p>\u201cUm dos mais extraordin\u00e1rios quadros da nova gera\u00e7\u00e3o de homens p\u00fablicos brasileiros\u201d. Foi dessa maneira que o senador A\u00e9cio Neves (PSDB) classificou o governador Pedro Taques (sem partido), que ir\u00e1 se filiar ao PSDB, no pr\u00f3ximo dia 29.<\/p>\n<p>A\u00e9cio falou sobre a decis\u00e3o, durante entrevista coletiva na tarde desta ter\u00e7a-feira (18), em Bras\u00edlia. Segundo ele, a ida Taques para o partido representa um momento de muita alegria.<br \/>\n\u201cO PSDB vive, hoje, um momento de enorme alegria. Depois de in\u00fameras conversas que tivemos, e de convites expressos por mim, pelo presidente Fernando Henrique e por outras lideran\u00e7as, quero anunciar\u00a0 a filia\u00e7\u00e3o ao PSDB do governador de Mato Grosso, Pedro Taques\u201d, disse.<br \/>\nNa sequ\u00eancia, ele lembrou a atua\u00e7\u00e3o de Taques no Senado, cargo que ele ocupou entre os anos de 2010 e 2014.<\/p>\n<p>\u201cO Pedro Taques, durante o tempo que esteve aqui, no Senado, mostrou n\u00e3o apenas a sua qualidade intelectual, a sua retid\u00e3o moral, mas tamb\u00e9m a sua extraordin\u00e1ria coragem para defender as suas posi\u00e7\u00f5es. Inclusive, muitas vezes, em disson\u00e2ncia daquilo que orientava a lideran\u00e7a de seu partido\u201d, disse.<\/p>\n<p>\u201cPedro foi, durante todos os dias de seu mandato, absolutamente fiel \u00e0s suas convic\u00e7\u00f5es\u201d, completou.<\/p>\n<p>Ainda durante a entrevista, A\u00e9cio afirmou que a postura de oposi\u00e7\u00e3o ao governo da presidente Dilma Rousseff (PT) \u00e9 que aproximou Taques dos tucanos.<\/p>\n<p>\u201cEssa postura o aproximou do PSDB. Ele tamb\u00e9m nos apoiou na campanha eleitoral passada, o que j\u00e1 trouxe forte identidade program\u00e1tica do ponto de vista da gest\u00e3o p\u00fablica eficiente, dos avan\u00e7os sociais que precisam vir\u201d, disse.<\/p>\n<p>\u201cRevoada\u201d<\/p>\n<p>O senador confirmou a presen\u00e7a de lideran\u00e7as tucanas em Cuiab\u00e1, no pr\u00f3ximo dia 29, ocasi\u00e3o em que ocorrer\u00e1 o ato de filia\u00e7\u00e3o de Taques.<\/p>\n<p>\u201cO PSDB recebe um refor\u00e7o de alt\u00edssima qualidade. Estaremos todos os tucanos em revoada no pr\u00f3ximo dia 29, pela manh\u00e3, para fazermos, l\u00e1 em Cuiab\u00e1, o ato de filia\u00e7\u00e3o\u201d.<\/p>\n<p>\u201cAgrade\u00e7o de p\u00fablico o governador Pedro Taques que, em uma hora dif\u00edcil da vida nacional, como essa, demonstra confian\u00e7a na condu\u00e7\u00e3o que o PSDB vem dando \u00e0 pol\u00edtica brasileira, no que diz respeito \u00e0s a\u00e7\u00f5es da oposi\u00e7\u00e3o\u201d, concluiu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cUm dos mais extraordin\u00e1rios quadros da nova gera\u00e7\u00e3o de homens p\u00fablicos brasileiros\u201d. Foi dessa maneira &hellip;<\/p>\n","protected":false},"author":1,"featured_media":1317,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59,14],"tags":[],"class_list":["post-1316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-mato-grosso"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/1316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=1316"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/1316\/revisions"}],"predecessor-version":[{"id":1318,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/1316\/revisions\/1318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/1317"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=1316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=1316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=1316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}