{"id":19426,"date":"2019-08-30T11:38:46","date_gmt":"2019-08-30T15:38:46","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=19426"},"modified":"2019-08-30T11:38:46","modified_gmt":"2019-08-30T15:38:46","slug":"na-verdade-na-verdade-vos-digo-que-se-o-grao-de-trigo-caindo-na-terra-nao-morrer-fica-ele-so-mas-se-morrer-da-muito-fruto-joao-1224","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/na-verdade-na-verdade-vos-digo-que-se-o-grao-de-trigo-caindo-na-terra-nao-morrer-fica-ele-so-mas-se-morrer-da-muito-fruto-joao-1224\/","title":{"rendered":"&#8220;Na verdade, na verdade vos digo que, se o gr\u00e3o de trigo, caindo na terra, n\u00e3o morrer, fica ele s\u00f3; mas se morrer, d\u00e1 muito fruto.&#8221; Jo\u00e3o 12:24"},"content":{"rendered":"<p align=\"justify\"><strong>Pensamento:<\/strong>\u00a0H\u00e1 coisas que t\u00eam que morrer, para que d\u00eaem lugar \u00e0 vida. Isso acontece constantemente em nossos relacionamentos. Se o orgulho n\u00e3o morrer, n\u00e3o nasce o perd\u00e3o. Se a inveja n\u00e3o morrer, n\u00e3o nasce coopera\u00e7\u00e3o. Se o \u00f3dio n\u00e3o morrer, n\u00e3o cresce o amor. Vale a pena fazer um balan\u00e7o do que deve morrer e do que deve viver em nossos relacionamentos. Vale a pena deixar morrer as sementes \u00e0s quais nos agarramos e que, por isso, nada produzem.<\/p>\n<p>&nbsp;<\/p>\n<p align=\"justify\"><strong>Ora\u00e7\u00e3o:<\/strong>\u00a0Deus pai todo poderoso, eu rejeito todo orgulho e toda falta de perd\u00e3o, assim como a cobi\u00e7a, o c\u00edmues, ira e a inveja. Ajuda-me a plantar as sementes certas, em terra f\u00e9rtil, para que eu possa dar bons frutos. Eu oro em nome de Jesus. Am\u00e9m.<\/p>\n<p align=\"justify\">\n<p align=\"justify\">Fonte:\u00a0https:\/\/www.devocionaldiario.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pensamento:\u00a0H\u00e1 coisas que t\u00eam que morrer, para que d\u00eaem lugar \u00e0 vida. Isso acontece constantemente &hellip;<\/p>\n","protected":false},"author":4,"featured_media":19427,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/19426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=19426"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/19426\/revisions"}],"predecessor-version":[{"id":19428,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/19426\/revisions\/19428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/19427"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=19426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=19426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=19426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}