{"id":19720,"date":"2019-09-10T15:57:10","date_gmt":"2019-09-10T19:57:10","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=19720"},"modified":"2019-09-10T15:59:38","modified_gmt":"2019-09-10T19:59:38","slug":"indicado-a-pgr-augusto-aras-se-compromete-com-evangelicos-sobre-valores-cristaos","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/indicado-a-pgr-augusto-aras-se-compromete-com-evangelicos-sobre-valores-cristaos\/","title":{"rendered":"Indicado \u00e0 PGR, Augusto Aras se compromete com evang\u00e9licos sobre &#8220;valores crist\u00e3os&#8221;"},"content":{"rendered":"<p>Indicado pelo presidente Jair Bolsonaro para a Procuradoria-Geral da Rep\u00fablica (PGR), Augusto Aras foi o \u00fanico dos candidatos ao cargo a se comprometer com uma s\u00e9rie de \u201cvalores crist\u00e3os\u201d previstos em carta da\u00a0<strong><a href=\"https:\/\/guiame.com.br\/gospel\/entrevistas\/deus-abriu-portas-para-eu-contribuir-com-o-brasil-diz-pastor-nomeado-por-bolsonaro.html\">Associa\u00e7\u00e3o Nacional de Juristas Evang\u00e9licos<\/a><\/strong>\u00a0(Anajure). Aras recebeu apoio institucional da entidade, que tem tr\u00e2nsito na c\u00fapula do governo, na disputa pela chefia do Minist\u00e9rio P\u00fablico.<\/p>\n<p>A controversa indica\u00e7\u00e3o de Augusto Aras p\u00f4de ser medida nas m\u00eddias sociais, onde as manifesta\u00e7\u00f5es contr\u00e1rias ao seu nome para a PGR deram origem \u00e0 #AugustoArasN\u00e3o. Para aqueles que se op\u00f5em ao nome de Aras, o passado dele em defesa de causas, como o fim da opera\u00e7\u00e3o Lava Jato, destoa do momento pol\u00edtico do Brasil.<\/p>\n<p>O documento, de dez p\u00e1ginas proposto pela Anajure, registra vis\u00e3o da entidade \u2013 bra\u00e7o das igrejas protestantes no meio jur\u00eddico \u2013 sobre temas como\u00a0<strong><a href=\"https:\/\/guiame.com.br\/gospel\/noticias\/em-reuniao-com-moro-frente-parlamentar-da-liberdade-religiosa-apoia-deportacao-sumaria.html\">liberdade religiosa<\/a><\/strong>, sexualidade, aborto, g\u00eanero, conceito de fam\u00edlia, acolhimento de refugiados, ensino confessional, repress\u00e3o \u00e0 corrup\u00e7\u00e3o e separa\u00e7\u00e3o dos Poderes, entre outros. Parte do texto sugere posi\u00e7\u00f5es institucionais que, no entendimento da associa\u00e7\u00e3o, deveriam ser adotadas pelo Minist\u00e9rio P\u00fablico e pelo governo.<\/p>\n<p>Na lista dos itens defendidos pela associa\u00e7\u00e3o est\u00e3o a manuten\u00e7\u00e3o dos s\u00edmbolos religiosos em reparti\u00e7\u00f5es p\u00fablicas, monumentos p\u00fablicos com conota\u00e7\u00e3o religiosa, feriados religiosos e a men\u00e7\u00e3o a \u201cDeus\u201d no pre\u00e2mbulo do texto constitucional. O documento diz que o Poder Judici\u00e1rio deve se abster de atuar como legislador. Para a entidade, o Minist\u00e9rio P\u00fablico deve ter sua atua\u00e7\u00e3o limitada \u00e0s fun\u00e7\u00f5es institucionais, evitando condutas \u201cpersonalistas\u201d em opera\u00e7\u00f5es como a Lava Jato \u2013 ideia j\u00e1 exposta por Aras.<\/p>\n<p>\u201cEle (Aras) falou que \u00e9 conservador, leu a carta e est\u00e1 de acordo com os princ\u00edpios ali elencados\u201d, disse ao Estado o presidente da Anajure, Uziel Santana. \u201cEle se comprometeu com a pauta prevista, tanto moral quanto de combate \u00e0 corrup\u00e7\u00e3o.\u201d A Anajure tem cerca de 700 associados, entre ju\u00edzes, desembargadores, advogados, promotores e procuradores.<\/p>\n<p>Bolsonaro prometeu editar\u00a0<strong><a href=\"https:\/\/guiame.com.br\/gospel\/noticias\/bolsonaro-determina-proibicao-de-ideologia-de-genero-no-ensino-fundamental.html\">projeto de lei para proibir \u201cideologia de g\u00eanero\u201d<\/a><\/strong>\u00a0no ensino fundamental. H\u00e1 dez a\u00e7\u00f5es no Supremo Tribunal Federal questionando a constitucionalidade de leis estaduais e municipais que versam sobre a mesma veda\u00e7\u00e3o a orienta\u00e7\u00f5es sobre sexualidade e g\u00eanero nas escolas. Sete delas foram propostas pela Procuradoria-Geral da Rep\u00fablica. Para a Anajure, as leis devem ser reconhecidas como v\u00e1lidas.<\/p>\n<p>\u201cH\u00e1 uma desconstru\u00e7\u00e3o de valores morais nos \u00faltimos anos, a imposi\u00e7\u00e3o de uma agenda contr\u00e1ria ao pensamento de pais e fam\u00edlias, da igreja. E isso n\u00e3o \u00e9 bom\u201d, afirmou Santana. Ele disse que a Anajure n\u00e3o deseja \u201cimpor\u201d a sua vis\u00e3o moral ao Pa\u00eds, mas busca que ela seja \u201crespeitada\u201d. Para ele, o \u201calinhamento\u201d entre governo e Procuradoria-Geral significa \u201cestar harm\u00f4nico sem falta de independ\u00eancia\u201d.<\/p>\n<p>A carta exp\u00f5e argumentos contra quest\u00f5es como o\u00a0<strong><a href=\"https:\/\/guiame.com.br\/gospel\/noticias\/20000-pessoas-marcham-em-silencio-contra-lei-do-aborto-na-irlanda-do-norte.html\">aborto<\/a><\/strong>\u00a0e o reconhecimento de fam\u00edlia, na esfera p\u00fablica, composta por uma uni\u00e3o homoafetiva. \u201cA institui\u00e7\u00e3o familiar deve ser preservada como heterossexual e monog\u00e2mica.\u201d A Anajure defende a possibilidade de realiza\u00e7\u00e3o de tratamentos para \u201crevers\u00e3o sexual\u201d, afirma que os registros p\u00fablicos devem admitir apenas o g\u00eanero bin\u00e1rio (masculino e feminino), argumenta em favor do ensino confessional e sugere a cria\u00e7\u00e3o de cargos de Estado para defender a liberdade religiosa internacionalmente.<\/p>\n<p>Num dos trechos, a entidade pede comprometimento do procurador-geral com o \u201cmandamento\u201d de que as igrejas \u201cs\u00e3o imunes \u00e0 cobran\u00e7a de tributos e assim devem permanecer\u201d. O temor de que elas venham a ter receitas taxadas aumentou por causa do projeto de uma contribui\u00e7\u00e3o sobre pagamentos em estudo, com apoio de setores da equipe de Bolsonaro, enquanto o Congresso debate a reforma tribut\u00e1ria. A Anajure e a Frente Parlamentar Evang\u00e9lica se articulam para barrar a iniciativa.<\/p>\n<p>Aras iniciou ontem corpo a corpo no Senado, onde ser\u00e1 sabatinado, em busca de apoio e j\u00e1 come\u00e7ou a montar sua equipe. O subprocurador aposentado Eitel Santiago Pereira confirmou, em redes sociais, que aceitou convite para o cargo de secret\u00e1rio-geral da PGR. \u201cQue Deus aben\u00e7oe minha decis\u00e3o.\u201d<\/p>\n<p>Nesta segunda-feira (09), l\u00edderes do Minist\u00e9rio P\u00fablico realizaram atos em defesa da independ\u00eancia da institui\u00e7\u00e3o e contra a indica\u00e7\u00e3o de Aras \u2013 Bolsonaro ignorou a lista tr\u00edplice eleita pela categoria. Em Bras\u00edlia, o primeiro colocado da lista, Mario Bonsaglia, afirmou que \u201cpreocupa a vis\u00e3o de que o procurador-geral precisaria ter um programa alinhado ao governo\u201d. Procurado, Aras n\u00e3o se manifestou.<\/p>\n<p>&nbsp;<\/p>\n<p>FONTE: GUIAME, COM INFORMA\u00c7\u00d5ES DO ESTAD\u00c3O | Foto:\u00a0Foto: Pedro Ladeira\/Folhapress<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Indicado pelo presidente Jair Bolsonaro para a Procuradoria-Geral da Rep\u00fablica (PGR), Augusto Aras foi o &hellip;<\/p>\n","protected":false},"author":4,"featured_media":19721,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,59],"tags":[],"class_list":["post-19720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news","category-destaque"],"wps_subtitle":"Os temas foram propostos pela Associa\u00e7\u00e3o Nacional de Juristas Evang\u00e9licos, bra\u00e7o das igrejas protestantes no meio jur\u00eddico.","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/19720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=19720"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/19720\/revisions"}],"predecessor-version":[{"id":19722,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/19720\/revisions\/19722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/19721"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=19720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=19720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=19720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}