{"id":19861,"date":"2019-09-19T14:05:31","date_gmt":"2019-09-19T18:05:31","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=19861"},"modified":"2019-09-19T14:10:55","modified_gmt":"2019-09-19T18:10:55","slug":"cupula-climatica-da-onu-testara-determinacao-global-para-conter-aquecimento","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/cupula-climatica-da-onu-testara-determinacao-global-para-conter-aquecimento\/","title":{"rendered":"C\u00fapula clim\u00e1tica da ONU testar\u00e1 determina\u00e7\u00e3o global para conter aquecimento"},"content":{"rendered":"<p>WASHINGTON\/BRUXELAS\u00a0 &#8211; Diante de inc\u00eandios florestais, ondas de calor e furac\u00f5es, o secret\u00e1rio-geral da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU), Ant\u00f3nio Guterres, disse que est\u00e1 contando com novas promessas de governos e empresas de abandonar os combust\u00edveis f\u00f3sseis durante uma c\u00fapula clim\u00e1tica especial em Nova York na segunda-feira.<\/p>\n<p>Com a press\u00e3o crescente da adolescente sueca Greta Thunberg e de outros ativistas sobre os delegados antes da C\u00fapula da A\u00e7\u00e3o Clim\u00e1tica, autoridades da ONU esperam que cerca de 60 pa\u00edses aprofundem seus compromissos com o Acordo de Paris de 2015 para combater o aquecimento global.<\/p>\n<p>\u201cEstamos perdendo a batalha contra a mudan\u00e7a clim\u00e1tica\u201d, disse Guterres em uma coletiva de imprensa na quarta-feira. \u201cEspero que aconte\u00e7a o an\u00fancio e a apresenta\u00e7\u00e3o de v\u00e1rios planos significativos para reduzir as emiss\u00f5es na pr\u00f3xima d\u00e9cada e alcan\u00e7ar a neutralidade de carbono at\u00e9 2050\u201d.<\/p>\n<p>Na semana que vem, estar\u00e3o em cena pa\u00edses que incluir\u00e3o pequenas ilhas-Estados mais vulner\u00e1veis \u00e0 eleva\u00e7\u00e3o dos mares e na\u00e7\u00f5es como Fran\u00e7a e Alemanha, de acordo com o esbo\u00e7o de uma programa\u00e7\u00e3o visto pela Reuters.<\/p>\n<p>At\u00e9 agora, grandes economias que ainda constroem ou financiam usinas de carv\u00e3o \u2014como Jap\u00e3o, Coreia do Sul e Austr\u00e1lia\u2014 n\u00e3o devem discursar, mas muitas ainda podem apresentar planos.<\/p>\n<p>O presidente dos Estados Unidos, Donald Trump, assim como o presidente Jair Bolsonaro, alguns dos poucos l\u00edderes mundiais que ainda questionam a ci\u00eancia clim\u00e1tica, n\u00e3o v\u00e3o participar, disseram seus representantes.<\/p>\n<p>Grupos ambientalistas dizem que a c\u00fapula acontece em um momento crucial, j\u00e1 que eventos clim\u00e1ticos extremos e temperaturas em eleva\u00e7\u00e3o afetam mais pessoas em mais partes do globo.<\/p>\n<p>\u201cA reuni\u00e3o n\u00e3o poderia ser mais importante\u201d, disse May Boeve, diretora-executiva do 350.org, um grupo de ativismo clim\u00e1tico. \u201cEla significa que os pa\u00edses finalmente precisar\u00e3o falar sobre a fonte das chamas que engolfam nosso planeta: os combust\u00edveis f\u00f3sseis\u201d.<\/p>\n<div><\/div>\n<p>Guterres pediu o fim da constru\u00e7\u00e3o das usinas de carv\u00e3o a partir de 2020 em todo o mundo, al\u00e9m da anula\u00e7\u00e3o gradual dos subs\u00eddios aos combust\u00edveis f\u00f3sseis e uma mudan\u00e7a r\u00e1pida para fontes de energias renov\u00e1veis, como solar, e\u00f3lica e geot\u00e9rmica.<\/p>\n<p>Embora o Acordo de Paris exija que os governos realizem uma transi\u00e7\u00e3o r\u00e1pida para formas de energia limpa, as emiss\u00f5es mundiais de gases de efeito estufa atingiram uma alta recorde no ano passado.<\/p>\n<p>&nbsp;<\/p>\n<p><a target=\"_blank\">Por: Valerie Volcovici e Matthew Green | Foto:\u00a0Bruno Kelly | Fonte:\u00a0https:\/\/br.reuters.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>WASHINGTON\/BRUXELAS\u00a0 &#8211; Diante de inc\u00eandios florestais, ondas de calor e furac\u00f5es, o secret\u00e1rio-geral da Organiza\u00e7\u00e3o &hellip;<\/p>\n","protected":false},"author":4,"featured_media":19862,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,59],"tags":[],"class_list":["post-19861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news","category-destaque"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/19861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=19861"}],"version-history":[{"count":2,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/19861\/revisions"}],"predecessor-version":[{"id":19868,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/19861\/revisions\/19868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/19862"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=19861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=19861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=19861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}