{"id":19938,"date":"2019-09-23T10:52:27","date_gmt":"2019-09-23T14:52:27","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=19938"},"modified":"2019-09-23T11:23:19","modified_gmt":"2019-09-23T15:23:19","slug":"prefeito-cita-aval-do-bndes-e-quer-autorizacao-da-camara-para-emprestimo-de-r-100-milhoes-para-asfaltar-20-bairros","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/prefeito-cita-aval-do-bndes-e-quer-autorizacao-da-camara-para-emprestimo-de-r-100-milhoes-para-asfaltar-20-bairros\/","title":{"rendered":"Prefeito cita aval do BNDES e quer autoriza\u00e7\u00e3o da C\u00e2mara para empr\u00e9stimo de R$ 100 milh\u00f5es para asfaltar 20 bairros"},"content":{"rendered":"<p>O prefeito de Cuiab\u00e1 Emanuel Pinheiro (MDB) anunciou no \u00faltimo s\u00e1bado durante evento pol\u00edtico em Cuiab\u00e1 que vai enviar nesta semana \u00e0 C\u00e2mara de Vereadores, o projeto de lei que pede a autoriza\u00e7\u00e3o para contrair empr\u00e9stimo de R$ 100 milh\u00f5es junto ao Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES). Os recursos dever\u00e3o ser utilizados da execu\u00e7\u00e3o de obras de asfalto em 20 bairros atrav\u00e9s do programa \u2018Minha Rua Asfaltada\u2019.<\/p>\n<p>De acordo com o chefe do Executivo municipal, a prefeitura tem capacidade de endividamento e o banco estatal de fomento j\u00e1 aprovou o empr\u00e9stimo. \u201cEnviarei para C\u00e2mara um financiamento de R$ 100 milh\u00f5es do BNDES para asfaltar mais 20 bairros em Cuiab\u00e1, que j\u00e1 tem aprova\u00e7\u00e3o da consulta pr\u00e9via dom BNDES, demonstra\u00e7\u00e3o da for\u00e7a e do equil\u00edbrio fiscal da Prefeitura Municipal de Cuiab\u00e1\u201d, afirmou.<\/p>\n<p>Emanuel destacou que os recursos ser\u00e3o usados com responsabilidade para melhorar a vida da popula\u00e7\u00e3o. \u201cDinheiro p\u00fablico n\u00e3o \u00e9 para ser poupado e gerar lucro. Dinheiro p\u00fablico \u00e9 para ser investido nas pessoas e na qualidade de vida na cidade. O munic\u00edpio n\u00e3o tem que ser agiota, n\u00e3o pode poupar dinheiro p\u00fablico com intuito de obter lucros. Temos a responsabilidade e o dever de receber dinheiro p\u00fablico e reinvesti-los no social e investimentos que melhorem a vida das pessoas\u201d.<\/p>\n<p>Desde o in\u00edcio do ano, a prefeitura vem buscando recursos para melhorar a infraestrutura do munic\u00edpio. Em janeiro, foi firmado um contrato de financiamento com o Banco do Brasil, no valor de R$\u00a050.869.138,28, para execu\u00e7\u00e3o de \u00a0dois viadutos, um na Avenida das Torres e outro na Avenida Beira Rio, no cruzamento com a ponte Ministro S\u00e9rgio Mota.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Cuiab\u00e1 Emanuel Pinheiro (MDB) anunciou no \u00faltimo s\u00e1bado durante evento pol\u00edtico em &hellip;<\/p>\n","protected":false},"author":4,"featured_media":19939,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,76],"tags":[],"class_list":["post-19938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mato-grosso","category-missoes"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/19938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=19938"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/19938\/revisions"}],"predecessor-version":[{"id":19940,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/19938\/revisions\/19940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/19939"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=19938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=19938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=19938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}