{"id":20144,"date":"2019-10-01T10:46:30","date_gmt":"2019-10-01T14:46:30","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=20144"},"modified":"2019-10-01T10:46:30","modified_gmt":"2019-10-01T14:46:30","slug":"ex-senador-e-alvo-de-mandado-de-busca-e-apreensao-da-pf-por-suposto-pagamento-de-propina-a-auditores-fiscais","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/ex-senador-e-alvo-de-mandado-de-busca-e-apreensao-da-pf-por-suposto-pagamento-de-propina-a-auditores-fiscais\/","title":{"rendered":"Ex-senador \u00e9 alvo de mandado de busca e apreens\u00e3o da PF por suposto pagamento de propina a auditores fiscais"},"content":{"rendered":"<p>O ex-senador e empres\u00e1rio no ramo de frigor\u00edficos, Cidinho Santos (PR) \u00e9 um dos alvos de busca e apreens\u00e3o da 4\u00aa fase da \u201cOpera\u00e7\u00e3o Carne Fraca\u201d, denominada \u201cRomanos\u201d, deflagrada na manh\u00e3 desta ter\u00e7a-feira (1) pela Pol\u00edcia Federal. \u00a0As buscas acontecem na sede da empresa de Cidinho, a Uni\u00e3o Av\u00edcola, no munic\u00edpio de Nova Maril\u00e2ndia, onde ele foi prefeito, e no escrit\u00f3rio em Cuiab\u00e1.<\/p>\n<p>Segundo fonte da Policia Federal, a Uni\u00e3o Av\u00edcola era usada pela BRF \u2013 grupo empresarial do ramo aliment\u00edcio, para repassar propina para fiscais agropecu\u00e1rios federais.<\/p>\n<p>A 4\u00aa fase da opera\u00e7\u00e3o investiga o pagamento de propinas a auditores fiscais agropecu\u00e1rios de v\u00e1rios de Mato Grosso e de outros oito estados para que atuassem em benef\u00edcio da companhia BRF. O grupo empresarial, segundo a Pol\u00edcia Federal, passou a atuar de maneira espont\u00e2nea com as autoridades p\u00fablicas e apontou 60 auditores fiscais agropecu\u00e1rios como favorecidos com as vantagens indevidas.<\/p>\n<p>Aproximadamente R$ 19 milh\u00f5es foram destinados a pagamentos de propinas, conforme a PF. Os valores eram pagos em esp\u00e9cie, por meio do custeio de planos de sa\u00fade e por contratos fict\u00edcios firmados com pessoas jur\u00eddicas que representavam o interesse dos fiscais.<\/p>\n<p>S\u00e3o cumpridos 68 mandados de busca e apreens\u00e3o em Mato Grosso e outros oitos estados: Paran\u00e1, S\u00e3o Paulo, Santa Catarina, Goi\u00e1s, Par\u00e1, Rio Grande do Sul, Minas Gerais e Rio de Janeiro. As medidas cautelares foram expedidas pela 1\u00aa Vara Federal de Ponta Grossa\/PR.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: https:\/\/odocumento.com.br | Foto:\u00a0\u00a0Pedro Fran\u00e7a<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ex-senador e empres\u00e1rio no ramo de frigor\u00edficos, Cidinho Santos (PR) \u00e9 um dos alvos &hellip;<\/p>\n","protected":false},"author":4,"featured_media":20145,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-20144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=20144"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20144\/revisions"}],"predecessor-version":[{"id":20146,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20144\/revisions\/20146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/20145"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=20144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=20144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=20144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}