{"id":20359,"date":"2019-10-11T09:39:46","date_gmt":"2019-10-11T13:39:46","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=20359"},"modified":"2019-10-11T09:39:46","modified_gmt":"2019-10-11T13:39:46","slug":"equipe-da-gcco-recebe-mocao-de-aplausos-concedida-por-dilemario-alencar","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/equipe-da-gcco-recebe-mocao-de-aplausos-concedida-por-dilemario-alencar\/","title":{"rendered":"Equipe da GCCO recebe Mo\u00e7\u00e3o de Aplausos concedida por Dilem\u00e1rio Alencar"},"content":{"rendered":"<div>O vereador Dilem\u00e1rio Alencar (PROS) entregou 34 mo\u00e7\u00f5es de aplausos aos servidores p\u00fablicos que comp\u00f5em a equipe da Ger\u00eancia de Combate ao Crime Organizado\u00a0 (GCCO), durante a sess\u00e3o plen\u00e1ria desta quinta-feira (10).<\/div>\n<div><\/div>\n<div>Entre os agraciados estavam Delegados, Escriv\u00e3es, Investigadores e Agentes Penitenci\u00e1rios. Na oportunidade Dilem\u00e1rio asseverou que \u201cdevemos honrar a quem tem honra. Estes servidores p\u00fablicos trabalham muito pelos cidad\u00e3os de Cuiab\u00e1 e do nosso estado\u201d.<\/div>\n<div><\/div>\n<div>O Delegado Fl\u00e1vio Strigueta ao receber a mo\u00e7\u00e3o disse que \u201cnem sempre as pol\u00edcias s\u00e3o elogiadas. \u00c0s vezes s\u00e3o criticadas. Mas neste caso temos o reconhecimento por um trabalho que vem sendo realizado apesar das dificuldades\u201d. Ele lembrou que \u201cgovernos anteriores trataram a Seguran\u00e7a P\u00fablica com descaso\u201d. Por isso, hoje, \u201ctemos problemas de estrutura e de efetivos. Mesmo assim, policiais da nossa unidade est\u00e3o comprometidos com as necessidades da sociedade\u201d.<\/div>\n<div><\/div>\n<div>O investigador Santiago Soares, com 20 anos de pol\u00edcia, sendo 10 destacado na GCCO, declarou se sentir gratificado pelo reconhecimento, fato que eleva o sentimento de orgulho pelo desempenho da profiss\u00e3o. Al\u00e9m dele tamb\u00e9m estiveram presentes na Sess\u00e3o a Delegada Juliana Chiquito Palhares, e os policiais Valdete Silva, Cleberson Lima, Marcial Bandeira Jr e Deise Pereira, que representaram a equipe.<\/div>\n<div><\/div>\n<div>A concess\u00e3o da Mo\u00e7\u00e3o de Aplausos foi motivada por a\u00e7\u00e3o ocorrida no dia 10 de maio em que foi impedido roubo a carro forte que estava prestando servi\u00e7os a um dos maiores mercados da Capital, localizado na entrada do bairro Tijucal.<\/div>\n<div><\/div>\n<div>O Delegado Strigueta reportou que a a\u00e7\u00e3o teve \u00eaxito em fun\u00e7\u00e3o do trabalho de intelig\u00eancia realizada durante meses pela equipe da GCCO. Atrav\u00e9s de escuta autorizada e outros procedimentos investigativos, os policiais tinham ci\u00eancia que haveria um roubo a carro forte naquela regi\u00e3o. A partir disso, mas sem certeza do local exato, equipes foram direcionadas para localizar e interceptar a a\u00e7\u00e3o dos meliantes, o que foi conseguido, frustrando os planos da quadrilha.<\/div>\n<div><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por: Etevaldo de Almeida | Fonte:\u00a0http:\/\/www.camaracuiaba.mt.gov.br | Foto:\u00a0Neemias Coelho<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O vereador Dilem\u00e1rio Alencar (PROS) entregou 34 mo\u00e7\u00f5es de aplausos aos servidores p\u00fablicos que comp\u00f5em &hellip;<\/p>\n","protected":false},"author":4,"featured_media":20360,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-20359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=20359"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20359\/revisions"}],"predecessor-version":[{"id":20361,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20359\/revisions\/20361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/20360"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=20359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=20359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=20359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}