{"id":20444,"date":"2019-10-15T11:19:24","date_gmt":"2019-10-15T15:19:24","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=20444"},"modified":"2019-10-15T11:19:24","modified_gmt":"2019-10-15T15:19:24","slug":"projeto-sola","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/projeto-sola\/","title":{"rendered":"&#8220;Projeto Sola&#8221;"},"content":{"rendered":"<p>Na Semana da Reforma Protestante em Lucas do Rio Verde, Adolescestes e Jovens da Igreja Presbiteriana de Lucas do Rio Verde, em parceria com as Igrejas Evang\u00e9licas Hist\u00f3ricas da cidade, por ocasi\u00e3o da Semana da Reforma Protestante, Realizaram o CULTO DA <a href=\"https:\/\/www.cfnews.com.br\/portal\/wp-content\/uploads\/2019\/10\/1-5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-20445 alignleft\" src=\"https:\/\/www.cfnews.com.br\/portal\/wp-content\/uploads\/2019\/10\/1-5-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.cfnews.com.br\/portal\/wp-content\/uploads\/2019\/10\/1-5-300x169.jpg 300w, https:\/\/www.cfnews.com.br\/portal\/wp-content\/uploads\/2019\/10\/1-5-768x432.jpg 768w, https:\/\/www.cfnews.com.br\/portal\/wp-content\/uploads\/2019\/10\/1-5-1024x576.jpg 1024w, https:\/\/www.cfnews.com.br\/portal\/wp-content\/uploads\/2019\/10\/1-5.jpg 1032w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>REFORMA com a participa\u00e7\u00e3o especial do grupo musical, Projeto Sola.<br \/>\nCerca de 400 participantes, das Igrejas da regi\u00e3o estiveram presentes ao evento alem disto, caravanas de Sorriso, Nova Mutum, Sinop, Diamantino e Itanhag\u00e1 estiveram mobilizadas para o evento.<br \/>\nO evento aconteceu neste \u00faltimo feriado de 12 de outubro, no Novo Templo da Igreja Presbiteriana de Lucas do Rio Verde, na Avenida Tocantins 1297, cruzamento com a Av. S\u00e3o Paulo.<br \/>\nA Semana da Reforma \u00e9 uma celebra\u00e7\u00e3o que comp\u00f5e o calend\u00e1rio oficial da cidade de Lucas do Rio Verde e conta com o Apoio das Igreja Evang\u00e9licas Hist\u00f3ricas de Lucas do Rio Verde.<br \/>\nPara pastor Roosevelt, da SIB de Lucas do Rio Verde este evento \u00e9 uma grande oportunidade, pois o Projeto Sola representa um esfor\u00e7o na dire\u00e7\u00e3o correta e os jovens t\u00eam se identificado com as suas letras.<br \/>\nPara a Pastora Christa da IECLB, o evento foi maravilhoso e todos os jovens e adolescentes est\u00e3o de parab\u00e9ns!<br \/>\nPara o Pastor Manoel, da Igreja Presbiteriana de Lucas do Rio Verde, sediar um evento como este \u00e9 uma alegria e privil\u00e9gio, pois quando nos unimos podemos fazer grandes coisas para o Nosso Deus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na Semana da Reforma Protestante em Lucas do Rio Verde, Adolescestes e Jovens da Igreja &hellip;<\/p>\n","protected":false},"author":4,"featured_media":20446,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,59,77],"tags":[],"class_list":["post-20444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news","category-destaque","category-estudo"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=20444"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20444\/revisions"}],"predecessor-version":[{"id":20447,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20444\/revisions\/20447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/20446"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=20444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=20444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=20444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}