{"id":20548,"date":"2019-10-18T11:06:23","date_gmt":"2019-10-18T15:06:23","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=20548"},"modified":"2019-10-18T11:06:23","modified_gmt":"2019-10-18T15:06:23","slug":"crescimento-da-bacia-leiteira-de-mt-e-tema-de-audiencia-em-araputanga","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/crescimento-da-bacia-leiteira-de-mt-e-tema-de-audiencia-em-araputanga\/","title":{"rendered":"Crescimento da bacia leiteira de MT \u00e9 tema de audi\u00eancia em Araputanga"},"content":{"rendered":"<p>Pensando em atender as demandas dos pequenos produtores, em espec\u00edfico da bacia leiteira estadual da regi\u00e3o oeste, que possui amplo potencial de crescimento e gera\u00e7\u00e3o de renda familiar no campo, o deputado Valmir Moretto (Republicanos)\u00a0comandar\u00e1 uma audi\u00eancia publica para tratar do tema, nesta segunda-feira (21). O evento ser\u00e1 realizado no munic\u00edpio de Araputanga, escolhido estrategicamente pelo alto n\u00famero de latic\u00ednios e por estar no centro das 22 cidades que comp\u00f5es a regi\u00e3o oeste de Mato Grosso.<\/p>\n<p>Atualmente, Mato Grosso \u00e9 o 11\u00ba maior produtor de leite do pa\u00eds, com m\u00e9dia mensal de 34 mil litros e anual de 684 milh\u00f5es de litros, sendo a cadeia do leite\u00a0a mais predominante nas propriedades dos agricultores familiares. Os n\u00fameros s\u00e3o expressivos; 21% da produ\u00e7\u00e3o do leite da agricultura familiar de Mato Grosso contribuem para o cen\u00e1rio do agroneg\u00f3cio brasileiro.<\/p>\n<p>Pensando em ajudar a crescer esses n\u00fameros e melhorar o ranking do estado, Moretto\u00a0 e t\u00e9cnicos da Empaer, Embrapa, Minist\u00e9rio da Agricultura e veterin\u00e1rios especialistas em gen\u00e9tica leiteira e embri\u00e3o convidam para participar do ato, que ocorrer\u00e1 na sede do Rotary Club de Araputanga, a partir das 18h30.<\/p>\n<p>Moretto afirmou que a audi\u00eancia ir\u00e1 tratar de assuntos que possam contribuir para o crescimento da cadeia leiteira. Mato Grosso j\u00e1 esteve melhor ranqueado, mas com a falta de investimento no setor, hoje o estado est\u00e1 atr\u00e1s de estados como Pernambuco, Bahia e Cear\u00e1, que possuem hist\u00f3ricos de maior seca por ano e solo que n\u00e3o s\u00e3o t\u00e3o \u00famidos como o de Mato Grosso.<\/p>\n<p>\u201c\u00c9 uma grande oportunidade que temos para mostrar e ver\u00a0o quanto a gen\u00e9tica do gado de leite vem desenvolvendo e melhorando a bacia leiteira dos munic\u00edpios da regi\u00e3o oeste. Precisamos melhorar nossa posi\u00e7\u00e3o no ranking. J\u00e1 estivemos entre os oito melhores do Brasil e hoje somos o 11\u00ba. Ent\u00e3o vamos discutir o melhoramento e o quanto podemos crescer\u201d, disse o parlamentar.<\/p>\n<p>O secret\u00e1rio Silvano Amaral, titular da pasta de Agricultura Familiar do Estado (Seaf), tamb\u00e9m confirmou participa\u00e7\u00e3o no evento, assim como membros de latic\u00ednios, sindicatos e institui\u00e7\u00f5es banc\u00e1rias que ir\u00e3o falar sobre oportunidade de cr\u00e9dito com os pecuaristas que estiverem no local.<\/p>\n<p><strong>Servi\u00e7o\u00a0 &#8211; O que &#8211;\u00a0<\/strong>Audi\u00eancia p\u00fablica sobre a bacia leiteira de Mato Grosso<\/p>\n<p><strong>Quando \u2013<\/strong>\u00a0Segunda-feira (21)<\/p>\n<p><strong>Hor\u00e1rio \u2013<\/strong>\u00a018h30<\/p>\n<p><strong>Onde \u2013<\/strong>\u00a0Rotary Club de Araputanga<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por:\u00a0MAX AGUIAR\u00a0 | Fonte:\u00a0https:\/\/www.al.mt.gov.br | Foto:\u00a0<i>FL\u00c1VIO GARCIA\u00a0<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pensando em atender as demandas dos pequenos produtores, em espec\u00edfico da bacia leiteira estadual da &hellip;<\/p>\n","protected":false},"author":4,"featured_media":20549,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-20548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Deputado Valmir Moretto ir\u00e1 reunir t\u00e9cnicos da Embrapa, Mapa, Empaer, Senar e institui\u00e7\u00f5es banc\u00e1rias para tratar do assunto com pecuaristas da regi\u00e3o oeste","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=20548"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20548\/revisions"}],"predecessor-version":[{"id":20550,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20548\/revisions\/20550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/20549"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=20548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=20548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=20548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}