{"id":20607,"date":"2019-10-22T11:22:00","date_gmt":"2019-10-22T15:22:00","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=20607"},"modified":"2019-10-22T11:22:00","modified_gmt":"2019-10-22T15:22:00","slug":"fraudes-em-contratos-de-r-10-milhoes-firmados-entre-cepromat-e-empresa-foram-delatadas-por-silval-e-nadaf","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/fraudes-em-contratos-de-r-10-milhoes-firmados-entre-cepromat-e-empresa-foram-delatadas-por-silval-e-nadaf\/","title":{"rendered":"Fraudes em contratos de R$ 10 milh\u00f5es firmados entre Cepromat e empresa foram delatadas por Silval e Nadaf"},"content":{"rendered":"<p>Os contratos da empresa Avan\u00e7ar Tecnologia em Soft Ware com o antigo Cepromat \u2013 atual Empresa Mato-grossense de Tecnologia da Informa\u00e7\u00e3o (MTI), para fornecimento de programas de computador nas escolas estaduais, foram feitos para com o objetivo de beneficiar o empres\u00e1rio Valdir Piran, revelaram o ex-governador Silval Barbosa e o ex-secret\u00e1rio da Casa Civil, Pedro Nadaf, em depoimento prestado em junho do ano passado \u00e0 Controladoria Geral do Estado (CGE).<\/p>\n<p>Os contratos serviram como base para a deflagra\u00e7\u00e3o na manh\u00e3 desta ter\u00e7a-feira (22) da Opera\u00e7\u00e3o \u201cQuadro Negro\u201d, em que foram presos, al\u00e9m de Piran, os ex-presidentes do Cepromat, Wilson Teixeira, o Dentinho, e Djalma Soares; o ex-secret\u00e1rio-adjunto de Educa\u00e7\u00e3o, Francisvaldo Pereira Assun\u00e7\u00e3o, e o empres\u00e1rio Weydson Soares Fonteles.<\/p>\n<p>de acordo com Silval e Nadaf, os contratos com a Avan\u00e7ar Tecnologia foram firmados no valor de R$ 10 milh\u00f5es, e teriam sido alvos de fraudes, para que por meio de desvio de recursos p\u00fablicos, um d\u00edvida de R$ 10 milh\u00f5es de Silval com Piran pudesse ser quitada.<\/p>\n<p>O primeiro contrato firmado em 2014 e encerrado em 2015, foi no valor de R$ 5 milh\u00f5es e previa a aquisi\u00e7\u00e3o e instala\u00e7\u00e3o de 250 mil licen\u00e7as de uso de software educacionais a serem instalados em 278 computadores interativos, de 30 escolas de Cuiab\u00e1, V\u00e1rzea Grande e outros 11 munic\u00edpios, al\u00e9m dos servi\u00e7os de customiza\u00e7\u00e3o, m\u00eddias de instala\u00e7\u00e3o, capacita\u00e7\u00e3o dos professores, manuten\u00e7\u00e3o e acompanhamento t\u00e9cnico pedag\u00f3gico.<\/p>\n<p>Entre as irregularidades, foi descoberto que dos 815 t\u00edtulos de aulas interativas fornecidos, 101 n\u00e3o possu\u00edam nenhum conte\u00fado e 38 tinham a inser\u00e7\u00e3o de uma figura com status \u201ccarregando\u201d.\u00a0Assim, a empresa entregou efetivamente 676 t\u00edtulos, ao passo que o contrato previa o fornecimento de 900.<\/p>\n<p>J\u00e1 o segundo contrato, tamb\u00e9m firmado em 2014 e no valor de R$ 5 milh\u00f5es, previa a aquisi\u00e7\u00e3o de 188.400 licen\u00e7as de uso de softwares educacionais a serem instalados em 157 salas de aulas de 30 escolas de Mato Grosso (educa\u00e7\u00e3o b\u00e1sica), por\u00e9m de acordo com auditoria da CGE, da 30 escolas onde eram previstas as instala\u00e7\u00f5es, nove n\u00e3o receberam nenhum software.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0https:\/\/odocumento.com.br<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os contratos da empresa Avan\u00e7ar Tecnologia em Soft Ware com o antigo Cepromat \u2013 atual &hellip;<\/p>\n","protected":false},"author":4,"featured_media":20608,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,59,77],"tags":[],"class_list":["post-20607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news","category-destaque","category-estudo"],"wps_subtitle":"De acordo com dela\u00e7\u00f5es, desvios de recursos tinham objetivo de quitar um d\u00edvida de Silval Barbosa com Piran","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=20607"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20607\/revisions"}],"predecessor-version":[{"id":20609,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20607\/revisions\/20609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/20608"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=20607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=20607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=20607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}