{"id":20659,"date":"2019-10-23T11:19:34","date_gmt":"2019-10-23T15:19:34","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=20659"},"modified":"2019-10-23T11:19:34","modified_gmt":"2019-10-23T15:19:34","slug":"uma-mente-para-gloria-de-deus-13","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/uma-mente-para-gloria-de-deus-13\/","title":{"rendered":"Uma mente para Gl\u00f3ria de Deus (13)"},"content":{"rendered":"<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Uma mente para Gl\u00f3ria de Deus (13)\" width=\"1170\" height=\"658\" src=\"https:\/\/www.youtube.com\/embed\/kAG1wdi3w20?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<header class=\"entry-header\">\n<h1 class=\"entry-title\">Rei e Pastor: O Senhor na vis\u00e3o e viv\u00eancia dos salmistas (49)<\/h1>\n<\/header>\n<div class=\"entry-content\">\n<p>Essa \u00e9 a palavra condenat\u00f3ria de Deus aos sacerdotes e profetas de Israel:\u00a0<em>\u201cCuram superficialmente a ferida do meu povo, dizendo: Paz, paz; quando n\u00e3o h\u00e1 paz\u201d<\/em>\u00a0(Jr 6.14; Jr 8.11).<\/p>\n<h2><strong>Psicologia e Prega\u00e7\u00e3o<\/strong><\/h2>\n<p>Culpa \u00e9 um conceito legal resultante de uma condena\u00e7\u00e3o pelo fato de ter-se quebrado uma lei.<a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftn1\">[1]<\/a>\u00a0N\u00e3o h\u00e1 genu\u00edna culpa sem um\u00a0<em>padr\u00e3o<\/em>, e a sua\u00a0<em>transgress\u00e3o<\/em>. As Escrituras nos ensinam que todos n\u00f3s como seres respons\u00e1veis que somos, tornamo-nos culpados por transgredir a sua lei (Jo 8.34; Rm 5.12; 6.23; Ef 2.1).<\/p>\n<p>A psicologia que invadiu os nossos p\u00falpitos, em parte pela aus\u00eancia de pessoas habilitadas para expor as Escrituras com autoridade e integridade, se misturou com a teologia de tal forma, que conceitos totalmente estranhos \u00e0 Palavra s\u00e3o difundidos com naturalidade sem que nem ao menos percebamos.<\/p>\n<h2><strong>Culpa e autoestima<\/strong><\/h2>\n<p>Um desses conceitos \u00e9 de que devemos eliminar o sentimento de culpa. Outro ensinamento associado a esse, \u00e9 da import\u00e2ncia de cultivarmos uma autoestima. Como se sensa\u00e7\u00e3o de n\u00e3o termos culpa ou um alto conceito de n\u00f3s mesmos mudasse a realidade do que somos.<\/p>\n<p>Sem d\u00favida, a\u00a0<strong>culpa psicol\u00f3gica,\u00a0<\/strong>que pode perdurar pela falsa ideia de pecado ou, pela compreens\u00e3o equivocada da obra expiat\u00f3ria de Cristo e do completo perd\u00e3o de Deus, deve ser superada.<a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftn2\">[2]<\/a><\/p>\n<p>No entanto, a autoestima n\u00e3o ir\u00e1 vencer o\u00a0<strong>genu\u00edno<\/strong>\u00a0sentimento de culpa resultante de um pecado\u00a0<strong>real<\/strong>. Somente o Evangelho pode fazer por nos mostrar o que somos e como podemos nos tornar em Cristo.<\/p>\n<p>Martin Buber (1878-1965), tem um insight muito perspicaz:<\/p>\n<blockquote class=\"wp-block-quote\"><p>Se Deus faz essa pergunta [\u201cOnde voc\u00ea est\u00e1?], Ele n\u00e3o quer saber algo que ainda n\u00e3o saiba sobre a pessoa; Ele quer provocar alguma coisa nessa pessoa, algo que s\u00f3 pode ser provocado dessa maneira \u2013 com a condi\u00e7\u00e3o de que a pergunta atinja o cora\u00e7\u00e3o da pessoa, de que a pessoa se permita ser atingida no cora\u00e7\u00e3o.<\/p><\/blockquote>\n<p>Ad\u00e3o se esconde para n\u00e3o ter de dar satisfa\u00e7\u00f5es, para escapar da responsabilidade em rela\u00e7\u00e3o \u00e0 pr\u00f3pria vida. Dessa maneira, todos os homens se escondem, pois todos s\u00e3o Ad\u00e3o e est\u00e3o na situa\u00e7\u00e3o de Ad\u00e3o. Para escapar da responsabilidade por sua vida, a exist\u00eancia \u00e9 transformada num sistema de esconderijos.<a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftn3\">[3]<\/a><\/p>\n<h2><strong>Sentimento de culpa como b\u00ean\u00e7\u00e3o<\/strong><\/h2>\n<p>O pecado n\u00e3o \u00e9 uma inven\u00e7\u00e3o crist\u00e3, antes \u00e9 a realidade do homem ap\u00f3s a Queda, quando nossos primeiros Pais desobedeceram a Deus resultando tal ato em vergonha e culpa.<a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftn4\">[4]<\/a><\/p>\n<p>\u201cA verdadeira culpa tem somente uma causa: o pecado. At\u00e9 que o pecado seja tratado, a consci\u00eancia lutar\u00e1 para acusar. E o pecado \u2013 e n\u00e3o a baixa estima \u2013 \u00e9 o que o Evangelho veio derrotar\u201d, enfatiza MacArthur.<a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftn5\">[5]<\/a><\/p>\n<p>O Cristianismo n\u00e3o \u00e9 uma religi\u00e3o de doen\u00e7a e enfermidade com \u00eanfase patol\u00f3gica no pecado. Mas, sem d\u00favida, o Cristianismo trata essencialmente com doentes e, sincera e misericordiosamente apresenta com clareza o seu diagn\u00f3stico terminal. Por\u00e9m, ao mesmo tempo, apresenta a cura definitiva na expia\u00e7\u00e3o de Cristo Jesus.<\/p>\n<p>Portanto, n\u00e3o podemos falar de perd\u00e3o sem considerarmos o pecado.<\/p>\n<p>Mohler Jr., coloca bem a quest\u00e3o:<\/p>\n<blockquote class=\"wp-block-quote\"><p>Onde o pecado n\u00e3o \u00e9 encarado como pecado, a gra\u00e7a n\u00e3o pode ser gra\u00e7a. Que necessidade de expia\u00e7\u00e3o poderiam ter homens e mulheres quando lhes \u00e9 dito que o seu problema mais profundo \u00e9 algo menos do que aquilo que a B\u00edblia ensina explicitamente? O ensino fraco sobre o pecado leva \u00e0 gra\u00e7a barata e n\u00e3o conduz ao evangelho.<a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftn6\">[6]<\/a><\/p><\/blockquote>\n<p>Jesus Cristo veio salvar os enfermos, n\u00e3o os supostamente s\u00e3os:\u00a0<em>\u201c<\/em><em><sup>31<\/sup><\/em><em>\u00a0Respondeu-lhes Jesus: Os s\u00e3os n\u00e3o precisam de m\u00e9dico, e sim os doentes.\u00a0\u00a0<sup>32<\/sup>\u00a0N\u00e3o vim chamar justos, e sim pecadores, ao arrependimento\u201d<\/em>\u00a0(Lc 5.31-32).<\/p>\n<p>\u201cO Cristianismo \u00e9 a religi\u00e3o do cora\u00e7\u00e3o ferido\u201d, resume Machen.<a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftn7\">[7]<\/a><\/p>\n<p>Considerar-nos s\u00e3os quando na realidade estamos em um estado terminal \u00e9 algo terrivelmente nocivo a todos n\u00f3s.<\/p>\n<p>Por isso, o sentimento de culpa pode ser uma das b\u00ean\u00e7\u00e3os de Deus para que n\u00e3o nos entreguemos totalmente ao pecado. \u201cA culpa que sentimos como pecadores \u00e9 leg\u00edtima, natural e at\u00e9 mesmo apropriada\u201d, conclui MacArthur.<a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftn8\">[8]<\/a><\/p>\n<h2><strong>Culpa \u00e9 gra\u00e7a<\/strong><\/h2>\n<p><strong>A culpa, nestes casos, \u00e9 gra\u00e7a!<\/strong>\u00a0Por exemplo, a sensa\u00e7\u00e3o indesejada de dor, como quando tocamos distraidamente em um ferro quente, propicia um alerta para evitar um mal maior.<a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftn9\">[9]<\/a>\u00a0O painel do carro que com tanta frequ\u00eancia em nosso pa\u00eds acende indicando problemas na \u201cinje\u00e7\u00e3o\u201d, \u00e9 indesejado, por\u00e9m, passa a ser um sinal important\u00edssimo at\u00e9 ent\u00e3o impercept\u00edvel, de que algo est\u00e1 errado. Em geral, para nossa alegria (n\u00e3o \u00e9 a \u201cinje\u00e7\u00e3o\u201d) e tristeza, \u00e9 o combust\u00edvel do posto \u201cconfi\u00e1vel\u201d com bandeira, que n\u00e3o atende \u00e0s especifica\u00e7\u00f5es da mistura, j\u00e1 por si s\u00f3, bastante generosa\u2026. Portanto, a luz vermelha n\u00e3o \u00e9 o problema. Ela apenas indica que algo est\u00e1 errado.<\/p>\n<p>A culpa n\u00e3o \u00e9 o fim, mas, por vezes, \u00e9 o meio utilizado por Deus para restringir o mal e nos conduzir, no momento pr\u00f3prio, de volta a Ele pela Palavra.<a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftn10\">[10]<\/a><\/p>\n<p>A nossa consci\u00eancia, n\u00e3o cauterizada, tem um papel importante nesse processo (1Tm 4.2\/1Co 4.3-5).<a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftn11\">[11]<\/a><\/p>\n<p>Somente a Palavra pode curar nossas feridas restaurando a nossa alma. N\u00e3o h\u00e1 restabelecimento espiritual sem o retorno a Deus; \u00e0 nossa restaura\u00e7\u00e3o primeira; \u00e0 comunh\u00e3o com Deus.<\/p>\n<p>Maring\u00e1, 11 de outubro de 2019.<\/p>\n<p>Rev. Hermisten Maia Pereira da Costa<\/p>\n<hr class=\"wp-block-separator\" \/>\n<p><a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftnref1\">[1]<\/a>\u00a0Veja-se: Culpa: In: Carl F.H. Henry, org.\u00a0<em>Dicion\u00e1rio de \u00c9tica Crist\u00e3,\u00a0<\/em>S\u00e3o Paulo: Cultura Crist\u00e3, 2007, p. 152-153.<\/p>\n<p><a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftnref2\">[2]<\/a>\u00a0Sobre esses pontos, veja-se: Francis A. Schaeffer,\u00a0<em>Verdadeira espiritualidade,\u00a0<\/em>S\u00e3o Paulo: Editora Fiel, 1980, p. 144-156.<\/p>\n<p><a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftnref3\">[3]<\/a>Martin Buber,\u00a0<em>O caminho do homem segundo o ensinamento chass\u00eddico,\u00a0<\/em>S\u00e3o Paulo: \u00c9 Realiza\u00e7\u00f5es, 2011, p. 10.<\/p>\n<p><a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftnref4\">[4]<\/a>\u201cQuando Ad\u00e3o e Eva cometeram sua primeira transgress\u00e3o, a vergonha e a culpa foram sentidas pela primeira vez na hist\u00f3ria humana\u201d (R.C. Sproul,\u00a0<em>Estudos b\u00edblicos expositivos em Romanos,\u00a0<\/em>S\u00e3o Paulo: Cultura Crist\u00e3, 2011, p. 109).<\/p>\n<p><a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftnref5\">[5]<\/a>John F. MacArthur, O aconselhamento e a pecaminosidade humana: In: John F. MacArthur, et. al., eds.\u00a0<em>\u00a0Introdu\u00e7\u00e3o ao aconselhamento b\u00edblico: um guia b\u00e1sico dos princ\u00edpios e pr\u00e1tica do aconselhamento,\u00a0<\/em>S\u00e3o Paulo: Hagnos, 2004, p. 130.<\/p>\n<p><a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftnref6\">[6]<\/a>Albert Mohler Jr.,\u00a0<em>O desaparecimento de Deus,\u00a0<\/em>\u00a0S\u00e3o Paulo: Cultura Crist\u00e3, 2010, p. 32.<\/p>\n<p><a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftnref7\">[7]<\/a>J. Gresham Machen,\u00a0<em>Cristianismo e Liberalismo<\/em>, S\u00e3o Paulo: Os Puritanos, 2001, p. 71.<\/p>\n<p><a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftnref8\">[8]<\/a>\u00a0John F. MacArthur, O aconselhamento e a pecaminosidade humana: In: John F. MacArthur, et. al., eds.\u00a0<em>\u00a0Introdu\u00e7\u00e3o ao aconselhamento b\u00edblico: um guia b\u00e1sico dos princ\u00edpios e pr\u00e1tica do aconselhamento,\u00a0<\/em>S\u00e3o Paulo: Hagnos, 2004, p. 138. Do mesmo modo, escreveu Stott: \u201cSe os seres humanos pecaram (o que aconteceu), e se s\u00e3o respons\u00e1veis por seus pecados (o que s\u00e3o), ent\u00e3o s\u00e3o culpados perante Deus. A culpa \u00e9 dedu\u00e7\u00e3o l\u00f3gica das premissas do pecado e responsabilidade. Erramos por nossa pr\u00f3pria falta, e, portanto, devemos arcar com a justa penalidade de nosso erro\u201d (John R.W. Stott,\u00a0<em>A Cruz de Cristo,<\/em>Miami: Editora Vida, 1991, p. 86).<\/p>\n<p><a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftnref9\">[9]<\/a>\u00a0Veja-se: Jay E. Adams,\u00a0<em>Teologia do aconselhamento crist\u00e3o,<\/em>Eus\u00e9bio, CE.: Editora Peregrino, 2016, p. 202-203.<\/p>\n<p><a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftnref10\">[10]<\/a>\u201cEstejamos seguros de que quando Deus nos faz sentir Sua m\u00e3o, de modo a humilhar-nos sob ela, que Deus nos est\u00e1 fazendo um favor especial, e que se trata de um privil\u00e9gio que Ele n\u00e3o concede a ningu\u00e9m, sen\u00e3o a seus pr\u00f3prios filhos\u201d (Juan Calvino, Bienaventurado el Hombre a Quem Dios Corrige: In:\u00a0<em>Sermones Sobre Job,<\/em>\u00a0Jenison, Michigan: T.E.L.L., 1988, (Sermon n\u00ba 3), p. 49).<\/p>\n<p><a href=\"https:\/\/www.hermisten.com.br\/rei-e-pastor-o-senhor-na-visao-e-vivencia-dos-salmistas-49\/#_ftnref11\">[11]<\/a><em>\u201cP<\/em><em>ela hipocrisia dos que falam mentiras e que t\u00eam cauterizada a pr\u00f3pria consci\u00eancia\u201d\u00a0<\/em>(1Tm 4.2).\u00a0<em>\u201cTodavia, a mim mui pouco se me d\u00e1 de ser julgado por v\u00f3s ou por tribunal humano; nem eu tampouco julgo a mim mesmo.\u00a0<sup>4<\/sup>Porque de nada me arg\u00fai a consci\u00eancia; contudo, nem por isso me dou por justificado, pois quem me julga \u00e9 o Senhor.\u00a0\u00a0<sup>5<\/sup>\u00a0Portanto, nada julgueis antes do tempo, at\u00e9 que venha o Senhor, o qual n\u00e3o somente trar\u00e1 \u00e0 plena luz as coisas ocultas das trevas, mas tamb\u00e9m manifestar\u00e1 os des\u00edgnios dos cora\u00e7\u00f5es\u201d\u00a0<\/em>(1Co 4.3-5).<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Rei e Pastor: O Senhor na vis\u00e3o e viv\u00eancia dos salmistas (49) Essa &hellip;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-20659","post","type-post","status-publish","format-standard","hentry","category-cf-news"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=20659"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20659\/revisions"}],"predecessor-version":[{"id":20660,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20659\/revisions\/20660"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=20659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=20659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=20659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}