{"id":20809,"date":"2019-10-31T10:56:26","date_gmt":"2019-10-31T14:56:26","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=20809"},"modified":"2019-10-31T10:56:26","modified_gmt":"2019-10-31T14:56:26","slug":"mauro-diz-que-troca-de-secretario-de-bolsonaro-impede-que-estudo-sobre-retomada-do-vlt-seja-concluido-em-novembro","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/mauro-diz-que-troca-de-secretario-de-bolsonaro-impede-que-estudo-sobre-retomada-do-vlt-seja-concluido-em-novembro\/","title":{"rendered":"Mauro diz que troca de secret\u00e1rio de Bolsonaro impede que estudo sobre retomada do VLT seja conclu\u00eddo em novembro"},"content":{"rendered":"<p>Apesar de o ministro do Desenvolvimento Regional (MDR), Gustavo Canuto, ter informado que a decis\u00e3o sobre a conclus\u00e3o das obras do Ve\u00edculo Leve Sobre Trilhos (VLT), em Cuiab\u00e1 e V\u00e1rzea Grande, deve ser divulgada at\u00e9 o pr\u00f3ximo dia 11 de novembro, o governador de Mato Grosso, Mauro Mendes (DEM), n\u00e3o acredita que o prazo ser\u00e1 mentido.<\/p>\n<p>Em coletiva no Pal\u00e1cio Paiagu\u00e1s, na tarde de quarta-feira (30), Mendes lamentou a troca, pela terceira vez no governo Jair Bolsonaro (PSL), do secret\u00e1rio nacional de Mobilidade Urbana. \u201cPrimeiro n\u00f3s lamentamos porque teve nova troca do secret\u00e1rio nacional de mobilidade urbana. Tinha um, trocou e agora vai trocar de novo. Eu j\u00e1 adianto que eles n\u00e3o v\u00e3o conseguir entregar esse relat\u00f3rio no dia 11 de novembro\u201d, destacou o governador.<\/p>\n<p>Mendes diz que aguarda uma justificativa t\u00e9cnica com a defini\u00e7\u00e3o de um novo prazo para a entrega do relat\u00f3rio que est\u00e1 sendo elaborado por uma equipe nacional com a participa\u00e7\u00e3o de t\u00e9cnicos do governo de Mato Grosso. \u201cEstou aguardando que eles me apresentem a justificativa t\u00e9cnica disso e qual o novo prazo necess\u00e1rio. Agora, muito disso foi em fun\u00e7\u00e3o dessas mudan\u00e7as que ocorreram em Bras\u00edlia na Secretaria Nacional de Mobilidade Urbana, um \u00f3rg\u00e3o t\u00e3o importante na fun\u00e7\u00e3o dos trabalhos t\u00e9cnicos que estamos fazendo para subsidiar uma decis\u00e3o final sobre o VLT\u201d, adiantou.<\/p>\n<p>O governador afirmou que s\u00f3 vai anunciar alguma decis\u00e3o sobre o Ve\u00edculo Leve sobre Trilhos com muita seguran\u00e7a. \u201cVamos fazer isso no tempo necess\u00e1rio, com a seguran\u00e7a necess\u00e1ria. Afinal de contas, temos a\u00ed cinco anos da paralisa\u00e7\u00e3o das obras. Eu j\u00e1 disse e repito, vamos tomar essa decis\u00e3o \u00e0 luz de informa\u00e7\u00f5es t\u00e9cnicas, n\u00e3o de disse me disse. Querer, todos querem tudo, mas n\u00e3o vamos tomar uma decis\u00e3o em cima de oba- oba\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0https:\/\/odocumento.com.br \u00a0| Foto:\u00a0Tch\u00e9lo Figueiredo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apesar de o ministro do Desenvolvimento Regional (MDR), Gustavo Canuto, ter informado que a decis\u00e3o &hellip;<\/p>\n","protected":false},"author":4,"featured_media":20810,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-20809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"Relat\u00f3rio deveria ser conclu\u00eddo at\u00e9 o pr\u00f3ximo dia 11, por\u00e9m, prazo foi descartado pelo governador ","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=20809"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20809\/revisions"}],"predecessor-version":[{"id":20811,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20809\/revisions\/20811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/20810"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=20809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=20809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=20809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}