{"id":20851,"date":"2019-11-01T11:22:46","date_gmt":"2019-11-01T15:22:46","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=20851"},"modified":"2019-11-01T11:22:46","modified_gmt":"2019-11-01T15:22:46","slug":"mendes-espera-r-400-mi-que-devem-ajudar-a-quitar-folha-e-13o","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/mendes-espera-r-400-mi-que-devem-ajudar-a-quitar-folha-e-13o\/","title":{"rendered":"Mendes espera R$ 400 mi, que devem ajudar a quitar folha e 13\u00ba"},"content":{"rendered":"<p>O governador Mauro Mendes (DEM) afirmou que trabalha com a expectativa de arrecadar R$ 400 milh\u00f5es por meio do Mutir\u00e3o de Concilia\u00e7\u00e3o Fiscal, lan\u00e7ado pelo Executivo e Judici\u00e1rio na manh\u00e3 desta sexta-feira (1\u00ba).<\/p>\n<p>Os recursos, segundo ele, ser\u00e3o usados para custear despesas do Governo, entre as quais a folha salarial de dezembro e o d\u00e9cimo terceiro do funcionalismo.<\/p>\n<p>\u201cEsperamos chegar ao final do Mutir\u00e3o e conciliar algo em torno de R$ 400 milh\u00f5es, fazendo com que isso traga recursos importantes para o equil\u00edbrio fiscal do Estado nesse final de primeiro ano\u201d, disse Mendes.<\/p>\n<p>\u201c\u00c9 um recurso que entra direto na Fonte 100 e \u00e9 utilizado para as diversas situa\u00e7\u00f5es demandadas: pagar sal\u00e1rios, custeio, investimentos, pagar poderes, pagar Sa\u00fade, transferir para os munic\u00edpios. Enfim, cumprir com obriga\u00e7\u00f5es do Estado\u201d, acrescentou o governador.<\/p>\n<p style=\"text-align: left;\">\n<div class=\"quote-wrapper right\">\n<div class=\"quote-img-wrapper right\" style=\"text-align: left;\"><img decoding=\"async\" class=\"quote-img right\" src=\"https:\/\/www.midianews.com.br\/images\/aspas_right.gif\" \/><\/div>\n<h2 class=\"quote-content\" style=\"text-align: left;\">Esperamos chegar ao final do Mutir\u00e3o e conciliar algo em torno de R$ 400 milh\u00f5es, fazendo com que isso traga recursos importantes para o equil\u00edbrio fiscal do Estado nesse final de primeiro ano<\/h2>\n<\/div>\n<p>Conforme o secret\u00e1rio de Estado de Fazenda, Rog\u00e9rio Gallo, somente para custear o d\u00e9cimo terceiro s\u00e3o necess\u00e1rios R$ 570 milh\u00f5es neste final de ano. J\u00e1 a folha de dezembro soma R$ 500 milh\u00f5es.<\/p>\n<p>Ainda segundo ele, dos R$ 400 milh\u00f5es esperados pelo Executivo no Mutir\u00e3o, ao menos R$ 250 milh\u00f5es devem ser de valores negociados \u00e0 vista e que j\u00e1 entram no caixa do Estado de forma imediata.<\/p>\n<p><strong>Negocia\u00e7\u00e3o<\/strong><\/p>\n<p>Durante o Mutir\u00e3o Fiscal ser\u00e1 poss\u00edvel renegociar d\u00edvidas fiscais e tribut\u00e1rias geradas no \u00e2mbito dos seguintes \u00f3rg\u00e3os: Secretaria de Fazenda (Sefaz), Procuradoria Geral do Estado (PGE), Instituto de Defesa Agropecu\u00e1ria (Indea), Departamento Estadual de Tr\u00e2nsito de Mato Grosso (Detran), Procon e Ag\u00eancia Estadual de Regula\u00e7\u00e3o dos Servi\u00e7os P\u00fablicos Delegados (Ager).<\/p>\n<p>As d\u00edvidas oriundas de multas e taxas do Detran, Sema, Indea, Procon-MT e Ager poder\u00e3o ser renegociadas por meio do Regularize.<\/p>\n<p>Segundo Galo, para as negocia\u00e7\u00f5es feitas \u00e0 vista, os descontos em juros e multas chegam a 75%. J\u00e1 os parcelamentos t\u00eam op\u00e7\u00f5es que permitem descontos de at\u00e9 70% nesses encargos.<\/p>\n<p>\u201cTemos ao longo desses 30 dias a possibilidade de at\u00e9 75% de descontos de juros e multas no pagamento \u00e0 vista. E o parcelamento, indo at\u00e9 48 vezes, com descontos decrescentes\u201d, disse.<\/p>\n<p>\u201cTrata-se de uma a\u00e7\u00e3o para permitir que o cidad\u00e3o e as empresas em Mato Grosso possam regularizar sua vida junto ao Fisco\u201d, acrescentou o governador.<\/p>\n<p><strong>Servi\u00e7o<\/strong><\/p>\n<p>O mutir\u00e3o \u00e9 realizado em parceria com o Poder Judici\u00e1rio Estadual. O atendimento \u00e9 feito no segundo andar da Arena Pantanal, de segunda a sexta-feira, das 8h \u00e0s 18h, sem intervalo para almo\u00e7o, com distribui\u00e7\u00e3o de senhas at\u00e9 \u00e0s 16h. O acesso \u00e9 pelo port\u00e3o A do est\u00e1dio.<\/p>\n<p>A exce\u00e7\u00e3o ficar\u00e1 por conta dos dias em que haver\u00e1 jogos pelo Campeonato Brasileiro da s\u00e9rie B. Nestas datas (1\u00ba, 5 e 12\/11), o atendimento ficar\u00e1 reduzido at\u00e9 \u00e0s 13h, com distribui\u00e7\u00e3o de senhas at\u00e9 \u00e0s 11h.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por:\u00a0CAMILA RIBEIRO | Fonte:\u00a0https:\/\/www.midianews.com.br | Foto:\u00a0Victor Ostetti<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Mauro Mendes (DEM) afirmou que trabalha com a expectativa de arrecadar R$ 400 &hellip;<\/p>\n","protected":false},"author":4,"featured_media":20852,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-20851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"Descontos em juros e multas chegam a 75%, caso o pagamento seja realizado \u00e0 vista","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=20851"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20851\/revisions"}],"predecessor-version":[{"id":20853,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20851\/revisions\/20853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/20852"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=20851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=20851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=20851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}