{"id":20897,"date":"2019-11-04T13:14:09","date_gmt":"2019-11-04T17:14:09","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=20897"},"modified":"2019-11-04T13:14:09","modified_gmt":"2019-11-04T17:14:09","slug":"audiencia-da-loa-2020-ocorre-na-proxima-terca-dia-05-2","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/audiencia-da-loa-2020-ocorre-na-proxima-terca-dia-05-2\/","title":{"rendered":"Audi\u00eancia da LOA 2020 ocorre na pr\u00f3xima ter\u00e7a, dia 05"},"content":{"rendered":"<div>A audi\u00eancia para debater a Lei Or\u00e7ament\u00e1ria Anual (LOA) do pr\u00f3ximo ano marcada para a tarde desta sexta-feira (1\u00ba) foi adiada para a pr\u00f3xima ter\u00e7a-feira, dia 05. Esta ser\u00e1 a primeira discuss\u00e3o em torno do tema, onde o enfoque ser\u00e1 Sa\u00fade, Meio Ambiente e Desenvolvimento Urbano, assim como Agricultura, Trabalho e Desenvolvimento Econ\u00f4mico.<\/div>\n<div><\/div>\n<div>O debate ser\u00e1 realizado a partir das 18h30 no plen\u00e1rio do Parlamento Municipal. Ele ser\u00e1 conduzido pela Comiss\u00e3o de Fiscaliza\u00e7\u00e3o e Acompanhamento da Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria, presidida pelo vereador Marcelo Bussiki (PSB).<\/div>\n<div><\/div>\n<div>No total, ser\u00e3o realizadas tr\u00eas audi\u00eancias p\u00fablicas para debater a pe\u00e7a or\u00e7ament\u00e1ria de 2020. As outras duas acontecem nos dias 22 de novembro e 6 de dezembro, respectivamente.<\/div>\n<div><\/div>\n<div>A segunda est\u00e1 agendada para as 14 horas e tratar\u00e1 sobre Educa\u00e7\u00e3o, Assist\u00eancia Social e Desenvolvimento Humano e Cultura, Esporte e Turismo.<\/div>\n<div><\/div>\n<div>J\u00e1 a \u00faltima Serpa realizada a partir das 9 horas e ter\u00e1 como tema Comunica\u00e7\u00e3o, Ordem P\u00fablica, Habita\u00e7\u00e3o e Regulariza\u00e7\u00e3o Fundi\u00e1ria, Obras P\u00fablicas, Servi\u00e7os Urbanos, Mobilidade Urbana e Gest\u00e3o.<\/div>\n<div><\/div>\n<div>A pe\u00e7a or\u00e7ament\u00e1ria deve ser votada pelos vereadores antes do recesso parlamentar de fim de ano. Ap\u00f3s as audi\u00eancias p\u00fablicas, os parlamentares poder\u00e3o apresentar emendas sugerindo altera\u00e7\u00f5es na proposta original encaminhada pela Prefeitura.<\/div>\n<div>A Lei Or\u00e7ament\u00e1ria Anual (LOA) de 2020 prev\u00ea receita e despesa na ordem de R$ 3,3 bilh\u00f5es, ou seja, acr\u00e9scimo de mais de R$ 700 milh\u00f5es se comparado ao or\u00e7amento deste ano.<\/div>\n<div><\/div>\n<div>O que chama a aten\u00e7\u00e3o na pe\u00e7a or\u00e7ament\u00e1ria \u00e9 recurso destinado a \u00e1rea da sa\u00fade. No pr\u00f3ximo ano, o or\u00e7amento da Secretaria de Sa\u00fade ser\u00e1 superior a R$ 1 bilh\u00e3o, totalizando R$ 1,130 bi. A previs\u00e3o de receita e despesa da \u00e1rea da sa\u00fade representa quase 35% do or\u00e7amento total do Munic\u00edpio.<\/div>\n<div><\/div>\n<div>O or\u00e7amento previsto da Secretaria de Obras na LOA 2020 \u00e9 de 591 milh\u00f5es, enquanto da Secretaria de Educa\u00e7\u00e3o \u00e9 de 561 milh\u00f5es. As secretarias da Mulher e do Turismo, propostas que ser\u00e3o encaminhadas na reforma administrativa, ter\u00e3o or\u00e7amento de R$ 2,5 milh\u00f5es e R$ 4,9 milh\u00f5es, respectivamente.<\/div>\n<div><\/div>\n<div>Na LOA 2020 j\u00e1 constam os empr\u00e9stimos realizados pela gest\u00e3o para investimento em obras, que somam mais de R$ 300 milh\u00f5es. Um deles \u00e9 o empr\u00e9stimo de R$ 100 milh\u00f5es para pavimentar mais 20 bairros que ser\u00e1 apreciado pelos vereadores.<\/div>\n<div><\/div>\n<div>Outro \u00e9 de R$ 50,8 milh\u00f5es, feito por meio de financiamento com o Banco do Brasil, para a constru\u00e7\u00e3o dos dois viadutos.<\/div>\n<div>Os demais financiamentos foram para pavimenta\u00e7\u00e3o. Um em andamento com o Banco do Brasil de R$ 28 milh\u00f5es e outro contra\u00eddo junto \u00e0 Caixa Econ\u00f4mica Federal de R$ 125 milh\u00f5es para a constru\u00e7\u00e3o do Contorno Leste.<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por: Kamila Arruda | Fonte:\u00a0http:\/\/www.camaracuiaba.mt.gov.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A audi\u00eancia para debater a Lei Or\u00e7ament\u00e1ria Anual (LOA) do pr\u00f3ximo ano marcada para a &hellip;<\/p>\n","protected":false},"author":4,"featured_media":20898,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59,60],"tags":[],"class_list":["post-20897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=20897"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20897\/revisions"}],"predecessor-version":[{"id":20899,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/20897\/revisions\/20899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/20898"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=20897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=20897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=20897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}