{"id":21189,"date":"2019-11-14T15:56:54","date_gmt":"2019-11-14T19:56:54","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=21189"},"modified":"2019-11-14T15:56:54","modified_gmt":"2019-11-14T19:56:54","slug":"prefeito-parabeniza-dona-domingas-por-alta-honraria-recebida-da-ufmt","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/prefeito-parabeniza-dona-domingas-por-alta-honraria-recebida-da-ufmt\/","title":{"rendered":"Prefeito parabeniza Dona Domingas por alta honraria recebida da UFMT"},"content":{"rendered":"<p style=\"font-weight: 400;\">A cultura cuiabana est\u00e1 em festa. Fundadora do grupo Flor Ribeirinha, um dos mais tradicionais de dan\u00e7as t\u00edpicas, o siriri cuiabano, Domingas Leonor, a Dona Domingas, foi agraciada com um dos mais altos t\u00edtulos concedidos pela Universidade Federal de Mato Grosso (UFMT). Pela incans\u00e1vel luta para divulgar e promover o siriri, o rasqueado, o boi a serra e outras tradi\u00e7\u00f5es mato-grossenses, ela recebeu a condecora\u00e7\u00e3o de Doutora Honoris Causa.<\/p>\n<p style=\"font-weight: 400;\">O grupo Flor Ribeirinha j\u00e1 conquistou muitos t\u00edtulos, como o do Festival Internacional na Turquia, e agora, no ano do tricenten\u00e1rio da Capital, desfilam pelo mundo a arte, a gra\u00e7a e a beleza da gente cuiabana. \u201cO agradecimento deve ser sempre nosso, que temos orgulho de participar dessa hist\u00f3ria de alguma forma. Somos gratos pela Domingas nos representar t\u00e3o bem, n\u00e3o s\u00f3 no nosso munic\u00edpio com as belas apresenta\u00e7\u00f5es, mas em todo Mato Grosso, Brasil e no mundo. Recebemos a not\u00edcia desse t\u00edtulo com muita honra\u201d, comentou Emanuel Pinheiro.<\/p>\n<p style=\"font-weight: 400;\">Na oportunidade, Pinheiro fez quest\u00e3o de dizer da honra de Cuiab\u00e1 ter uma figura t\u00e3o importante como essa. \u201cQuem ganhou esse t\u00edtulo n\u00e3o foi apenas a Dona Domingas e seu grupo, mas sim a nossa Cuiab\u00e1. Que o exemplo de for\u00e7a, persist\u00eancia e amor pela cultura regional dela sirva de inspira\u00e7\u00e3o para outros grupos. Temos muito talentos ainda escondidos que precisam ser descobertos e valorizados\u201d, disse.<\/p>\n<p style=\"font-weight: 400;\">A aprova\u00e7\u00e3o da homenagem para a incans\u00e1vel militante da cultura tradicional cuiabana foi por humanidade pelo Conselho da UFMT. Domingas foi escolhida por representar a hist\u00f3ria da universidade com a comunidade de S\u00e3o Gon\u00e7alo Beira Rio, com a cultura popular, com a tradi\u00e7\u00e3o. A entrega do t\u00edtulo ser\u00e1 no dia 10 de dezembro, em cerim\u00f4nia no Foyer do Teatro da UFMT.<\/p>\n<p style=\"font-weight: 400;\">A honraria \u00e9 concedida para aquelas pessoas que se destacam em sua \u00e1rea de atua\u00e7\u00e3o, possuem o reconhecimento da sociedade pelo seu trabalho realizado, mas nem sempre t\u00eam gradua\u00e7\u00e3o ou especializa\u00e7\u00e3o. O termo Doutor Honoris Causa significa \u201cpor causa de honra\u201d, em latim.<\/p>\n<p style=\"font-weight: 400;\">\u201cN\u00e3o poderia ter uma pessoa melhor para receber um t\u00edtulo de tamanha grandeza. Mulher de fibra, que trabalha e dedica sua vida para expandir e difundir a cultura cuiabana para os quatro cantos do Brasil e do mundo. Sinto me honrado, de como prefeito da Capital repassar uma not\u00edcia t\u00e3o valiosa como essa. A trajet\u00f3ria ascendente, repleta de conquistas, atinge um ponto elevado, de um dos maiores \u00edcones locais\u201d, concluiu Pinheiro.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por:\u00a0CAROLINA MIRANDA | Foto:\u00a0Luiz Alves | Fonte:\u00a0http:\/\/www.cuiaba.mt.gov.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A cultura cuiabana est\u00e1 em festa. Fundadora do grupo Flor Ribeirinha, um dos mais tradicionais &hellip;<\/p>\n","protected":false},"author":4,"featured_media":21190,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-21189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"Pela incans\u00e1vel luta para promover a cultura mato-grossenses, ela recebeu o t\u00edtulo de Doutora Honoris Causa","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=21189"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21189\/revisions"}],"predecessor-version":[{"id":21191,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21189\/revisions\/21191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/21190"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=21189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=21189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=21189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}