{"id":21299,"date":"2019-11-21T10:51:02","date_gmt":"2019-11-21T14:51:02","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=21299"},"modified":"2019-11-21T10:51:02","modified_gmt":"2019-11-21T14:51:02","slug":"cpi-da-energisa-define-primeiras-oitivas","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/cpi-da-energisa-define-primeiras-oitivas\/","title":{"rendered":"CPI da Energisa define primeiras oitivas"},"content":{"rendered":"<p>A Assembleia Legislativa de Mato Grosso (ALMT) realizou, na ter\u00e7a-feira (19), a segunda reuni\u00e3o ordin\u00e1ria da Comiss\u00e3o Parlamentar de Inqu\u00e9rito (CPI) da Energisa. Na reuni\u00e3o, foram\u00a0entregues ao corpo t\u00e9cnico da CPI v\u00e1rios documentos com den\u00fancias e assinaturas relatando as defici\u00eancias dos servi\u00e7os que a Energisa tem prestado \u00e0\u00a0sociedade mato-grossense.<\/p>\n<p>\u201cS\u00e3o v\u00e1rias den\u00fancias que t\u00eam chegado, a come\u00e7ar pelo aumento abusivo das faturas de energia el\u00e9trica e as graves den\u00fancias da m\u00e1 presta\u00e7\u00e3o de servi\u00e7os. Hoje entregamos esses documentos ao corpo t\u00e9cnico da Casa para que possam ser analisados\u201d, destacou Elizeu Nascimento.<\/p>\n<p>\u201cDas 11 concession\u00e1rias que a Energisa tem no pa\u00eds, quatro est\u00e3o sendo investigadas atrav\u00e9s de CPIs. Primeiro vamos ouvir os reclamantes, depois ouvir os outros segmentos que ser\u00e3o importantes para come\u00e7ar a fazer a compara\u00e7\u00e3o e ent\u00e3o chegar \u00e0s conclus\u00f5es importantes\u201d, explicou o relator, deputado Carlos\u00a0Avallone (PSDB).<\/p>\n<p>Os deputados membros da CPI aprovaram as convoca\u00e7\u00f5es. As primeiras oitivas ser\u00e3o com o\u00a0presidente do Sindicato dos Trabalhadores nas Ind\u00fastrias Urbanas do Estado de Mato Grosso (STIU-MT), Dillon Caporossi, que falar\u00e1 \u00e0 CPI no\u00a026 de novembro, \u00e0s 14 horas, e a secret\u00e1ria-adjunta do Procon-MT, Gisela Simona, que ser\u00e1 ouvida no\u00a0dia 5 de dezembro, \u00e0s\u00a016 horas,\u00a0ambas na sala das comiss\u00f5es.<\/p>\n<p>De acordo com o deputado estadual Elizeu Nascimento (DC), que preside os trabalhos da CPI, os depoimentos s\u00e3o de extrema import\u00e2ncia para esclarecimentos de d\u00favidas e apura\u00e7\u00e3o de informa\u00e7\u00f5es.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por:\u00a0LAIS MEDEIROS DO CANTO\u00a0 | Fonte:\u00a0https:\/\/www.al.mt.gov.br | Foto:\u00a0<i>\u00a0Ronaldo Mazza<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Assembleia Legislativa de Mato Grosso (ALMT) realizou, na ter\u00e7a-feira (19), a segunda reuni\u00e3o ordin\u00e1ria &hellip;<\/p>\n","protected":false},"author":4,"featured_media":21300,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,59,77],"tags":[],"class_list":["post-21299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news","category-destaque","category-estudo"],"wps_subtitle":"Os primeiros a depor ser\u00e3o o presidente do STIU-MT, Dillon Caporossi, e a secret\u00e1ria-adjunta do Procon-MT, Gisela Simona.","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=21299"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21299\/revisions"}],"predecessor-version":[{"id":21301,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21299\/revisions\/21301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/21300"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=21299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=21299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=21299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}