{"id":21348,"date":"2019-11-22T15:04:14","date_gmt":"2019-11-22T19:04:14","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=21348"},"modified":"2019-11-22T15:04:14","modified_gmt":"2019-11-22T19:04:14","slug":"justica-suspende-registro-de-63-agrotoxicos-autorizados-em-setembro","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/justica-suspende-registro-de-63-agrotoxicos-autorizados-em-setembro\/","title":{"rendered":"Justi\u00e7a suspende registro de 63 agrot\u00f3xicos autorizados em setembro"},"content":{"rendered":"<div class=\"mc-column content-text active-extra-styles active-capital-letter\" data-block-type=\"unstyled\" data-block-weight=\"35\" data-block-id=\"1\">\n<p class=\"content-text__container theme-color-primary-first-letter\" data-track-category=\"Link no Texto\" data-track-links=\"\">A Justi\u00e7a Federal do Cear\u00e1 suspendeu o\u00a0registro de 63 agrot\u00f3xicos feito pelo Minist\u00e9rio da Agricultura em setembro. A decis\u00e3o \u00e9 provis\u00f3ria e ainda cabe recurso e o governo disse que ainda n\u00e3o foi notificado.<\/p>\n<\/div>\n<div class=\"wall protected-content\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"50\" data-block-id=\"2\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O pedido foi feito por meio de uma A\u00e7\u00e3o Popular movida pelo deputado federal C\u00e9lio Studart (PV-CE). A decis\u00e3o foi publicada na segunda-feira (19) e o juiz respons\u00e1vel pela a\u00e7\u00e3o, Lu\u00eds Praxedes Vieira da Silva, entendeu que a comercializa\u00e7\u00e3o destes produtos pode trazer riscos \u00e0 sa\u00fade e ao meio ambiente.<\/p>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"36\" data-block-id=\"4\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Os produtos registrados em setembro, os mais pol\u00eamicos s\u00e3o os que t\u00eam como base o sulfoxaflor, que \u00e9 relacionado \u00e0 redu\u00e7\u00e3o de enxames de abelhas e est\u00e1 em estudo no exterior (veja a lista completa abaixo).<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"22\" data-block-id=\"5\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Outros produtos que tiveram o registro suspensos est\u00e3o princ\u00edpios ativos fluopiram, que \u00e9 usado para matar fungos, e o dinotefuram, um inseticida.<\/p>\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O\u00a0registro dos 63 agrot\u00f3xicos\u00a0suspensos pela Justi\u00e7a ocorreu no dia 17 de setembro. Desse total, 2 s\u00e3o princ\u00edpios ativos (que servir\u00e3o de base para produtos in\u00e9ditos) e 5 s\u00e3o novos produtos que estar\u00e3o \u00e0 venda. Os demais 56 s\u00e3o gen\u00e9ricos de pesticidas que j\u00e1 existem no mercado.<\/p>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"67\" data-block-id=\"8\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">\u201cA permiss\u00e3o para livre comercializa\u00e7\u00e3o dos agrot\u00f3xicos com alta taxa de toxibilidade (sic) \u00e9 incompat\u00edvel com os princ\u00edpios que regem a atividade econ\u00f4mica [\u2026] De nada adiante um pa\u00eds economicamente rico com uma popula\u00e7\u00e3o gradativamente doente, o que ser\u00e1 desencadeado dentro em breve se n\u00e3o combatermos hoje a pr\u00e1tica inclusiva de tais agentes qu\u00edmicos e biol\u00f3gicos nocivos ao nosso meio ambiente\u201d, disse o magistrado na decis\u00e3o.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"43\" data-block-id=\"9\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Procurado pelo\u00a0<strong>G1<\/strong>, o Minist\u00e9rio da Agricultura disse que ainda n\u00e3o foi notificado da decis\u00e3o e que \u201coportunamente, ir\u00e1 analisar as medidas cab\u00edveis\u201d. O governo tem 15 dias para contestar a medida ap\u00f3s sua publica\u00e7\u00e3o. No ano,\u00a0o governo registrou 382 novos pesticidas.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"2\" data-block-id=\"10\">\n<div class=\"content-intertitle\">\n<h2>Agrot\u00f3xicos suspensos<\/h2>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"35\" data-block-id=\"11\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O\u00a0<strong>dinotefuram<\/strong>\u00a0\u00e9 utilizado no controle de insetos sugadores, como percevejos. Ele poder\u00e1 ser aplicado em 16 atividades: arroz, aveia, batata, caf\u00e9, cana-de-a\u00e7\u00facar, centeio, cevada, citros, feij\u00e3o, milheto, milho, pastagem, soja, tomate, trigo e triticale.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"48\" data-block-id=\"12\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Ele \u00e9 considerado extremamente t\u00f3xico pela Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa). O pesticida n\u00e3o tem registro para uso agr\u00edcola na Uni\u00e3o Europeia (apenas dom\u00e9stico) e est\u00e1 em reavalia\u00e7\u00e3o nos Estados Unidos, onde o primeiro registro consta de 1985. Para uso agr\u00edcola, o produto tem aval desde 2004.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"32\" data-block-id=\"13\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">J\u00e1 o fungicida\u00a0<strong>fluopiram<\/strong>\u00a0\u00e9 um produto indicado para combater parasitas que atacam a ra\u00edzes das plantas (nematoides) e ter\u00e1 autoriza\u00e7\u00e3o para 7 culturas: algod\u00e3o, batata, caf\u00e9, cana-de-a\u00e7\u00facar, feij\u00e3o, milho e soja.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">O Minist\u00e9rio da Agricultura afirmou que o produto estava na fila para registro no Brasil havia 10 anos. Ele possui registro na Uni\u00e3o Europeia e tamb\u00e9m est\u00e1 autorizado nos Estados Unidos desde 2012 (e em an\u00e1lise para uso residencial).<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"10\" data-block-id=\"18\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><strong>Veja a lista dos outros princ\u00edpios ativos registrados no dia:<\/strong><\/p>\n<\/div>\n<div class=\"row medium-uncollapsed content-media content-photo\" data-block-type=\"backstage-photo\" data-block-id=\"19\">\n<div class=\"mc-column content-media__container\">\n<div class=\"progressive-img can-open-lightbox\" data-min-size=\"1008x3187\" data-min-size-url=\"https:\/\/s2.glbimg.com\/BV2S8LbOoVqSHhPi4VoXMyzRxUQ=\/0x0:1380x4364\/1008x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png\" data-max-size=\"1600x5059\" data-max-size-url=\"https:\/\/s2.glbimg.com\/yLIL1Ix9gcqbQKd_q7LpYhExxsw=\/0x0:1380x4364\/1600x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png\" data-media-index=\"1\">\n<div class=\"placeholder-container\"><\/div>\n<picture><source srcset=\"https:\/\/s2.glbimg.com\/b5yM-2leHAdM36yh8UnRa6Rxu_g=\/0x0:1380x4364\/600x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png 1x, https:\/\/s2.glbimg.com\/YKsFcC7W4SKKAq-UGYvo6USwmnw=\/0x0:1380x4364\/1200x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png 2x\" media=\"(max-width: 1024px)\" data-src=\"https:\/\/s2.glbimg.com\/b5yM-2leHAdM36yh8UnRa6Rxu_g=\/0x0:1380x4364\/600x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png 1x, https:\/\/s2.glbimg.com\/YKsFcC7W4SKKAq-UGYvo6USwmnw=\/0x0:1380x4364\/1200x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png 2x\" \/><source srcset=\"https:\/\/s2.glbimg.com\/tVThp2QG3V7AKRED5Xw_lMJcNW0=\/0x0:1380x4364\/640x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png 1x, https:\/\/s2.glbimg.com\/KbTseVU-oG5OiCBGRWApRATggCo=\/0x0:1380x4364\/1280x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png 2x\" media=\"(max-width: 1280px)\" data-src=\"https:\/\/s2.glbimg.com\/tVThp2QG3V7AKRED5Xw_lMJcNW0=\/0x0:1380x4364\/640x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png 1x, https:\/\/s2.glbimg.com\/KbTseVU-oG5OiCBGRWApRATggCo=\/0x0:1380x4364\/1280x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png 2x\" \/><source srcset=\"https:\/\/s2.glbimg.com\/LCW2scxZDrwpiBaHRx3OY96aoDo=\/0x0:1380x4364\/984x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png 1x, https:\/\/s2.glbimg.com\/o5hWSfEKr1v2hLaOgemnKTGrWvk=\/0x0:1380x4364\/1968x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png 2x\" media=\"(max-width: 1360px)\" data-src=\"https:\/\/s2.glbimg.com\/LCW2scxZDrwpiBaHRx3OY96aoDo=\/0x0:1380x4364\/984x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png 1x, https:\/\/s2.glbimg.com\/o5hWSfEKr1v2hLaOgemnKTGrWvk=\/0x0:1380x4364\/1968x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png 2x\" \/><source srcset=\"https:\/\/s2.glbimg.com\/bZ2PeES6RMQerEaoIVkcIzoNzgY=\/0x0:1380x4364\/1000x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png 1x, https:\/\/s2.glbimg.com\/BEaS1CnQDnWQF3z-WSwdzJyh4vI=\/0x0:1380x4364\/2000x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png 2x\" media=\"(min-width: 1361px)\" data-src=\"https:\/\/s2.glbimg.com\/bZ2PeES6RMQerEaoIVkcIzoNzgY=\/0x0:1380x4364\/1000x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png 1x, https:\/\/s2.glbimg.com\/BEaS1CnQDnWQF3z-WSwdzJyh4vI=\/0x0:1380x4364\/2000x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png 2x\" \/><source srcset=\"https:\/\/s2.glbimg.com\/LCW2scxZDrwpiBaHRx3OY96aoDo=\/0x0:1380x4364\/984x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png\" data-src=\"https:\/\/s2.glbimg.com\/LCW2scxZDrwpiBaHRx3OY96aoDo=\/0x0:1380x4364\/984x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png\" \/><img decoding=\"async\" class=\"image content-media__image progressive-loaded\" title=\"Lista de princ\u00edpios ativos que foram utilizados na formula\u00e7\u00e3o de agrot\u00f3xicos gen\u00e9ricos \u2014 Foto: Rikardy Tooge\/G1\" src=\"https:\/\/s2.glbimg.com\/LCW2scxZDrwpiBaHRx3OY96aoDo=\/0x0:1380x4364\/984x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png\" alt=\"Lista de princ\u00edpios ativos que foram utilizados na formula\u00e7\u00e3o de agrot\u00f3xicos gen\u00e9ricos \u2014 Foto: Rikardy Tooge\/G1\" data-src=\"https:\/\/s2.glbimg.com\/LCW2scxZDrwpiBaHRx3OY96aoDo=\/0x0:1380x4364\/984x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/j\/5\/ErhzfjQZmA5SlOH6zEKA\/bgstn-produtos-gen-ricos-autorizados-2-.png\" \/><\/picture><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"content-media__description \">Por:\u00a0Rikardy Tooge | Foto: Rikardy Tooge\/G1 | Fonte:\u00a0https:\/\/www.cenariomt.com.br<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Justi\u00e7a Federal do Cear\u00e1 suspendeu o\u00a0registro de 63 agrot\u00f3xicos feito pelo Minist\u00e9rio da Agricultura &hellip;<\/p>\n","protected":false},"author":4,"featured_media":21349,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-21348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=21348"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21348\/revisions"}],"predecessor-version":[{"id":21350,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21348\/revisions\/21350"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/21349"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=21348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=21348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=21348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}