{"id":21453,"date":"2019-11-27T11:26:07","date_gmt":"2019-11-27T15:26:07","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=21453"},"modified":"2019-11-27T11:26:07","modified_gmt":"2019-11-27T15:26:07","slug":"comissao-de-etica-protocola-noticia-crime-no-gaeco","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/comissao-de-etica-protocola-noticia-crime-no-gaeco\/","title":{"rendered":"Comiss\u00e3o de \u00c9tica protocola not\u00edcia-crime no Gaeco"},"content":{"rendered":"<div>A Comiss\u00e3o de \u00c9tica e Decoro Parlamentar da C\u00e2mara Municipal de Cuiab\u00e1 protocolou na manh\u00e3 desta quarta-feira, dia 27, uma not\u00edcia-crime junto ao Grupo de Atua\u00e7\u00e3o Especial contra o Crime Organizado (Gaeco).<\/div>\n<div><\/div>\n<div>A medida \u00e9 reflexa de uma oitiva realizada na tarde desta ter\u00e7a-feira (27), no \u00e2mbito do processo que apura poss\u00edvel quebra de decoro parlamentar por parte do vereador Ab\u00edlio Junior, o qual est\u00e1 tramitando no Legislativo Cuiabano.<\/div>\n<div><\/div>\n<div>Conforme o vereador Toninho de Souza (PSDB), presidente da Comiss\u00e3o,\u00a0 depoente trouxe fatos graves, os quais n\u00e3o tem liga\u00e7\u00e3o alguma com a investiga\u00e7\u00e3o que esta em curso no Parlamento Municipal.<\/div>\n<div><\/div>\n<div>Por conta disso, o parlamentar e os demais membros do grupo, os vereadores Ricardo Saad (PSDB) e Vinicyus Hugueney (PP), optaram por levar tal informa\u00e7\u00e3o ao Gaeco.<\/div>\n<div><\/div>\n<div>\u201cN\u00f3s recebemos nesta ter\u00e7a, dia 26, em uma oitiva da Comiss\u00e3o de \u00e9tica uma depoente que trouxe acusa\u00e7\u00f5es graves. Ao tomar conhecimento disso, fizemos o nosso papel de tomar o depoimento, mas diante da gravidade da den\u00fancia feita por ela, n\u00f3s tomamos a atitude, em Comiss\u00e3o, de tirar uma c\u00f3pia da \u00edntegra das oitivas e protocolar no Gaeco pedindo investiga\u00e7\u00e3o. Como o que ela colocou n\u00e3o diz respeito a nossa comiss\u00e3o, nos estamos encaminhamos a quem \u00e9 devido. Estamos fazendo o nosso dever de um agente publico de pedir provid\u00eancias, quando toma conhecimento de uma informa\u00e7\u00e3o grave\u201d, explicou Toninho.<\/div>\n<div><\/div>\n<div>Vale ressaltar, entretanto, que, no in\u00edcio da investiga\u00e7\u00e3o de poss\u00edvel quebra de decoro por parte do vereador Ab\u00edlio, a Comiss\u00e3o definiu em ata, que todo o processo correria sob sigilo, sob pena de prejudicar o andamento do caso.<\/div>\n<div><\/div>\n<div>Diante disso, os membros do grupo n\u00e3o puderam externar o teor da den\u00fancia feita pela depoente. \u201cN\u00f3s temos uma normativa interna da Comiss\u00e3o no caso desta investiga\u00e7\u00e3o que nos reserva o direito de n\u00e3o falar sobre o conte\u00fado, sob pena de prejudicar o processo que esta em andamento. Ent\u00e3o, n\u00e3o podemos falar sobre o conte\u00fado que ela relatou, mas podemos dizer que s\u00e3o acusa\u00e7\u00f5es graves e que nos estamos tomando as providencias devidas cab\u00edveis\u201d, completou o social democrata.<\/div>\n<div><\/div>\n<div>O processo que tramita no Legislativo contra o vereador Ab\u00edlio \u00e9 fruto de uma representa\u00e7\u00e3o feita pelo ex-vereador Oseas Machado. A investiga\u00e7\u00e3o vem sendo conduzida pela Comiss\u00e3o de \u00c9tica que, atualmente, encontra-se na fase de oitivas.<\/div>\n<div>Nesta segunda e ter\u00e7a-feira, dias 25 e 26, foram colhidos os depoimentos das testemunhas de acusa\u00e7\u00e3o. J\u00e1 nesta quarta e quinta-feira, dias 27 e 28, os membros do grupo ouvir\u00e3o as testemunhas de defesa.<\/div>\n<div><\/div>\n<div>Ap\u00f3s isso, caber\u00e1 ao vereador Ricardo Saad, relator do processo, elaborar o relat\u00f3rio final das investiga\u00e7\u00f5es.<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por: Kamila Arruda | Fonte: <a href=\"http:\/\/www.camaracuiaba.mt.gov.br\">C\u00e2mara Municipal de Cuiab\u00e1<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o de \u00c9tica e Decoro Parlamentar da C\u00e2mara Municipal de Cuiab\u00e1 protocolou na manh\u00e3 &hellip;<\/p>\n","protected":false},"author":4,"featured_media":21454,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,59,77],"tags":[],"class_list":["post-21453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news","category-destaque","category-estudo"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=21453"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21453\/revisions"}],"predecessor-version":[{"id":21455,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21453\/revisions\/21455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/21454"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=21453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=21453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=21453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}