{"id":21494,"date":"2019-11-28T08:16:32","date_gmt":"2019-11-28T12:16:32","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=21494"},"modified":"2019-11-28T08:16:32","modified_gmt":"2019-11-28T12:16:32","slug":"assembleia-aprova-alteracao-na-lei-de-concessao-de-incentivos-fiscais-a-empresas","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/assembleia-aprova-alteracao-na-lei-de-concessao-de-incentivos-fiscais-a-empresas\/","title":{"rendered":"Assembleia aprova altera\u00e7\u00e3o na lei de concess\u00e3o de incentivos fiscais a empresas"},"content":{"rendered":"<p>Deputados votam vetos e aprovam PLC sobre benef\u00edcios Depois de votar 15 vetos governamentais em duas sess\u00f5es, uma ordin\u00e1ria e outra extraordin\u00e1ria nesta quarta-feira (27), os deputados estaduais aprovaram o Projeto de Lei Complementar 92\/2019, de autoria das lideran\u00e7as partid\u00e1rias, que altera a Lei Complementar 631, de julho de 2019, que disp\u00f5e sobre a remiss\u00e3o e anistia de cr\u00e9ditos tribut\u00e1rios, relativos ao ICMS e sobre a reinstitui\u00e7\u00e3o e revoga\u00e7\u00e3o de benef\u00edcios fiscais, nos termos da Lei Complementar Federal n\u00ba 160, de 7 de agosto de 2017 e do Conv\u00eanio ICMS 190\/2017.<\/p>\n<p>O PLC foi aprovado em segunda vota\u00e7\u00e3o e vai ao expediente, e promove altera\u00e7\u00f5es nos artigos 5\u00ba, 15\u00ba e 16\u00ba. No artigo 5\u00ba, a altera\u00e7\u00e3o \u00e9 no par\u00e1grafo 1\u00ba. Na lei, o par\u00e1grafo 1\u00ba diz que somente ser\u00e3o\u00a0reconhecidas a remiss\u00e3o e anistia na forma deste artigo ap\u00f3s o benefici\u00e1rio, at\u00e9 30 de novembro de 2019. Com a nova reda\u00e7\u00e3o, o par\u00e1grafo 1\u00ba diz que somente ser\u00e3o reconhecidas a remiss\u00e3o e anistia na forma deste artigo ap\u00f3s o benefici\u00e1rio, at\u00e9 30 de dezembro de 2019.<\/p>\n<p>Em justificativa ao PLC, as lideran\u00e7as partid\u00e1rias argumentam que a propositura visa dilatar o prazo, que era at\u00e9 30 de novembro, para 30 de dezembro de 2019, para que os contribuintes enquadrados em Programa de Desenvolvimento Econ\u00f4mico e\/ou autorizados \u00e0 frui\u00e7\u00e3o de incentivos vigentes, possam realizar a migra\u00e7\u00e3o para o benef\u00edcio fiscal reinstitu\u00eddo e\/ou alterado por meio da Lei Complementar n.\u00ba 631, de 31 de julho de 2019.<\/p>\n<p>No artigo 15\u00ba, a nova reda\u00e7\u00e3o do par\u00e1grafo 4\u00ba diz que \u201cpara os fins do disposto neste artigo, o contribuinte dever\u00e1 comunicar sua migra\u00e7\u00e3o para o tratamento previsto neste cap\u00edtulo, at\u00e9 30 de dezembro de 2019, na forma definida em regulamento, mediante formaliza\u00e7\u00e3o do termo de ades\u00e3o de que trata o inciso II do caput do artigo 9\u00ba desta Lei Complementar\u201d. Pela lei 630<\/p>\n<p>No artigo 16\u00ba, a altera\u00e7\u00e3o no par\u00e1grafo 3\u00ba diz que\u201d os contribuintes que estavam enquadrados em Programa ou autorizados \u00e0 frui\u00e7\u00e3o de benef\u00edcio fiscal, e que n\u00e3o fizerem a migra\u00e7\u00e3o para a frui\u00e7\u00e3o dos novos tratamentos reinstitu\u00eddos e alterados nos termos desta Lei Complementar, na forma fixada em regulamento, at\u00e9 30 de dezembro de 2019, ficam impedidos, a partir de 1\u00ba de janeiro de 2020, de fru\u00edrem dos benef\u00edcios fiscais previstos nos correspondentes atos concessivos, bem como daqueles disciplinados nesta Lei Complementar\u201d.<\/p>\n<p>O presidente da Assembleia Legislativa, deputado Eduardo Botelho (DEM), justificou que a vota\u00e7\u00e3o dos vetos pelos parlamentares evitou que a pauta de projetos em tramita\u00e7\u00e3o fosse sobrestada. \u201cDecidimos dar celeridade na vota\u00e7\u00e3o dos vetos. Tinham vetos que estavam tramitando h\u00e1 mais de 90 dias na Casa de Leis\u201d, afirmou. Conforme Botelho, a expectativa, a partir de agora, \u00e9 votar o Projeto de Lei Or\u00e7ament\u00e1ria Anual. \u201cAgora, nossa esperan\u00e7a e come\u00e7ar a votar a LOA a partir da pr\u00f3xima semana\u201d, completou.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0https:\/\/odocumento.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deputados votam vetos e aprovam PLC sobre benef\u00edcios Depois de votar 15 vetos governamentais em &hellip;<\/p>\n","protected":false},"author":4,"featured_media":21495,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-21494","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=21494"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21494\/revisions"}],"predecessor-version":[{"id":21496,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21494\/revisions\/21496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/21495"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=21494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=21494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=21494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}