{"id":21529,"date":"2019-11-29T10:36:46","date_gmt":"2019-11-29T14:36:46","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=21529"},"modified":"2019-11-29T10:36:46","modified_gmt":"2019-11-29T14:36:46","slug":"com-investimentos-de-quase-r-800-mil-pinheiro-entrega-nova-unidade-de-saude","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/com-investimentos-de-quase-r-800-mil-pinheiro-entrega-nova-unidade-de-saude\/","title":{"rendered":"Com investimentos de quase R$ 800 mil, Pinheiro entrega nova unidade de Sa\u00fade"},"content":{"rendered":"<p>Terrenos com obras n\u00e3o iniciadas, que estavam abandonados, trazendo inseguran\u00e7a para a popula\u00e7\u00e3o e esqueletos de constru\u00e7\u00f5es inacabadas que, al\u00e9m disso, serviam como ponto de drogas e locais de prostitui\u00e7\u00e3o\u00a0n\u00e3o far\u00e3o mais parte do cen\u00e1rio de Cuiab\u00e1 at\u00e9 o fim de 2020. A declara\u00e7\u00e3o, firmada pelo prefeito Emanuel Pinheiro em seu Plano de Governo, foi enfatizada\u00a0na noite desta quinta-feira (28),\u00a0durante a cerim\u00f4nia de entrega da Unidade B\u00e1sica de Sa\u00fade (UBS) que atender\u00e1 os bairros Santa Terezinha e Itapaj\u00e9.<\/p>\n<p>\u201cFoi um dos primeiros compromissos que fiz com a popula\u00e7\u00e3o cuiabana e que tenho a grata satisfa\u00e7\u00e3o de dizer que j\u00e1 cumprimos mais de 50%. Do pacote de 67 obras paralisadas ou n\u00e3o iniciadas em outras gest\u00f5es j\u00e1 entregamos a reforma e amplia\u00e7\u00e3o de 30 unidades entre Centros de Sa\u00fade e PSFs. A constru\u00e7\u00e3o das duas novas UBS, a Jockey Clube e esta v\u00e3o beneficiar os moradores do Santa Terezinha, do Itapaj\u00e9 e de toda a regi\u00e3o. E ainda entregamos semana passada o maior complexo hospitalar do Centro-Oeste, que \u00e9 o HMC. Este \u00faltimo est\u00e1 100% entregue \u00e0 popula\u00e7\u00e3o e j\u00e1 est\u00e1 salvando vidas, n\u00e3o apenas de pessoas de Cuiab\u00e1, mas de outros munic\u00edpios do estado e at\u00e9 estados e pa\u00edses vizinhos como Rond\u00f4nia, Acre e Bol\u00edvia. S\u00e3o grandes obras que antes traziam insatisfa\u00e7\u00e3o e inseguran\u00e7a para a popula\u00e7\u00e3o e hoje, significam mais humaniza\u00e7\u00e3o em Sa\u00fade\u201d, frisou Pinheiro, salientando que nos pr\u00f3ximos meses entregar\u00e1 as UPAs Verd\u00e3o e Leblon, al\u00e9m de mais obras da aten\u00e7\u00e3o B\u00e1sica, avan\u00e7ando assim ainda mais para por fim aos esqueletos de obras da Sa\u00fade em Cuiab\u00e1.<\/p>\n<p>Com investimento de R$ 783.888,16 viabilizados por meio de recursos do Minist\u00e9rio da Sa\u00fade e do pr\u00f3prio Munic\u00edpio, a nova UBS, que foi entregue totalmente equipada, climatizada e com equipes odontol\u00f3gicas e ir\u00e1 beneficiar mais de 10 mil pessoas da regi\u00e3o, tamb\u00e9m contribui para o aumento da preven\u00e7\u00e3o \u00e0 sa\u00fade por meio do aumento das Equipes de Sa\u00fade da Fam\u00edlia. A afirma\u00e7\u00e3o \u00e9 do secret\u00e1rio de Sa\u00fade, Luiz Ant\u00f4nio P\u00f4ssas de Carvalho.<\/p>\n<p>\u201cEstamos avan\u00e7ando no processo de humaniza\u00e7\u00e3o na sa\u00fade e n\u00e3o h\u00e1 como faz\u00ea-lo sem investirmos na Aten\u00e7\u00e3o Prim\u00e1ria, a qual recebemos apenas com cerca de 70 equipes de Sa\u00fade da Fam\u00edlia, o que corresponde a cerca de 48% de cobertura total. Com as unidades entregues, aliadas \u00e0s que entregaremos at\u00e9 fim do mandato, conseguiremos progredir para mais 60 equipes de Sa\u00fade da Fam\u00edlia, finalizando a gest\u00e3o com mais de 120, pr\u00f3ximo do considerado ideal pelo Minist\u00e9rio da Sa\u00fade. Esse foi outro compromisso do prefeito e \u00e9 o caminho para levarmos a sa\u00fade \u00e0s fam\u00edlias cuiabanas, diminuindo os atendimentos na urg\u00eancia e emerg\u00eancia e na m\u00e9dia e alta complexidade\u201d completou.<\/p>\n<p>O morador do Santa Terezinha e conselheiro de Sa\u00fade, Claudiney Vaillant agradeceu o empenho do prefeito e do secret\u00e1rio em trazer esse benef\u00edcio para a comunidade. \u201cAguardamos por muitos anos a constru\u00e7\u00e3o desta UBS. Ela tamb\u00e9m \u00e9 s\u00edmbolo de luta do Conselho de Sa\u00fade, que esteve do lado do prefeito para n\u00e3o perder o recurso que voltaria para o Governo Federal, uma vez que o Itapaj\u00e9, local estabelecido para constru\u00e7\u00e3o inicialmente, n\u00e3o comportava a dimens\u00e3o da constru\u00e7\u00e3o. Lutamos e conseguimos trazer a UBS para o Santa Terezinha e hoje a popula\u00e7\u00e3o pode desfrutar de uma unidade novinha, com m\u00e9dicos e dentistas. Ent\u00e3o, essa obra \u00e9 uma vit\u00f3ria e em meu nome e do companheiro Neno, enquanto conselheiros e moradores do Santa Terezinha e da regi\u00e3o do Coxip\u00f3, que est\u00e1 sendo profundamente beneficiada com obras na Sa\u00fade,\u00a0agradecemos ao prefeito Emanuel Pinheiro e ao secret\u00e1rio pelo comprometimento. Realmente estamos assistindo a virada de p\u00e1gina da Sa\u00fade na Capital\u201d, disse.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>HOMENAGEM<\/strong><\/p>\n<p>A UBS recebeu o nome do\u00a0m\u00e9dico Luiz Gonzaga Figueiredo.\u00a0O m\u00e9dico, que foi pioneiro no estado na \u00e1rea de Nefrologia, tratamento de hemodi\u00e1lise e transplante renal, morreu aos 64 anos v\u00edtima de uma arritmia card\u00edaca e parada respirat\u00f3ria enquanto pescava.<\/p>\n<p>O Dr. Luiz Guilherme Filho agradeceu a homenagem ao pai. \u201cEsse \u00e9 um momento hist\u00f3rico para a fam\u00edlia Figueiredo. Em nome de todos n\u00f3s, fam\u00edlia e amigos, agrade\u00e7o imensamente ao prefeito Emanuel Pinheiro, ao secret\u00e1rio Luiz P\u00f4ssas e aos vereadores em nome do meu amigo Zidiel Coutinho pela homenagem ao homem que desbravou a nefrologia e outros tantos \u00a0avan\u00e7os da medicina, n\u00e3o apenas em Cuiab\u00e1, mas em outros munic\u00edpios do estado. Meu pai agora est\u00e1 eternizado, n\u00e3o apenas nos nossos cora\u00e7\u00f5es e nos daqueles que o conheceram, ou na medicina, mas, tamb\u00e9m, nessa unidade b\u00e1sica de Sa\u00fade que passa a eternizar seu nome na hist\u00f3ria\u201d, agradeceu.\u00a0A vi\u00fava do homenageado, Sueli Maria de Figueiredo, entregou um presente da fam\u00edlia ao prefeito, como forma de agradecimento.<\/p>\n<p>Al\u00e9m de populares, presidentes de bairros e secret\u00e1rios, compareceram ao evento os vereadores Misael Galv\u00e3o, Orivaldo da Farm\u00e1cia e Adevair Cabral.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por:\u00a0OZIANE RODRIGUES | Fonte:\u00a0http:\/\/www.cuiaba.mt.gov.br | Foto:\u00a0 Gustavo Duarte<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Terrenos com obras n\u00e3o iniciadas, que estavam abandonados, trazendo inseguran\u00e7a para a popula\u00e7\u00e3o e esqueletos &hellip;<\/p>\n","protected":false},"author":4,"featured_media":21530,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-21529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"A USB que foi entregue totalmente equipada, climatizada, com odontologia e homenageou \u00edcone da nefrologia do estado","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=21529"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21529\/revisions"}],"predecessor-version":[{"id":21531,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21529\/revisions\/21531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/21530"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=21529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=21529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=21529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}