{"id":21790,"date":"2019-12-10T10:28:28","date_gmt":"2019-12-10T14:28:28","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=21790"},"modified":"2019-12-10T10:28:28","modified_gmt":"2019-12-10T14:28:28","slug":"conab-safra-de-graos-deve-crescer-2-e-atingir-2466-mi-de-toneladas","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/conab-safra-de-graos-deve-crescer-2-e-atingir-2466-mi-de-toneladas\/","title":{"rendered":"Conab: safra de gr\u00e3os deve crescer 2% e atingir 246,6 mi de toneladas"},"content":{"rendered":"<p>A<a href=\"https:\/\/www.conab.gov.br\/\"><strong>\u00a0Companhia Nacional de Abastecimento (Conab)<\/strong>\u00a0<\/a>elevou nesta ter\u00e7a-feira, 10, a estimativa de produ\u00e7\u00e3o de gr\u00e3os na safra 2019\/2020. A entidade aumentou em 0,1% a proje\u00e7\u00e3o em rela\u00e7\u00e3o ao m\u00eas anterior e em 1,9% a expectativa de safra na compara\u00e7\u00e3o com o colhido no ciclo 2018\/2019. Portanto, para esta temporada, a estimativa da safra de gr\u00e3os \u00e9 de 246,6 milh\u00f5es de toneladas, contra 242 milh\u00f5es de toneladas no ano anterior.<\/p>\n<p>Para a \u00e1rea plantada, a expectativa \u00e9 de crescimento de 1,5%, alcan\u00e7ando 64,2 milh\u00f5es de hectares, contra 63,2 milh\u00f5es de hectares.<\/p>\n<h3><strong>Soja<\/strong><\/h3>\n<p><strong>Para a soja, a expectativa \u00e9 que a produ\u00e7\u00e3o chegue a 121,1 milh\u00f5es de toneladas. Se confirmada, esta seria a maior safra do gr\u00e3o da hist\u00f3ria do Brasil, com alta de 5,3% em rela\u00e7\u00e3o ao ano passado, que atingiu 115 milh\u00f5es de toneladas. \u201cH\u00e1 tend\u00eancia de crescimento de 2,6% na \u00e1rea plantada em rela\u00e7\u00e3o \u00e0 safra passada\u201d, disse a Conab em relat\u00f3rio.<\/strong><\/p>\n<p><strong>A entidade explica que as chuvas irregulares registradas no in\u00edcio do ciclo, em estados da regi\u00e3o Centro-Oeste e Sudeste, por exemplo, apresentaram melhoras a partir do m\u00eas de novembro, o que favoreceu o avan\u00e7o das opera\u00e7\u00f5es de plantio.\u00a0<\/strong><\/p>\n<p><strong>J\u00e1 na regi\u00e3o do Maranh\u00e3o, Tocantins, Piau\u00ed e Bahia (Matopiba), as mudan\u00e7as clim\u00e1ticas interferiram na evolu\u00e7\u00e3o da semeadura, mas a perspectiva \u00e9 que o plantio seja realizado dentro do calend\u00e1rio pr\u00f3prio para a regi\u00e3o.<\/strong><\/p>\n<h3>Milho<\/h3>\n<p>A produ\u00e7\u00e3o de milho total em 2019\/2020 deve ser de 98,4 milh\u00f5es de toneladas, contra 98,3 milh\u00f5es de toneladas no relat\u00f3rio anterior e 100 milh\u00f5es de toneladas no ciclo passado. Se confirmado, a queda em rela\u00e7\u00e3o a safra 2018\/2019 ser\u00e1 de 1,6%. A expectativa de \u00e1rea plantada \u00e9 de 17,5 milh\u00f5es de hectares, alta de 0,3% em rela\u00e7\u00e3o a temporada anterior.<\/p>\n<p>O milho primeira safra deve ter produ\u00e7\u00e3o de 26,3 milh\u00f5es de toneladas, alta de 2,6% na compara\u00e7\u00e3o com as 25,6 milh\u00f5es de toneladas do ano anterior. Para a \u00e1rea plantada, \u00e9 esperado um incremento de 1,2%, totalizando 4,2 milh\u00f5es de hectares.<\/p>\n<div class=\"ad ad-float ad-300-250\">\n<div id=\"banner-300x250-3-area\">\n<h3>Para a segunda safra, a Conab projeta produ\u00e7\u00e3o em 70,9 milh\u00f5es de toneladas, queda de 3,1% em rela\u00e7\u00e3o aos 73,1 milh\u00f5es de toneladas do ciclo anterior. J\u00e1 a \u00e1rea semeada deve atingir 12,8 milh\u00f5es de hectares, montante igual ao ano passado.<\/h3>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por:\u00a0<a href=\"https:\/\/www.canalrural.com.br\">Canal Rural<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A\u00a0Companhia Nacional de Abastecimento (Conab)\u00a0elevou nesta ter\u00e7a-feira, 10, a estimativa de produ\u00e7\u00e3o de gr\u00e3os na &hellip;<\/p>\n","protected":false},"author":4,"featured_media":21791,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-21790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Entidade estima que a safra de soja chegue a 121,1 milh\u00f5es de toneladas, maior produ\u00e7\u00e3o do gr\u00e3o da hist\u00f3ria","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=21790"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21790\/revisions"}],"predecessor-version":[{"id":21792,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21790\/revisions\/21792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/21791"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=21790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=21790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=21790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}