{"id":21910,"date":"2019-12-16T11:00:46","date_gmt":"2019-12-16T15:00:46","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=21910"},"modified":"2019-12-16T11:00:46","modified_gmt":"2019-12-16T15:00:46","slug":"para-aumentar-a-seguranca-camara-de-cuiaba-implanta-sistema-de-catracas-eletronicas","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/para-aumentar-a-seguranca-camara-de-cuiaba-implanta-sistema-de-catracas-eletronicas\/","title":{"rendered":"Para aumentar a seguran\u00e7a, C\u00e2mara de Cuiab\u00e1 implanta sistema de catracas eletr\u00f4nicas"},"content":{"rendered":"<div>A fim de oferecer maior seguran\u00e7a aos servidores, a C\u00e2mara Municipal de Cuiab\u00e1 passa a aderir ao sistema de catracas biom\u00e9tricas. A medida obriga a identifica\u00e7\u00e3o de todos os funcion\u00e1rios, visitantes e at\u00e9 mesmo vereadores, ao adentrar ao pr\u00e9dio do Legislativo Cuiabano.<\/div>\n<div><\/div>\n<div>Com isso, o Parlamento Municipal passa adotar uma forma de trabalho que j\u00e1 vigora em v\u00e1rios outros \u00f3rg\u00e3os p\u00fablicos, garantindo mais seguran\u00e7a tanto para o cidad\u00e3o que busca a Casa de Leis para resolver problemas ou apresentar demandas aos vereadores, quanto para os pr\u00f3prios servidores, no desempenho do trabalho.<\/div>\n<div><\/div>\n<div>Al\u00e9m da seguran\u00e7a, a Casa de Leis ainda passa a ter maior controle a cerca de quem entra e quem sai do pr\u00e9dio por meio deste sistema.<\/div>\n<div><\/div>\n<div>A instala\u00e7\u00e3o de catracas eletr\u00f4nicas faz parte de uma s\u00e9ria de a\u00e7\u00f5es que vem sendo implementadas no Legislativo visando \u00e0 moderniza\u00e7\u00e3o do sistema da C\u00e2mara.<\/div>\n<div><\/div>\n<div>\u201cA instala\u00e7\u00e3o das catracas e da biometria s\u00e3o mudan\u00e7as importantes, mas somente neste ano intensificamos o trabalho da ouvidoria, melhoramos o sistema do Portal da Transpar\u00eancia, readequamos espa\u00e7os considerados insalubres para o trabalho e atendido ao p\u00fablico\u201d, explica o presidente da C\u00e2mara de Cuiab\u00e1, vereador Misael Galv\u00e3o (PTB).<\/div>\n<div><\/div>\n<div>Conforme o petebista, outros modifica\u00e7\u00f5es ainda devem ser implementadas no Legislativo. \u201cEm breve iremos trazer mais inova\u00e7\u00f5es como o projeto \u2018Papel Zero\u2019, visando \u00e0 preserva\u00e7\u00e3o e conscientiza\u00e7\u00e3o ambiental. J\u00e1 para os mun\u00edcipes tamb\u00e9m facilitar\u00e1, pois as reivindica\u00e7\u00f5es, indica\u00e7\u00f5es, sugest\u00f5es de projetos poder\u00e3o ser feitos no formato online\u201d, relata o petebista.<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por: Kamila Arruda | Fonte: <a href=\"http:\/\/www.camaracuiaba.mt.gov.br\">C\u00e2mara Municipal de Cuiab\u00e1<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A fim de oferecer maior seguran\u00e7a aos servidores, a C\u00e2mara Municipal de Cuiab\u00e1 passa a &hellip;<\/p>\n","protected":false},"author":4,"featured_media":21911,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,59,77],"tags":[],"class_list":["post-21910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news","category-destaque","category-estudo"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=21910"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21910\/revisions"}],"predecessor-version":[{"id":21912,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21910\/revisions\/21912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/21911"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=21910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=21910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=21910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}