{"id":21945,"date":"2019-12-17T10:29:41","date_gmt":"2019-12-17T14:29:41","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=21945"},"modified":"2019-12-17T10:29:41","modified_gmt":"2019-12-17T14:29:41","slug":"vereadores-acompanham-entrega-do-novo-posto-da-prf-e-12-km-de-pista-duplicada","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/vereadores-acompanham-entrega-do-novo-posto-da-prf-e-12-km-de-pista-duplicada\/","title":{"rendered":"Vereadores acompanham entrega do novo posto da PRF e 12 km de pista duplicada"},"content":{"rendered":"<div>Vereadores da C\u00e2mara Municipal de Cuiab\u00e1 participaram na manh\u00e3 desta segunda-feira (16) da entrega do novo posto da Pol\u00edcia Rodovi\u00e1ria Federal (PRF), na BR 364. Na oportunidade, o Departamento Nacional de Infraestrutura (DNIT) tamb\u00e9m entregou 12 km de pista duplicada na BR 163\/164, do Distrito Industrial at\u00e9 o novo posto da PRF.<\/div>\n<div><\/div>\n<div>Durante seu discurso, o presidente do legislativo Cuiabano se emocionou ao lembrar de quando passava por essa BR para buscar mercadorias em outros estados. \u201cPassei por muitas vezes nessa estrada correndo risco de vida para buscar o sustento da minha fam\u00edlia. Hoje parabenizo o Senador Wellington Fagundes que ganhou essa empreitada de duplicar a BR e trazer qualidade de vida para essas que por aqui transitam , sendo um Senador que cuida do povo\u201d.<\/div>\n<div><\/div>\n<div>Tamb\u00e9m participou do evento o prefeito de Cuiab\u00e1 Emanuel Pinheiro, presidente da C\u00e2mara de Santo Antonio do Leverger Dudu Moreira, e os vereadores por Cuiab\u00e1, Vinicyus Hugueney, Orivaldo da Farm\u00e1cia e Chico 2000.<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por: Susan Bento | Fonte: <a href=\"http:\/\/www.camaracuiaba.mt.gov.br\">C\u00e2mara Municipal de Cuiab\u00e1<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vereadores da C\u00e2mara Municipal de Cuiab\u00e1 participaram na manh\u00e3 desta segunda-feira (16) da entrega do &hellip;<\/p>\n","protected":false},"author":4,"featured_media":21946,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,59,77],"tags":[],"class_list":["post-21945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news","category-destaque","category-estudo"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=21945"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21945\/revisions"}],"predecessor-version":[{"id":21947,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/21945\/revisions\/21947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/21946"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=21945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=21945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=21945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}