{"id":22330,"date":"2020-01-06T10:24:56","date_gmt":"2020-01-06T14:24:56","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=22330"},"modified":"2020-01-06T10:24:56","modified_gmt":"2020-01-06T14:24:56","slug":"parlamentares-cedem-a-fundo-eleitoral-menor-para-evitar-veto-de-bolsonaro","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/parlamentares-cedem-a-fundo-eleitoral-menor-para-evitar-veto-de-bolsonaro\/","title":{"rendered":"Parlamentares cedem a fundo eleitoral menor para evitar veto de Bolsonaro"},"content":{"rendered":"<p>L\u00edderes partid\u00e1rios recuaram e passaram a aceitar um valor menor para o fundo de financiamento das elei\u00e7\u00f5es de 2020, que deve ficar em R$ 2 bilh\u00f5es.<\/p>\n<p>Congressistas querem evitar o constrangimento de um\u00a0<a href=\"https:\/\/www1.folha.uol.com.br\/poder\/2019\/12\/sob-pressao-parlamentares-cogitam-encolher-fundo-eleitoral-de-r-38-bi-para-r-25-bi.shtml\">poss\u00edvel veto do presidente Jair Bolsonaro<\/a>.<\/p>\n<p>O Pal\u00e1cio do Planalto se posicionou contra o\u00a0<a href=\"https:\/\/www1.folha.uol.com.br\/poder\/2019\/12\/relator-preve-ampliar-fundo-eleitoral-para-r-38-bilhoes-no-orcamento-2020.shtml\">aumento do fundo eleitoral para R$ 3,8 bilh\u00f5es<\/a>, articulado h\u00e1 duas semanas por partidos que representam a maioria do Congresso.<\/p>\n<div class=\"c-advertising c-advertising--300x250 u-hidden-xs\">\n<div id=\"banner-300x250-area-materia\" class=\"c-advertising__banner-area\"><\/div>\n<\/div>\n<p>Sob press\u00e3o, o relator da proposta do Or\u00e7amento de 2020, deputado Domingos Neto (PSD-CE), buscou um acordo para que o fundo voltasse a ser de R$ 2 bilh\u00f5es.<\/p>\n<p>At\u00e9 o fechamento do relat\u00f3rio final\u00a0tamb\u00e9m foi cogitada a\u00a0<a href=\"https:\/\/www1.folha.uol.com.br\/poder\/2019\/12\/sob-pressao-parlamentares-cogitam-encolher-fundo-eleitoral-de-r-38-bi-para-r-25-bi.shtml\">possibilidade de o fundo\u00a0ser de R$ 2,5 bilh\u00f5es<\/a>.<\/p>\n<div id=\"_dynad_c_I5550010343_15765699959741458475903\">Na semana passada, interlocutores de\u00a0Bolsonaro\u00a0tentaram um consenso em rela\u00e7\u00e3o a esse patamar. Mas o pr\u00f3prio presidente desautorizou a articula\u00e7\u00e3o de l\u00edderes aliados e insistiu em um teto de R$ 2 bilh\u00f5es.<\/div>\n<p>Uma ala do\u00a0centr\u00e3o\u00a0ainda defendia a amplia\u00e7\u00e3o para R$ 2,5 bilh\u00f5es, mas Neto diz ter conseguido um consenso com partidos em favor de um financiamento mais enxuto.<\/p>\n<p>O deputado s\u00f3 deve divulgar o relat\u00f3rio final do Or\u00e7amento, que inclui o novo patamar do financiamento de campanha, nesta ter\u00e7a-feira (17), pouco antes da vota\u00e7\u00e3o do projeto no Congresso.<\/p>\n<p>Deputados do centr\u00e3o \u2014grupo de partidos independentes ao governo e que, juntos, representam a maioria da C\u00e2mara\u2014\u00a0foram escalados para negociar com interlocutores do Planalto.<\/p>\n<p>Essa n\u00e3o foi a primeira vez que o presidente e o Congresso entraram numa queda de bra\u00e7o.<\/p>\n<p>L\u00edderes j\u00e1 articulavam, em julho, o aumento do fundo para R$ 3,7 bilh\u00f5es na vota\u00e7\u00e3o da Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO), fase que antecede a proposta de Or\u00e7amento.<\/p>\n<p>Diante de cr\u00edticas, o relator da LDO, deputado Cac\u00e1 Le\u00e3o (PP-BA), desistiu, em agosto, de inflar a verba.<\/p>\n<p>Mas o assunto voltou \u00e0 articula\u00e7\u00e3o do Congresso na reta final do projeto de Or\u00e7amento.<\/p>\n<p>Presidentes e l\u00edderes de partidos enviaram um documento a Neto\u00a0pedindo que o valor do fundo chegasse a R$ 4 bilh\u00f5es.<\/p>\n<p>A press\u00e3o era sob o argumento de que o n\u00famero de candidatos de uma elei\u00e7\u00e3o municipal \u00e9 bem maior do que o n\u00famero de candidatos das elei\u00e7\u00f5es para presidente, governos estaduais, Congresso e Assembleias.<\/p>\n<p>Assinaram o of\u00edcio representantes do PP, MDB, PTB, PT, PSL, PL, PSD, PSB, Republicanos, PSDB, PDT, DEM e Solidariedade. Eles representam 430 dos 513 deputados e 62 dos 81 senadores.<\/p>\n<p>Neto, ent\u00e3o, elevou de R$ 2 bilh\u00f5es para R$ 3,8 bilh\u00f5es o tamanho do fundo. A Comiss\u00e3o Mista de Or\u00e7amento\u00a0autorizou esse aumento na verba h\u00e1 duas semanas.<\/p>\n<p>Podemos, Cidadania, PSOL e Novo foram contra. Mas essas legendas, mesmo juntas, n\u00e3o tinham for\u00e7a pol\u00edtica para barrar a investida.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por:\u00a0<a title=\"Posts de Anna Ruth\" href=\"http:\/\/www.politicaemfoco.com\/author\/annaruth\/\" rel=\"author\">Anna Ruth<\/a>\u00a0| Fonte: <a href=\"http:\/\/www.politicaemfoco.com\">Politica em Foco<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u00edderes partid\u00e1rios recuaram e passaram a aceitar um valor menor para o fundo de financiamento &hellip;<\/p>\n","protected":false},"author":4,"featured_media":22331,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-22330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/22330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=22330"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/22330\/revisions"}],"predecessor-version":[{"id":22332,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/22330\/revisions\/22332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/22331"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=22330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=22330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=22330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}