{"id":22387,"date":"2020-01-08T10:12:09","date_gmt":"2020-01-08T14:12:09","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=22387"},"modified":"2020-01-08T10:12:09","modified_gmt":"2020-01-08T14:12:09","slug":"producao-de-graos-pode-ter-novo-recorde-e-atingir-248-mi-de-toneladas","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/producao-de-graos-pode-ter-novo-recorde-e-atingir-248-mi-de-toneladas\/","title":{"rendered":"Produ\u00e7\u00e3o de gr\u00e3os pode ter novo recorde e atingir 248 mi de toneladas"},"content":{"rendered":"<p>A produ\u00e7\u00e3o de gr\u00e3os na safra 2019\/2020 do Brasil deve atingir\u00a0u novo recorde. Dados divulgados nesta quarta-feira, 8, pela Companhia Nacional de Abastecimento (Conab), indicaram uma safra de 248 milh\u00f5es de toneladas, alta de 2,5% ou de 6,1 milh\u00f5es de toneladas em rela\u00e7\u00e3o ao ciclo 2018\/2019.<\/p>\n<p>A expectativa para a \u00e1rea semeada \u00e9 que sejam cultivados 64,2 milh\u00f5es de hectares, incremento de 1,5% em compara\u00e7\u00e3o \u00e0 da safra anterior. \u201cAs condi\u00e7\u00f5es clim\u00e1ticas, que apresentaram certa instabilidade no in\u00edcio do plantio de ver\u00e3o na maioria das regi\u00f5es produtoras, tomaram agora um novo ritmo de normaliza\u00e7\u00e3o. A perspectiva \u00e9 que os n\u00edveis de produtividade apresentem bom desempenho nessa etapa\u201d, disse a Conab.<\/p>\n<p><strong>Soja<\/strong><\/p>\n<p>Para a oleaginosa, a expectativa \u00e9 que a\u00a0<strong>produ\u00e7\u00e3o chegue a 122,2 milh\u00f5es de toneladas<\/strong>, alta de 6,3% em rela\u00e7\u00e3o ao ciclo anterior e de 0,9% em rela\u00e7\u00e3o \u00e0 estimativa de dezembro. Se confirmada, essa ser\u00e1 a\u00a0<strong>maior safra de soja registrada na hist\u00f3ria<\/strong>. J\u00e1 a proje\u00e7\u00e3o de \u00e1rea plantada \u00e9 que se tenha um incremento de 2,6% na compara\u00e7\u00e3o com a \u00faltima temporada, continuando a tend\u00eancia de crescimento.<\/p>\n<div class=\"ad ad-float ad-300-250\">\n<div id=\"banner-300x250-2-area\">\n<h3><\/h3>\n<\/div>\n<\/div>\n<p>\u201cA semeadura iniciou de maneira desuniforme em diversos estados produtores devido ao atraso das chuvas, mas por ora se encontra dentro da normalidade quando comparada \u00e0s outras safras. Na Regi\u00e3o Centro-Oeste, as condi\u00e7\u00f5es clim\u00e1ticas registradas no pa\u00eds foram variadas e esse cen\u00e1rio impactou na evolu\u00e7\u00e3o do cultivo\u201d, comenta a Conab.<\/p>\n<p>Na regi\u00e3o Nordeste, particularmente no Matopiba, , regi\u00e3o que compreende algumas \u00e1reas do Maranh\u00e3o, Tocantins, Piau\u00ed e Bahia, as precipita\u00e7\u00f5es aconteceram com maior normalidade a partir de dezembro de 2019, com maior intensidade na primeira quinzena do m\u00eas. \u201cNa sequ\u00eancia, as chuvas apresentaram-se esparsas nas diversas regi\u00f5es produtoras e com reduzido volume, insuficientes para assegurar a umidade do solo para o plantio das culturas de uma forma segura.\u201d, pondera a entidade.<\/p>\n<p><strong>Milho<\/strong><\/p>\n<p>A expectativa de\u00a0<strong>produ\u00e7\u00e3o total<\/strong>\u00a0de milho no Brasil \u00e9 de 98,7 milh\u00f5es de toneladas, queda de 1,3% em rela\u00e7\u00e3o \u00e0 safra 2018\/2019, que teve produ\u00e7\u00e3o de 100 milh\u00f5es de toneladas. Para a\u00a0<strong>primeira safra<\/strong>, estima-se alta de 3,8%, com produ\u00e7\u00e3o de 26,6 milh\u00f5es de toneladas, ante 25,6 milh\u00f5es de toneladas.\u00a0 \u201cA estimativa de \u00e1rea de milho primeira safra, \u00e9 de 4,1 mil hectares, 1,1% maior que a \u00e1rea cultivada na safra 2018\/19, influenciada pelas boas cota\u00e7\u00f5es atuais do cereal\u201d, disse a entidade.<\/p>\n<div class=\"ad ad-float ad-300-250\">\n<div id=\"banner-300x250-3-area\">\n<h3><\/h3>\n<\/div>\n<\/div>\n<p>Segundo a Conab, as lavouras j\u00e1 se encontram totalmente semeadas na regi\u00e3o Centro-Sul e no Matopiba e apresentam bom desenvolvimento vegetativo.<\/p>\n<p>J\u00e1 para a\u00a0<strong>segunda safra<\/strong>, a tend\u00eancia \u00e9 de queda. A Conab projeta redu\u00e7\u00e3o de 3,1%, com 70,9 milh\u00f5es de toneladas nesta safra. No ciclo 2018\/2019, a produ\u00e7\u00e3o foi de 73,1 milh\u00f5es de toneladas.<\/p>\n<p>\u201cCom rela\u00e7\u00e3o ao plantio da segunda safra, previsto para iniciar em janeiro, existe ainda um quadro de indefini\u00e7\u00e3o com rela\u00e7\u00e3o \u00e0 amplitude no aumento da \u00e1rea plantada. O atraso no plantio da soja em todo o pa\u00eds, principal liberador de \u00e1rea para o plantio da segunda safra do cereal, por conta da falta e da desuniformidade das chuvas, criou uma expectativa de risco por conta do ciclo da soja, que poder\u00e1 ter sua evolu\u00e7\u00e3o avan\u00e7ando sobre fevereiro, e encurtar a janela de plantio favor\u00e1vel ao milho de segunda safra\u201d, afirma o relat\u00f3rio.<\/p>\n<p>Para a\u00a0<strong>terceira safra de milho<\/strong>, que se trata do\u00a0cereal produzido na regi\u00e3o da Sealba (Sergipe, Alagoas e nordeste da Bahia), como tamb\u00e9m no Amap\u00e1 e Roraima,<br \/>\na produ\u00e7\u00e3o inicialmente estimada ser\u00e1 de 1,1 milh\u00e3o de toneladas, queda de 5,1% em rela\u00e7\u00e3o \u00e0s 1,2 milh\u00e3o de toneladas.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>Foto: Silvio \u00c1vila |\u00a0<\/em>Fonte: <a href=\"https:\/\/www.canalrural.com.br\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A produ\u00e7\u00e3o de gr\u00e3os na safra 2019\/2020 do Brasil deve atingir\u00a0u novo recorde. Dados divulgados &hellip;<\/p>\n","protected":false},"author":4,"featured_media":22388,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-22387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Expectativa \u00e9 que produ\u00e7\u00e3ode soja chegue a 122,2 milh\u00f5es de toneladas, alta de 6,5% em rela\u00e7\u00e3o ao ciclo anterior; se confirmada, esta ser\u00e1 a maior safra da hist\u00f3ria","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/22387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=22387"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/22387\/revisions"}],"predecessor-version":[{"id":22389,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/22387\/revisions\/22389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/22388"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=22387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=22387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=22387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}