{"id":22548,"date":"2020-01-17T11:12:11","date_gmt":"2020-01-17T15:12:11","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=22548"},"modified":"2020-01-17T11:12:11","modified_gmt":"2020-01-17T15:12:11","slug":"regimento-interno-sera-alterado-neste-ano","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/regimento-interno-sera-alterado-neste-ano\/","title":{"rendered":"Regimento Interno ser\u00e1 alterado neste ano"},"content":{"rendered":"<div>A Comiss\u00e3o Especial, criada na C\u00e2mara Municipal de Cuiab\u00e1 para promover a revis\u00e3o do Regimento Interno, deve finalizar os trabalhos ainda no primeiro semestre deste ano. A medida visa dar maior agilidade, funcionalidade e andamento nos processos legislativos.<\/div>\n<div><\/div>\n<div>Para tanto, o grupo formado pelos vereadores Sargento Joelson (PSC), Luis Cl\u00e1udio (PP) e Clebinho Borges (DC), conta com a consultoria t\u00e9cnica da Secretaria de Apoio Legislativo.<\/div>\n<div><\/div>\n<div>A revis\u00e3o do Regimento Interno atende a um pleito de todos os vereadores, ap\u00f3s discuss\u00f5es promovidas em plen\u00e1rio que causaram interpreta\u00e7\u00f5es d\u00fabias. \u201cO presidente criou a Comiss\u00e3o e nos pediu que desse todo o amparo t\u00e9cnico, a fim de tornar o Regimento mais moderno e condizente da a\u00e7\u00e3o atual. Ap\u00f3s a Comiss\u00e3o terminar o trabalho, ele ser\u00e1 levado para aprecia\u00e7\u00e3o dos vereadores no Col\u00e9gio de L\u00edderes para discuss\u00e3o interna, e somente depois ir\u00e1 para vota\u00e7\u00e3o em plen\u00e1rio\u201d, destaca o titular da Secretaria de Apoio Legislativo Mesa Diretora Eronides Dias da Luz.<\/div>\n<div><\/div>\n<div>Entre os pontos que devem ser alterados, est\u00e3o as normas para a condu\u00e7\u00e3o das sess\u00f5es plen\u00e1rias. \u201cEstamos fazendo uma proposta que \u00e9 a invers\u00e3o de etapas da sess\u00e3o que hoje s\u00e3o divididas em fases. Atualmente, depois do grande expediente j\u00e1 entraremos na ordem do dia, onde os vereadores v\u00e3o debater os projetos que est\u00e3o na pauta. Trata-se da parte mais importante da sess\u00e3o que, \u00e0s vezes, fica renegada a um segundo plano. Ent\u00e3o, vamos fazer essa invers\u00e3o, trazer a ordem do dia para depois do pequeno expediente, deixando o grande expediente pro final\u201d, esclareceu o tamb\u00e9m consultor.<\/div>\n<div><\/div>\n<div>A atual estrutura de cada sess\u00e3o plen\u00e1ria se divide em pequeno expediente, grande expediente e ordem do dia, cabendo ainda nessa fase, a comunica\u00e7\u00e3o de lideran\u00e7a, al\u00e9m de expedientes do pela ordem e pela lideran\u00e7a e explica\u00e7\u00f5es pessoais.<\/div>\n<div><\/div>\n<div>O secret\u00e1rio garante que essa invers\u00e3o n\u00e3o trar\u00e1 qualquer preju\u00edzo ao andamento da sess\u00e3o e nenhuma de suas fazes, como por exemplo, a tribuna livre, onde o cidad\u00e3o tem vez e voz, para falar de seus problemas e buscas de solu\u00e7\u00f5es as quest\u00f5es para as comunidades.<\/div>\n<div><\/div>\n<div>\u201cN\u00e3o vai haver preju\u00edzo, o pequeno expediente tem dura\u00e7\u00e3o de uma hora e vai continuar assim. Ent\u00e3o, n\u00e3o tem altera\u00e7\u00e3o do tempo da fala de cada vereador, o pequeno expediente vai continuar de uma hora, vamos fazer apenas a invers\u00e3o para a ordem do dia\u201d.<\/div>\n<div><\/div>\n<div>Outra quest\u00e3o que est\u00e1 sendo averiguada \u00e9 o tempo de fala para cada vereador. \u201cVamos levar isso para debate. A proposta \u00e9 diminuir o tempo de justificativa de voto e aumentar o tempo de fala do vereador no grande expediente, onde ele usa a tribuna para debater assuntos importantes de sua pol\u00edtica\u201d, finalizou Eronildes.<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por: Ad\u00e3o de Oliveira e Kamila Arruda | Fonte:\u00a0 <a href=\"http:\/\/www.camaracuiaba.mt.gov.br\/\">C\u00e2mara Municipal de Cuiab\u00e1<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o Especial, criada na C\u00e2mara Municipal de Cuiab\u00e1 para promover a revis\u00e3o do Regimento &hellip;<\/p>\n","protected":false},"author":4,"featured_media":22463,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-22548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/22548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=22548"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/22548\/revisions"}],"predecessor-version":[{"id":22549,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/22548\/revisions\/22549"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/22463"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=22548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=22548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=22548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}