{"id":22693,"date":"2020-01-22T09:55:21","date_gmt":"2020-01-22T13:55:21","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=22693"},"modified":"2020-01-22T09:55:21","modified_gmt":"2020-01-22T13:55:21","slug":"vereador-clebinho-continua-investindo-nos-bairros-da-capital-sobretudo-na-regiao-oeste","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/vereador-clebinho-continua-investindo-nos-bairros-da-capital-sobretudo-na-regiao-oeste\/","title":{"rendered":"Vereador Clebinho continua investindo nos bairros da capital sobretudo na Regi\u00e3o Oeste"},"content":{"rendered":"<div>Para a execu\u00e7\u00e3o do Or\u00e7amento Geral Anual para Cuiab\u00e1 nesse ano de 2020, o montante a ser investido nos bairros da Regi\u00e3o Oeste, deve ser na ordem de R$ 600 mil, gra\u00e7as \u00e0 atua\u00e7\u00e3o do vereador Clebinho Borges (DC), que destinou grande parte do valor de sua emenda impositiva para investimentos na regi\u00e3o.<\/div>\n<div><\/div>\n<div>O parlamenta escolheu 20 \u00e1reas para investimentos necess\u00e1rios, de forma a melhorar a qualidade de vida na regi\u00e3o.<\/div>\n<div><\/div>\n<div>\u201cLimitamos os nossos investimentos em at\u00e9 R$ 80 mil nas emendas impositivas, para atender ao Maximo de moradores que precisam do poder publico para melhorar a vida\u201d, destacou o vereador, que priorizou al\u00e9m do setor de sa\u00fade, os setores de cultura, comunit\u00e1rio, saneamento, al\u00e9m de apoio as comunidades evang\u00e9licas e cat\u00f3licas, como \u00e9 o caso de recupera\u00e7\u00e3o da imagem de Nossa Senhora Aparecida no Parque Cuiab\u00e1, a pedido da comunidade ao custo de R$ 15 mil.<\/div>\n<div><\/div>\n<div>Outros investimentos foram para os centros comunit\u00e1rios em subven\u00e7\u00f5es sociais, nas unidades dos bairros do Jardim Vit\u00f3ria, Cidade Alta, e ainda no Jardim Paulista. Cada um receber\u00e1 a quantia de R$ 15 para promover reformas, manuten\u00e7\u00f5es ou outo tipo de interven\u00e7\u00e3o.<\/div>\n<div><\/div>\n<div>O bairro Santa Am\u00e1lia ainda vai ganhar uma academia ao ar livre novinha aos valores de R$ 18 mil reais. Outros R$ 270 mil reais v\u00e3o para ampliar e melhorar a assist\u00eancia ambulatorial e hospitalar nas comunidades do Ribeir\u00e3o do Lipa, Jardim Ara\u00e7\u00e1 e Jardim Colorado.<\/div>\n<div><\/div>\n<div>O vereador que \u00e9 filiado ao DC, tamb\u00e9m seguindo os outros parlamentares, investiu o valor de R$ 30 mil no Hospital Santa Helena, custeando despesa com material e medicamento.<\/div>\n<div><\/div>\n<div>Mais investimentos atrav\u00e9s das emendas impositiva ser\u00e3o liberados nesse ano, e mais uma vez pela atua\u00e7\u00e3o do vereador Clebinho,\u00a0 que\u00a0 n\u00e3o se esqueceu do saneamento b\u00e1sico,\u00a0 e destinou R$ 80 mil reais para obras de esgotamento sanit\u00e1rio na Vila Santa Izabel, melhorando\u00a0 nesse setor.<\/div>\n<div><\/div>\n<div>\u201cAinda na \u00e1rea cultural estamos propondo a quantia de 45 mil para eventos culturais e religiosos na capital\u201d, ainda detalhou Clebinho, que assinou ainda\u00a0 emenda impositiva no valor R$ 30 mil reais, ao Rotary Clube Bandeirantes, como subeven\u00e7\u00f5es sociais, e tamb\u00e9m a constru\u00e7\u00e3o de\u00a0 uma academia\u00a0 ao ar livre no Residencial Milton Figueiredo, no valor do investimentos R$ 20 mil reais.<\/div>\n<div><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por: Ad\u00e3o de Oliveira &#8211; <a href=\"http:\/\/www.camaracuiaba.mt.gov.br\/\">C\u00e2mara Municipal de Cuiab\u00e1<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para a execu\u00e7\u00e3o do Or\u00e7amento Geral Anual para Cuiab\u00e1 nesse ano de 2020, o montante &hellip;<\/p>\n","protected":false},"author":4,"featured_media":22694,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-22693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/22693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=22693"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/22693\/revisions"}],"predecessor-version":[{"id":22695,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/22693\/revisions\/22695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/22694"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=22693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=22693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=22693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}