{"id":22759,"date":"2020-01-27T09:47:29","date_gmt":"2020-01-27T13:47:29","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=22759"},"modified":"2020-01-27T09:47:29","modified_gmt":"2020-01-27T13:47:29","slug":"residencial-santa-terezinha-recebe-o-projeto-arboriza-cuiaba","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/residencial-santa-terezinha-recebe-o-projeto-arboriza-cuiaba\/","title":{"rendered":"Residencial Santa Terezinha recebe o Projeto \u2018Arboriza Cuiab\u00e1\u2019"},"content":{"rendered":"<div>Os moradores do Residencial Santa Terezinha, regi\u00e3o sul da Capital, receberam na manh\u00e3 deste s\u00e1bado (25) o Projeto \u2018Arboriza Cuiab\u00e1\u2019, que tem como objetivo central conscientizar e sensibilizar a popula\u00e7\u00e3o a plantar \u00e1rvores e construir um meio ambiente saud\u00e1vel, despertando a\u00e7\u00f5es que favore\u00e7am a melhoria da qualidade de vida e evitem a degrada\u00e7\u00e3o do meio ambiente.<\/div>\n<div><\/div>\n<div>Essa iniciativa partiu da Mesa Diretora da C\u00e2mara Municipal de Cuiab\u00e1, tendo a frente o presidente da Casa de Leis, vereador Misael Galv\u00e3o (PTB), que esteve presente no ato fazendo seu discurso de abertura dos trabalhos, juntamente com os vereadores Orivaldo da F\u00e1rmacia (Progressistas) e M\u00e1rio Nadaf (PV).<\/div>\n<div><\/div>\n<div>Logo ap\u00f3s, com toda a sua equipe, Misael fez o plantio da primeira muda, tendo ao seu lado duas crian\u00e7as do bairro que o acompanharam por toda a extens\u00e3o do plantio.<\/div>\n<div><\/div>\n<div>\u201cHoje estamos dando in\u00edcio ao projeto-piloto do \u2018Arboriza Cuiab\u00e1\u2019, que faz parte das a\u00e7\u00f5es do programa \u2018C\u00e2mara M\u00f3vel\u2019, a onde vamos levar toda a nossa estrutura aos bairros da Capital, ouvindo as pessoas, sabendo das suas necessidades, procurando auxiliar no que for poss\u00edvel, pois este \u00e9 o papel da C\u00e2mara Municipal. Estou muito feliz por estar aqui, nesta manh\u00e3 ensolarada, com minha equipe, fazendo esse plantio. \u00c9 muito gratificante poder contribuir para que Cuiab\u00e1 volte a ter o t\u00edtulo t\u00e3o merecido de Cidade Verde\u201d, destacou, emocionado, Misael Galv\u00e3o.<\/div>\n<div><\/div>\n<div>O Horto Florestal de Cuiab\u00e1, vinculado \u00e0 Secretaria Municipal de Meio Ambiente e Desenvolvimento Urbano, e a Secretaria Municipal de Servi\u00e7os Urbanos, se fazendo presente no plantio com o seu secret\u00e1rio Jos\u00e9 Roberto Stopa, foram os grandes parceiros desta a\u00e7\u00e3o in\u00e9dita. Foram disponibilizadas 500 mudas, entre \u00e1rvores frut\u00edferas e ornamentais. 200 foram doadas para os moradores da regi\u00e3o e 300 plantadas em um dos principais canteiros do Residencial, com aproximadamente 2.000 metros de extens\u00e3o.<\/div>\n<div><\/div>\n<div>\u201cAntes de mais nada quero parabenizar o presidente da C\u00e2mara Municipal de Cuiab\u00e1, vereador Misael Galv\u00e3o, todos os vereadores e os servidores do Legislativo que est\u00e3o dando um \u00f3timo exemplo de consci\u00eancia ambiental com esse projeto, o \u2018Arboriza Cuiab\u00e1\u2019. Iniciativas como essa s\u00e3o louv\u00e1veis pois nunca \u00e9 demais cuidarmos do nosso meio ambiente, e principalmente plantando \u00e1rvores, t\u00e3o importante para os animais sobreviverem e para o ar que respiramos. A Prefeitura de Cuiab\u00e1 \u00e9 e sempre ser\u00e1 parceira em a\u00e7\u00f5es positivas como essa, realizadas pelos vereadores de Cuiab\u00e1\u201d, frisou o secret\u00e1rio municipal de Servi\u00e7os Urbanos, Jos\u00e9 Roberto Stopa.<\/div>\n<div><\/div>\n<div>Para o presidente do Residencial Santa Terezinha, senhor M\u00e1rcio N\u00e9ris, a Mesa Diretora da C\u00e2mara Municipal est\u00e1 dando um belo exemplo para as futuras gera\u00e7\u00f5es, cuidando do meio ambiente. \u201cQuando os moradores aqui do Santa Terezinha ficaram sabendo que o nosso bairro foi escolhido pra receber esse projeto, a felicidade foi geral. Sofremos aqui com a falta de \u00e1rvores, quase n\u00e3o temos sombras por aqui. Agora com 300 mudas plantadas e mais 200 espelhadas pelas casas vamos ter um local com mais oxig\u00eanio, mais verde, mais sombras para as nossas crian\u00e7as brincarem. O vereador Misael Galv\u00e3o foi muito feliz em criar esse projeto, e n\u00f3s, moradores, mais felizes ainda por sermos os escolhidos para o ponta-p\u00e9 desse trabalho ambiental\u201d, justificou N\u00e9ris.<\/div>\n<div><\/div>\n<div>Cabe ressaltar que desde quinta-feira, dia 23 de janeiro, alguns servidores da C\u00e2mara Municipal estiveram antecipando os preparativos do plantio, quando resolveram \u201ccolocar a m\u00e3o na massa\u201d e preparar os canteiros que receberam as mudas. De acordo com o secret\u00e1rio geral do Parlamento Cuiabano, que \u00e9 respons\u00e1vel pelas tratativas necess\u00e1rias para implanta\u00e7\u00e3o do projeto \u2018Arborizar Cuiab\u00e1\u2019, tudo transcorreu dentro do programado e esperado.<\/div>\n<div><\/div>\n<div>\n<div>\u201cNosso pessoal est\u00e1 aqui no Residencial Santa Terezinha desde de anteontem, preparando tudo, com muita garra e dedica\u00e7\u00e3o, para que a comunidade pudesse participar da nossa a\u00e7\u00e3o ambiental, e isso \u00e9 muito gratificante. S\u00f3 temos que agradecer a cada servidor que se empenhou para o sucesso desse evento\u201d, concluiu o secret\u00e1rio geral da C\u00e2mara, Daniel Lima.<\/div>\n<div><\/div>\n<div>As \u00e1rvores s\u00e3o indispens\u00e1veis na natureza por possu\u00edrem diversas finalidades. Elas auxiliam na purifica\u00e7\u00e3o e umidade do ar, pois agem como sequestradoras de CO2, capturando gases t\u00f3xicos e devolvendo oxig\u00eanio para a atmosfera. Al\u00e9m disso, as \u00e1rvores trazem outros benef\u00edcios para v\u00e1rios ecossistemas e espa\u00e7os p\u00fablicos. Atenta a essa din\u00e2mica, a C\u00e2mara Municipal est\u00e1 fortalecendo os cuidados com o meio ambiente de Cuiab\u00e1, planejando a expans\u00e3o do projeto \u2018Arboriza Cuiab\u00e1\u2019 para outros bairros da Capital.<\/div>\n<div><\/div>\n<\/div>\n<div><\/div>\n<p>Por: Abra\u00e3o Ribeiro | <a href=\"http:\/\/www.camaracuiaba.mt.gov.br\/\">C\u00e2mara Municipal de Cuiab\u00e1<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os moradores do Residencial Santa Terezinha, regi\u00e3o sul da Capital, receberam na manh\u00e3 deste s\u00e1bado &hellip;<\/p>\n","protected":false},"author":4,"featured_media":22760,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,59,77],"tags":[],"class_list":["post-22759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news","category-destaque","category-estudo"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/22759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=22759"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/22759\/revisions"}],"predecessor-version":[{"id":22761,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/22759\/revisions\/22761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/22760"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=22759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=22759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=22759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}