{"id":22855,"date":"2020-01-31T08:11:32","date_gmt":"2020-01-31T12:11:32","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=22855"},"modified":"2020-01-31T08:11:32","modified_gmt":"2020-01-31T12:11:32","slug":"pecuaristas-seguram-boiada-e-preco-da-arroba-volta-a-subir-no-brasil","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/pecuaristas-seguram-boiada-e-preco-da-arroba-volta-a-subir-no-brasil\/","title":{"rendered":"Pecuaristas seguram boiada e pre\u00e7o da arroba volta a subir no Brasil"},"content":{"rendered":"<p>Os frigor\u00edficos encontram maior dificuldade na compra de gado e, ap\u00f3s quedas sucessivas, o mercado parece reagir<\/p>\n<p>O mercado f\u00edsico do boi gordo apresentou poucas varia\u00e7\u00f5es nesta quinta-feira, mas voltou a cair no Brasil. Segundo o analista de Safras &amp; Mercado, Fernando Henrique Iglesias, os frigor\u00edficos encontram maior dificuldade na compra de gado, natural frente a relut\u00e2ncia dos pecuaristas em negociar nos pre\u00e7os vigentes.<\/p>\n<div class=\"ad ad-float ad-300-250\">\n<div id=\"banner-300x250-area\">\n<h3><\/h3>\n<\/div>\n<\/div>\n<p>\u201cA capacidade de reten\u00e7\u00e3o segue positiva, avaliando a boa condi\u00e7\u00e3o das pastagens neste momento. Uma eventual recupera\u00e7\u00e3o da demanda no decorrer de fevereiro pode contribuir para a retomada do movimento de alta, no entanto, os patamares alcan\u00e7ados dificilmente v\u00e3o repetir os n\u00fameros do \u00faltimo m\u00eas de novembro\u201d, disse.<\/p>\n<p>Em S\u00e3o Paulo, pre\u00e7os subiram para R$ 187 a arroba para pagamento \u00e0 vista. Em Minas Gerais, pre\u00e7os de R$ 183 a arroba, em Uberaba, contra R$ 181 na quarta-feira. Em Mato Grosso do Sul, pre\u00e7os subiram de R$ 173 para R$ 175 a arroba, em Dourados. Em Goi\u00e1s, o pre\u00e7o indicado subiu de R$ 180 para R$ 182 a arroba em Goi\u00e2nia. J\u00e1 em Mato Grosso o pre\u00e7o ficou em R$ 173 a arroba em Cuiab\u00e1.<\/p>\n<h3><strong>Atacado<\/strong><\/h3>\n<p>O mercado atacadista volta a se deparar com acomoda\u00e7\u00e3o dos pre\u00e7os. \u201c\u00c9 importante destacar que o escoamento da carne apresenta alguns sinais de avan\u00e7o nessa semana, a reposi\u00e7\u00e3o tende a ser ainda mais efetiva durante a primeira quinzena do m\u00eas, per\u00edodo pautado pela entrada dos sal\u00e1rios, al\u00e9m do retorno \u00e0s aulas como motivador da demanda\u201d, finalizou.<\/p>\n<p>Corte traseiro segue precificado a R$ 13,05, por quilo. Corte dianteiro ainda \u00e9 cotado a R$ 10,40, por quilo. Ponta de agulha permanece cotada a R$ 9,70, por quilo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por:\u00a0\u00a0Ag\u00eancia Safras\u00a0| Foto:\u00a0Madson Maranh\u00e3o\u00a0| Fonte: <a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os frigor\u00edficos encontram maior dificuldade na compra de gado e, ap\u00f3s quedas sucessivas, o mercado &hellip;<\/p>\n","protected":false},"author":4,"featured_media":22856,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-22855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/22855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=22855"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/22855\/revisions"}],"predecessor-version":[{"id":22857,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/22855\/revisions\/22857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/22856"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=22855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=22855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=22855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}