{"id":23085,"date":"2020-02-13T09:35:06","date_gmt":"2020-02-13T13:35:06","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=23085"},"modified":"2020-02-13T09:35:06","modified_gmt":"2020-02-13T13:35:06","slug":"dia-d-contra-sarampo-e-realizado-neste-sabado-na-rede-sus-cuiaba","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/dia-d-contra-sarampo-e-realizado-neste-sabado-na-rede-sus-cuiaba\/","title":{"rendered":"\u2018Dia D\u2019 contra Sarampo \u00e9 realizado neste s\u00e1bado na rede SUS Cuiab\u00e1"},"content":{"rendered":"<p align=\"center\">A Secretaria Municipal de Sa\u00fade realiza neste s\u00e1bado (15), o \u201cDia D\u201d da Campanha Nacional de Vacina\u00e7\u00e3o contra o Sarampo.\u00a0Esta fase da campanha, que come\u00e7ou no \u00faltimo dia 10, contempla a faixa et\u00e1ria de cinco a 19 anos.<\/p>\n<p>De acordo com a Respons\u00e1vel T\u00e9cnica (RT) de Imuniza\u00e7\u00e3o da Secretaria de Sa\u00fade de Cuiab\u00e1, Sandra Horn, o p\u00fablico-alvo foi definido com base nas idades pontuadas pelos boletins epidemiol\u00f3gicos como mais suscept\u00edveis a desenvolverem a forma grave da doen\u00e7a, podendo inclusive levar \u00e0 morte.<\/p>\n<p>\u201cO Minist\u00e9rio da Sa\u00fade considerou as idades que, segundo as notifica\u00e7\u00f5es da vigil\u00e2ncia epidemiol\u00f3gica, apresentaram maior incid\u00eancia em desenvolver casos mais graves onde a possibilidade de \u00f3bitos \u00e9 de 0,80 por 100.000 habitantes\u201d, explicou Horn.<\/p>\n<p>A abertura oficial da campanha acontecer\u00e1 \u00e0s 8h30 na Unidade B\u00e1sica de Sa\u00fade do bairro Jardim Vit\u00f3ria I. Entretanto, em toda a cidade estar\u00e3o funcionando 67 salas de vacinas, incluindo tr\u00eas na \u00e1rea rural &#8211; no Distrito da Guia, Agua\u00e7u e Rio dos Peixes -, que re\u00fane as comunidades do Coxip\u00f3 do Ouro e Barreiro Branco. O hor\u00e1rio de atendimento em todas elas ser\u00e1 das 8h \u00e0s 17h.<\/p>\n<p><strong>Servi\u00e7o:<\/strong><\/p>\n<p>O que: Dia D de Vacina\u00e7\u00e3o contra Sarampo<\/p>\n<p>Quando:\u00a0S\u00e1bado (15), das 8h \u00e0s 17h<\/p>\n<p>Onde: Abertura oficial, unidade b\u00e1sica de Sa\u00fade Jardim Vit\u00f3ria I, Av. Central, 958 &#8211; \u00a0bairro Jardim Vit\u00f3ria<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por:\u00a0OZIANE RODRIGUES\u00a0| Foto:\u00a0Gusavo Duarte \u00a0| Fonte:\u00a0 <a href=\"http:\/\/www.cuiaba.mt.gov.br\/\">Prefeitura de Cuiab\u00e1<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria Municipal de Sa\u00fade realiza neste s\u00e1bado (15), o \u201cDia D\u201d da Campanha Nacional &hellip;<\/p>\n","protected":false},"author":4,"featured_media":23086,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,59,77],"tags":[],"class_list":["post-23085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news","category-destaque","category-estudo"],"wps_subtitle":"Abertura oficial da campanha ser\u00e1 \u00e0s 8h30 na Unidade B\u00e1sica de Sa\u00fade do bairro Jardim Vit\u00f3ria I","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=23085"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23085\/revisions"}],"predecessor-version":[{"id":23087,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23085\/revisions\/23087"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/23086"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=23085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=23085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=23085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}