{"id":23186,"date":"2020-02-19T14:08:15","date_gmt":"2020-02-19T18:08:15","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=23186"},"modified":"2020-02-19T14:08:15","modified_gmt":"2020-02-19T18:08:15","slug":"secretaria-recebe-computadores-para-escola-do-servidor-atividades-comecam-neste-ano","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/secretaria-recebe-computadores-para-escola-do-servidor-atividades-comecam-neste-ano\/","title":{"rendered":"Secretaria recebe computadores para Escola do Servidor; atividades come\u00e7am neste ano"},"content":{"rendered":"<p>A Secretaria de Gest\u00e3o avan\u00e7a na cria\u00e7\u00e3o da Escola do Servidor. Na \u00faltima semana a Pasta recebeu os computadores que integrar\u00e3o os laborat\u00f3rios de inform\u00e1tica da unidade, localizada na Avenida Get\u00falio Vargas. O espa\u00e7o servir\u00e1 como ambiente de capacita\u00e7\u00e3o e conv\u00edvio e oferecer\u00e1 cursos aos mais de 18 mil servidores do Munic\u00edpio.<\/p>\n<p>De acordo com a secret\u00e1ria de Gest\u00e3o, Ozenira Felix, o projeto de lei que prev\u00ea a funda\u00e7\u00e3o da Escola deve ser aprovado na C\u00e2mara Municipal nas pr\u00f3ximas semanas. Al\u00e9m de laborat\u00f3rios o local contar\u00e1 ainda com audit\u00f3rio, biblioteca e restaurante. A expectativa \u00e9 de que at\u00e9 julho as atividades tenham sido iniciadas.<\/p>\n<p>Ela explica que as capacita\u00e7\u00f5es atender\u00e3o a todas as secretarias, que passar\u00e3o a concentrar estas iniciativas em um \u00fanico lugar. Isso aumenta o controle da gest\u00e3o, que pode aproveitar melhor cada qualifica\u00e7\u00e3o. \u201c\u00c0s vezes uma capacita\u00e7\u00e3o serve para mais de uma secretaria, ent\u00e3o podemos aproveit\u00e1-la para diversos setores.\u201d<\/p>\n<p>Para isso, foi realizado um levantamento de necessidade de capacita\u00e7\u00e3o. Assim, os cursos ser\u00e3o oferecidos conforme as principais demandas da Prefeitura. \u201cCom a pesquisa realizada entre os setores conseguimos diagnosticar as principais necessidades em cada um. Deste modo, trabalharemos em cima dos pontos fracos.\u201d<\/p>\n<p>O projeto \u00e9 uma das promessas de campanha do preito Emanuel Pinheiro e vem sendo desenvolvido desde 2017. A proposta tamb\u00e9m inclui a oferta de cursos online e parcerias com artistas regionais para o lan\u00e7amento de exposi\u00e7\u00f5es.<\/p>\n<p>Com rela\u00e7\u00e3o \u00e0s aulas, Ozenira explica que ideia \u00e9 tamb\u00e9m aproveitar o quadro da gest\u00e3o por meio de um programa de instrutoria. \u201cNossos profissionais de carreira, com um grau de conhecimento maior, ir\u00e3o capacitar os colegas de seus setores. Esta \u00e9 uma maneira de reconhecer e motivar estes talentos\u201d, finaliza.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por:\u00a0ANDR\u00c9 GARCIA SANTANA\u00a0| Foto: Luiz Alves\u00a0\u00a0|\u00a0 Fonte: <a href=\"http:\/\/www.cuiaba.mt.gov.br\/\">Prefeitura de Cuiab\u00e1<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Gest\u00e3o avan\u00e7a na cria\u00e7\u00e3o da Escola do Servidor. Na \u00faltima semana a &hellip;<\/p>\n","protected":false},"author":4,"featured_media":23187,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,59,77],"tags":[],"class_list":["post-23186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news","category-destaque","category-estudo"],"wps_subtitle":"Al\u00e9m de laborat\u00f3rios o local contar\u00e1 ainda com audit\u00f3rio, biblioteca e restaurante","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=23186"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23186\/revisions"}],"predecessor-version":[{"id":23188,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23186\/revisions\/23188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/23187"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=23186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=23186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=23186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}