{"id":23217,"date":"2020-02-20T09:27:50","date_gmt":"2020-02-20T13:27:50","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=23217"},"modified":"2020-02-20T09:27:50","modified_gmt":"2020-02-20T13:27:50","slug":"tenho-certeza-que-esse-sera-um-ano-de-entregas-do-governo-para-o-social-afirma-deputado","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/tenho-certeza-que-esse-sera-um-ano-de-entregas-do-governo-para-o-social-afirma-deputado\/","title":{"rendered":"\u201cTenho certeza que esse ser\u00e1 um ano de entregas do Governo para o social\u201d, afirma deputado"},"content":{"rendered":"<p>O deputado estadual Max Russi afirmou ter certeza que, neste ano, o Governo do Estado promover\u00e1 muitas entregas para a \u00e1rea social. A declara\u00e7\u00e3o foi dada durante reuni\u00e3o promovida pelo Governo,\u00a0que contou com mais de 400 lideran\u00e7as do movimento comunit\u00e1rio de todo o Estado, nesta ter\u00e7a-feira (18).<\/p>\n<p>O evento teve\u00a0a presen\u00e7a do governador Mauro Mendes; do secret\u00e1rio-chefe da Casa Civil, Mauro Carvalho; do secret\u00e1rio-chefe do Gabinete de Governo, Alberto Machado; da secret\u00e1ria de Assist\u00eancia Social e Cidadania, Rosamaria Carvalho, e de seus adjuntos; e al\u00e9m de Russi,\u00a0dos deputados Carlos Avalone, Paulo Ara\u00fajo e Ondanir Bortolini, o Nininho.<\/p>\n<p>\u201cEsse ano j\u00e1 existe uma expectativa muito grande da comunidade e tenho certeza que ser\u00e1 um ano de entregas. O governador recriar a [Secretaria] Adjunta de Assuntos Comunit\u00e1rios \u00e9 muito importante, porque essa adjunta faz a defesa da comunidade dentro do Governo. Faz a interlocu\u00e7\u00e3o aqui dentro\u201d, ressaltou Max Russi, ao lembrar a promessa de campanha cumprida pelo governador.<\/p>\n<p>Durante o evento, o governador Mauro Mendes ouviu as demandas dos representantes comunit\u00e1rios e apresentou as a\u00e7\u00f5es j\u00e1 realizadas em 2019, al\u00e9m das entregas planejadas para 2020.<\/p>\n<p>Entre as principais a\u00e7\u00f5es em prol do social, o chefe do Executivo destacou o projeto SER Crian\u00e7a, levou lazer e recrea\u00e7\u00e3o para crian\u00e7as em vulnerabilidade; o programa Aconchego, que distribuiu mais de 100 mil cobertores, e a Arena Encantada, que arrecadou mais de 83 toneladas de alimentos, tendo p\u00fablico superior a 230 mil pessoas.<\/p>\n<p>Al\u00e9m disso, o governador ressaltou as a\u00e7\u00f5es nas \u00e1reas de Infraestrutura, Sa\u00fade e Educa\u00e7\u00e3o, que geram reflexo direto na melhoria da qualidade de vida de quem mais precisa, a exemplo das 64 obras de infraestrutura conclu\u00eddas, com investimento de R$ 496 milh\u00f5es, e outras 119 em andamento em mais de 100 munic\u00edpios; 82 obras em andamento na educa\u00e7\u00e3o, com 13 novas escolas constru\u00eddas, 11 constru\u00e7\u00f5es ou reformas de quadras, 18 reformas gerais e previs\u00e3o de climatiza\u00e7\u00e3o de 40 unidades; e os repasses em dia para os 141 munic\u00edpios que, somente em 2019, somaram R$ 305 milh\u00f5es, com mais R$ 120 milh\u00f5es oriundos de d\u00edvidas de anos anteriores, al\u00e9m da inaugura\u00e7\u00e3o do Hospital Estadual Santa Casa e das obras em cinco hospitais regionais (Sorriso, Sinop, Alta Floresta, Rondon\u00f3polis e Metropolitano).<\/p>\n<p>\u201cQuero parabeniz\u00e1-lo por esse avan\u00e7o e essa evolu\u00e7\u00e3o que est\u00e1 sendo feita. Infelizmente ainda existe grande desigualdade, com homens e mulheres que n\u00e3o conseguem ter acesso m\u00ednimo a educa\u00e7\u00e3o, moradia e alimenta\u00e7\u00e3o. \u00c9 uma realidade que o movimento comunit\u00e1rio conhece muito bem. Temos uma primeira-dama muito atuante, e muito forte no social. E tenho certeza que o senhor vai deixar um grande legado nessa \u00e1rea. N\u00e3o um social de entregas, mas um social que realmente vai diminuir a extrema pobreza e que vai proporcionar mais oportunidade. O objetivo do Estado \u00e9 diminuir as desigualdades E temos que oferecer o m\u00ednimo para quem n\u00e3o tem acesso\u201d, pontuou Russi.<\/p>\n<p>Para o deputado Nininho, a conduta do Governo do Estado em ouvir as demandas dos l\u00edderes comunit\u00e1rios fortalece ainda mais a interlocu\u00e7\u00e3o com o cidad\u00e3o, que \u00e9 para quem o Estado precisa priorizar.<\/p>\n<p>Ouvir esses l\u00edderes \u00e9 de grande import\u00e2ncia para a sua gest\u00e3o, para saber o que essa popula\u00e7\u00e3o almeja, quais s\u00e3o as demandas mais importantes para esses cidad\u00e3os que representam seus bairros, cidades e a popula\u00e7\u00e3o do estado. N\u00e3o tenho d\u00favida que o senhor vem fazendo a diferen\u00e7a. Avan\u00e7ou muito nesse primeiro ano em rela\u00e7\u00e3o \u00e0 sa\u00fade, que estava um caos, na regulariza\u00e7\u00e3o fundi\u00e1ria, que d\u00e1 mais dignidade a essas pessoas. Nossa primeira-dama \u00e9 acess\u00edvel e demonstrou que tem voca\u00e7\u00e3o de fazer o bem e ajudar as pessoas menos favorecidas no nosso estado\u201d, declarou.<\/p>\n<p>Para o deputado Paulo Ara\u00fajo, a reuni\u00e3o mostra que os movimentos sociais est\u00e3o sendo cada vez mais reconhecidos e valorizados pelo Governo do Estado.<\/p>\n<p>\u201cA Assembleia Legislativa est\u00e1 \u00e0 disposi\u00e7\u00e3o para colaborar com o Estado para poder fazer o que precisa ser feito. Com essas a\u00e7\u00f5es, o Governo vai entregar um Estado infinitamente melhor\u201d, afirmou.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: <a href=\"https:\/\/odocumento.com.br\/\">Odocumento<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O deputado estadual Max Russi afirmou ter certeza que, neste ano, o Governo do Estado &hellip;<\/p>\n","protected":false},"author":4,"featured_media":23218,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-23217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"Max Russi afirmou que a gest\u00e3o tem aprimorado as pol\u00edticas p\u00fablicas voltadas \u00e0 popula\u00e7\u00e3o mais carente","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=23217"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23217\/revisions"}],"predecessor-version":[{"id":23219,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23217\/revisions\/23219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/23218"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=23217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=23217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=23217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}