{"id":23542,"date":"2020-03-11T10:25:39","date_gmt":"2020-03-11T14:25:39","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=23542"},"modified":"2020-03-11T10:25:39","modified_gmt":"2020-03-11T14:25:39","slug":"preco-do-milho-atinge-novo-recorde-e-e-cotado-em-quase-r-56-por-saca","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/preco-do-milho-atinge-novo-recorde-e-e-cotado-em-quase-r-56-por-saca\/","title":{"rendered":"Pre\u00e7o do milho atinge novo recorde e \u00e9 cotado em quase R$ 56 por saca"},"content":{"rendered":"<p>Os pre\u00e7os do milho, medidos pelo indicador Esalq\/BM&amp;fBovespa, atingiram novo recorde no fechamento da ter\u00e7a-feira, 10. Segundo o Centro de Estudos Avan\u00e7ados em Economia Aplicada (Cepea), a saca do cereal fechou o dia a R$ 55,83.<\/p>\n<p>Essa disparada nos pre\u00e7os \u00e9 explicada pelas exporta\u00e7\u00f5es recordes do gr\u00e3o em 2019, estoques de passagem menores e demanda aquecida.\u00a0Al\u00e9m disso, com o avan\u00e7o da colheita da soja, produtores rurais optam por n\u00e3o comercializar o gr\u00e3o neste momento, o que for\u00e7a novos movimentos de alta.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: <a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os pre\u00e7os do milho, medidos pelo indicador Esalq\/BM&amp;fBovespa, atingiram novo recorde no fechamento da ter\u00e7a-feira, &hellip;<\/p>\n","protected":false},"author":4,"featured_media":23543,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-23542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=23542"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23542\/revisions"}],"predecessor-version":[{"id":23544,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23542\/revisions\/23544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/23543"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=23542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=23542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=23542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}