{"id":23592,"date":"2020-03-12T09:56:34","date_gmt":"2020-03-12T13:56:34","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=23592"},"modified":"2020-03-12T09:56:34","modified_gmt":"2020-03-12T13:56:34","slug":"dem-lanca-julio-campos-e-dilmar-dal-bosco-candidatos-as-eleicoes-suplementares-do-senado","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/dem-lanca-julio-campos-e-dilmar-dal-bosco-candidatos-as-eleicoes-suplementares-do-senado\/","title":{"rendered":"DEM lan\u00e7a J\u00falio Campos e Dilmar Dal Bosco candidatos \u00e0s elei\u00e7\u00f5es suplementares do Senado"},"content":{"rendered":"<p>Os Democratas (DEM) homologou na noite desta quarta (11) a candidatura do ex-governador J\u00falio Campos ao Senado da Rep\u00fablica, em conven\u00e7\u00e3o no Centro de Eventos do Pantanal.<\/p>\n<p>O partido definiu chapa completa com o deputado Dilmar Dal Bosco (DEM) como primeiro suplente e Neurilan Fraga Filho (PL), presidente da AMM, como segundo suplente, mas neste caso da segunda supl\u00eancia, que \u00e9 uma indica\u00e7\u00e3o do senador\u00a0 Wellington Fagundes (PL), o martelo ficou de ser batido nesta quinta-feira (12).<\/p>\n<p>-\u201cN\u00f3s temos o nome que vai representar todo Mato Grosso com sabedoria e experi\u00eancia\u201d, disse o presidente da Assembleia Legislativa, deputado estadual Eduardo Botelho, ap\u00f3s a homologa\u00e7\u00e3o.<\/p>\n<p>O PTB esteve presente com o deputado Emanuelzinho Pinheiro, junto com vereadores. O governador Mauro Mendes n\u00e3o participou do encontro, pois cumpria agenda de inaugura\u00e7\u00e3o da escola estadual Coronel Antonio Paes de Barros, em Bar\u00e3o do Melga\u00e7o. Cerca de mil pessoas entre lideran\u00e7as e militantes participaram do evento.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0\u00a0<strong>FL\u00c1VIO GARCIA\/ Especial para<\/strong>\u00a0\u00a0<a href=\"https:\/\/odocumento.com.br\/\">Odocumento<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os Democratas (DEM) homologou na noite desta quarta (11) a candidatura do ex-governador J\u00falio Campos &hellip;<\/p>\n","protected":false},"author":4,"featured_media":23593,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-23592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"J\u00falio e Dilmar s\u00e3o cabe\u00e7as da chapa do DEM para elei\u00e7\u00f5es ao Senado","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=23592"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23592\/revisions"}],"predecessor-version":[{"id":23594,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23592\/revisions\/23594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/23593"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=23592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=23592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=23592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}