{"id":23647,"date":"2020-03-16T12:06:01","date_gmt":"2020-03-16T16:06:01","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=23647"},"modified":"2020-03-16T12:06:01","modified_gmt":"2020-03-16T16:06:01","slug":"projeto-de-lei-deve-instituir-o-estatuto-do-portador-de-diabetes-em-mato-grosso","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/projeto-de-lei-deve-instituir-o-estatuto-do-portador-de-diabetes-em-mato-grosso\/","title":{"rendered":"Projeto de lei deve instituir o estatuto do portador de diabetes em Mato Grosso"},"content":{"rendered":"<p>O deputado estadual Dr. Jo\u00e3o (MDB) apresentou, em sess\u00e3o plen\u00e1ria, o<a href=\"https:\/\/www.al.mt.gov.br\/storage\/webdisco\/cp\/20200309081721154100.pdf\" target=\"_blank\" rel=\"noopener\">\u00a0Projeto de Lei n\u00ba197\/2020<\/a>,\u00a0que deve instituir no Estado o Estatuto do Portador de Diabetes ao estabelecer diretrizes, normas e crit\u00e9rios b\u00e1sicos para assegurar, promover, proteger e resguardar o exerc\u00edcio pleno dos direitos das pessoas com diabetes.<\/p>\n<p>O diabetes \u00e9 uma doen\u00e7a cr\u00f4nica incur\u00e1vel, que necessita de tratamento e controle adequado. O tratamento requer restri\u00e7\u00f5es na alimenta\u00e7\u00e3o do paciente e, em alguns casos, o uso de medicamentos. A doen\u00e7a atinge n\u00e3o s\u00f3 adultos, mas tamb\u00e9m crian\u00e7as e adolescentes. O portador da doen\u00e7a n\u00e3o consegue degradar mol\u00e9culas de glicose corretamente ou em velocidade suficiente. A glicose \u00e9 um tipo de a\u00e7\u00facar b\u00e1sico que ingerimos na alimenta\u00e7\u00e3o, e \u00e9 essencial para a vida. A alta taxa de glicose circulante no sangue, entretanto, pode provocar danos em \u00f3rg\u00e3os como os rins, al\u00e9m de poder levar \u00e0 amputa\u00e7\u00e3o de membros inferiores e causar cegueira. Pacientes com hiperglicemia s\u00e3o mais suscet\u00edveis a ataques card\u00edacos ou derrames.<\/p>\n<p>S\u00f3 em Mato Grosso, a doen\u00e7a atinge cerca de 184 mil pessoas, entre adultos e crian\u00e7as. No Brasil, 13 milh\u00f5es de pessoas s\u00e3o portadoras da doen\u00e7a e a Organiza\u00e7\u00e3o Mundial de Sa\u00fade (OMS) estima que, at\u00e9 2030, existam 300 milh\u00f5es de diab\u00e9ticos em todo o mundo. Por\u00e9m, metade dos portadores n\u00e3o sabe que tem o problema. Entre 2010 e 2016, o diabetes j\u00e1 vitimou 5.586 pessoas no Mato Grosso.<\/p>\n<p>A diabetes se divide em duas categorias, os tipos 1 e 2. A primeira \u00e9 uma forma de diabetes relacionada ao sistema autoimune, em geral identificada na inf\u00e2ncia ou adolesc\u00eancia. As c\u00e9lulas respons\u00e1veis pela defesa do organismo acabam atacando outras, capazes de sintetizar insulina, por causa de um defeito no sistema imunol\u00f3gico. Os pacientes diagnosticados com essa varia\u00e7\u00e3o s\u00e3o chamados de insulinodependentes, pois precisam fazer uma reposi\u00e7\u00e3o da insulina, al\u00e9m de se tratarem com outros medicamentos, adotarem alimenta\u00e7\u00e3o balanceada e realizarem atividade f\u00edsica. Na diabetes do tipo 2, a administra\u00e7\u00e3o de insulina \u00e9 necess\u00e1ria apenas em alguns casos. A maior incid\u00eancia de diabetes se concentra nesse grupo, que \u00e9 quando o organismo n\u00e3o produz insulina suficiente para controlar a taxa de a\u00e7\u00facar no sangue, ou n\u00e3o \u00e9 capaz de usar adequadamente a que produz.<\/p>\n<p>O gasto com a doen\u00e7a chega pr\u00f3ximo aos R$ 100 bilh\u00f5es por ano: al\u00e9m do grande n\u00famero de diagnosticados, o pre\u00e7o da insulina e dos medicamentos para o tratamento s\u00e3o muito elevados. Para uma pessoa que se trata exclusivamente com insulina, o custo hoje fica entre R$ 500 a R$ 800 por m\u00eas, dependendo do tipo de medicamento utilizado, se adquirido em farm\u00e1cias comerciais. O programa Farm\u00e1cia Popular disponibiliza algumas op\u00e7\u00f5es de tratamento, com medicamentos gen\u00e9ricos orais usados por pessoas com diabetes tipo 2, mas falta muito investimento em sa\u00fade.<\/p>\n<p>Outro fator que aumenta expressivamente o custo, principalmente pensando em sa\u00fade p\u00fablica, \u00e9 a presen\u00e7a de complica\u00e7\u00f5es do diabetes, que podem ser consequ\u00eancia de um mau controle da doen\u00e7a por um per\u00edodo prolongado. As complica\u00e7\u00f5es advindas do mau controle do diabetes podem ser microvasculares, com destaque para a nefropatia diab\u00e9tica, que pode levar \u00e0 insufici\u00eancia renal e necessidade de di\u00e1lise e transplante de rins, ou \u00e0 retinopatia diab\u00e9tica, que pode levar a um comprometimento da vis\u00e3o e cegueira.<\/p>\n<p>Para o deputado Dr.Jo\u00e3o, com a melhoria nas padroniza\u00e7\u00f5es de tratamento, os pacientes ter\u00e3o uma maior ades\u00e3o ao seu tratamento, que hoje tamb\u00e9m \u00e9 outro ponto cr\u00edtico. Al\u00e9m disso, com a utiliza\u00e7\u00e3o de tecnologias, ser\u00e1 poss\u00edvel obter dados da sa\u00fade p\u00fablica e privada para nortear melhor as a\u00e7\u00f5es necess\u00e1rias para melhoria desse cen\u00e1rio no pa\u00eds.<\/p>\n<p>\u201cSer reconhecido e respeitado como cidad\u00e3o pode n\u00e3o curar a doen\u00e7a, mas encoraja o paciente a conviver com a sobrecarga que ela acarreta. Devemos ter em mente que o paciente com diabetes, por todo esse sofrimento multifacetado a que \u00e9 exposto, tem o direito de uma vida digna. Desta forma, \u00e9 necess\u00e1rio que a Casa Legislativa analise atenciosamente esta quest\u00e3o, uma vez que, a\u00e7\u00f5es como estas, podem, ao menos, amenizar o sofrimento pelos quais passam as pessoas portadoras de referida doen\u00e7a,\u201d enfatizou o parlamentar.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por:\u00a0\u00a0MICHELLE DAS NEVES MOURA\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 \u00a0<i>Ronaldo Mazza\u00a0 \u00a0|\u00a0 Fonte:\u00a0 <a href=\"https:\/\/www.al.mt.gov.br\/\">ALMT<\/a><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O deputado estadual Dr. Jo\u00e3o (MDB) apresentou, em sess\u00e3o plen\u00e1ria, o\u00a0Projeto de Lei n\u00ba197\/2020,\u00a0que deve &hellip;<\/p>\n","protected":false},"author":4,"featured_media":23648,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,59,77],"tags":[],"class_list":["post-23647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news","category-destaque","category-estudo"],"wps_subtitle":"O objetivo \u00e9 estabelecer crit\u00e9rios b\u00e1sicos para proteger e resguardar o exerc\u00edcio pleno dos direitos das pessoas com diabetes","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=23647"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23647\/revisions"}],"predecessor-version":[{"id":23649,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23647\/revisions\/23649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/23648"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=23647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=23647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=23647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}