{"id":23856,"date":"2020-03-25T10:19:40","date_gmt":"2020-03-25T14:19:40","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=23856"},"modified":"2020-03-25T10:19:40","modified_gmt":"2020-03-25T14:19:40","slug":"camara-sugere-prorrogacao-no-vencimento-do-iptu-e-desconto-de-50-na-taxa-de-esgoto","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/camara-sugere-prorrogacao-no-vencimento-do-iptu-e-desconto-de-50-na-taxa-de-esgoto\/","title":{"rendered":"C\u00e2mara sugere prorroga\u00e7\u00e3o no vencimento do IPTU e desconto de 50% na taxa de esgoto"},"content":{"rendered":"<div>O presidente da C\u00e2mara Municipal de Cuiab\u00e1, vereador Misael Galv\u00e3o (PTB), encaminhou um novo of\u00edcio ao prefeito Emanuel Pinheiro (MDB) sugerindo a implanta\u00e7\u00e3o de medidas que venham a minimizar o impacto econ\u00f4mico e social que vem sendo causado pelo novo Coronav\u00edrus (Covid-19).<\/div>\n<div><\/div>\n<div>Os encaminhamentos foram decididos pela Mesa Diretora e pelo Col\u00e9gio de L\u00edderes. O of\u00edcio protocolado nesta ter\u00e7a-feira, dia 24. Dentre as sugest\u00f5es est\u00e1 a prorroga\u00e7\u00e3o do vencimento e da cobran\u00e7a do IPTU, e o desconto de 50% na taxa de esgoto.<\/div>\n<div><\/div>\n<div>\u201cTemos que levar em considera\u00e7\u00e3o esse momento delicado que tem afetado o cidad\u00e3o economicamene, tendo em vista a paralisa\u00e7\u00e3o da ind\u00fastria e do com\u00e9rcio, assim como o estado de calamidade decretado pelo Executivo\u201d, justificou o presidente.<\/div>\n<div><\/div>\n<div>Al\u00e9m disso, informou ao Executivo o desejo dos parlamentares de efetuarem o remanejamento das emendas impositivas apresentadas ao or\u00e7amento deste ano, as quais foram aproadas pela Casa de Leis em 2019. A inten\u00e7\u00e3o \u00e9 alocar os recursos na a\u00e9rea da sa\u00fade, para auxiliar a Prefeitura nas a\u00e7\u00f5es de combate ao v\u00edrus.<\/div>\n<div><\/div>\n<div>Nesta segunda-feira (24), o Parlamento Municipal j\u00e1 havia anunciado algumas medidas emergenciais, tais com a disponibiliza\u00e7\u00e3o dos 25 autom\u00f3veis e a van, locados pela Casa para atender as demandas administrativas das secretarias e dos vereadores.<\/div>\n<div><\/div>\n<div>Os ve\u00edculos foram cedidos \u00e0 Secretaria de Sa\u00fade do munic\u00edpio, assegurando 50 litros de combust\u00edveis por semana. Al\u00e9m disso, tamb\u00e9m foi colocado a disposi\u00e7\u00e3o do Executivo o seu pr\u00e9dio para ser utilizado como retaguarda ou ponto de apoio para a sa\u00fade.<\/div>\n<div><\/div>\n<div>Por fim, a Casa de Leis ainda ir\u00e1 efetuar a devolu\u00e7\u00e3o de R$ 2 milh\u00f5es. O recurso dever\u00e1 ser destinado \u00e0 compra de insumos b\u00e1sicos para as unidades de sa\u00fade da Capital, tais como m\u00e1scaras, luvas, \u00e1lcool gel, entre outras coisas.<\/div>\n<div><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por: Kamila Arruda |\u00a0 Fonte: <a href=\"http:\/\/www.camaracuiaba.mt.gov.br\/\">C\u00e2mara Municipal de Cuiab\u00e1<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente da C\u00e2mara Municipal de Cuiab\u00e1, vereador Misael Galv\u00e3o (PTB), encaminhou um novo of\u00edcio &hellip;<\/p>\n","protected":false},"author":4,"featured_media":23857,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,59,77],"tags":[],"class_list":["post-23856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news","category-destaque","category-estudo"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=23856"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23856\/revisions"}],"predecessor-version":[{"id":23858,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23856\/revisions\/23858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/23857"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=23856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=23856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=23856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}