{"id":23876,"date":"2020-03-25T10:44:09","date_gmt":"2020-03-25T14:44:09","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=23876"},"modified":"2020-03-25T10:44:09","modified_gmt":"2020-03-25T14:44:09","slug":"governo-define-atividade-da-imprensa-como-essencial","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/governo-define-atividade-da-imprensa-como-essencial\/","title":{"rendered":"Governo define atividade da imprensa como essencial"},"content":{"rendered":"<div id=\"tps_slideContainer_193005\" class=\"theiaPostSlider_slides\">\n<div class=\"theiaPostSlider_preloadedSlide\">\n<div class=\"post-item-wrap\">\n<p>De acordo com o texto, dever\u00e3o ser resguardados o exerc\u00edcio pleno e o funcionamento de todos os meios de comunica\u00e7\u00e3o e divulga\u00e7\u00e3o dispon\u00edveis, \u201cinclu\u00eddos a radiodifus\u00e3o de sons e de imagens, a internet, os jornais e as revistas, entre outros\u201d. A medida visa garantir a difus\u00e3o de informa\u00e7\u00f5es \u00e0 popula\u00e7\u00e3o e tamb\u00e9m cumpre o princ\u00edpio constitucional da publicidade em rela\u00e7\u00e3o aos atos praticados pelo governo.<\/p>\n<p>Pelo decreto, est\u00e1 proibida a restri\u00e7\u00e3o \u00e0 circula\u00e7\u00e3o de trabalhadores da imprensa que possa afetar o funcionamento das atividades. Mas, na execu\u00e7\u00e3o dos servi\u00e7os, dever\u00e3o ser adotadas todas as cautelas para redu\u00e7\u00e3o da transmiss\u00e3o do novo coronav\u00edrus.<\/p>\n<p>Na\u00a0sexta-feira (20), o governo havia editado decreto com uma lista de\u00a0<a href=\"https:\/\/agenciabrasil.ebc.com.br\/geral\/noticia\/2020-03\/bolsonaro-edita-mp-e-decreto-para-definir-atividades-essenciais\" target=\"_blank\" rel=\"noopener noreferrer\">35 atividades essenciais<\/a>\u00a0durante a crise provocada pelo\u00a0covid-19, mas n\u00e3o incluiu a imprensa. Entre os\u00a0<a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/_ato2019-2022\/2020\/decreto\/D10282.htm\" target=\"_blank\" rel=\"noopener noreferrer\">servi\u00e7os j\u00e1 listados\u00a0<\/a>\u00a0est\u00e3o a assist\u00eancia \u00e0 sa\u00fade (inclu\u00eddos os servi\u00e7os m\u00e9dicos e hospitalares), o transporte intermunicipal, interestadual e internacional de passageiros e os servi\u00e7os de t\u00e1xi ou de aplicativo, servi\u00e7o de call center, capta\u00e7\u00e3o e tratamento de esgoto e lixo, servi\u00e7os funer\u00e1rios, compensa\u00e7\u00e3o banc\u00e1ria e servi\u00e7os n\u00e3o presenciais de institui\u00e7\u00f5es financeiras, fiscaliza\u00e7\u00e3o ambiental e fabrica\u00e7\u00e3o\u00a0e venda de produtos de sa\u00fade, higiene, alimentos e bebidas.<\/p>\n<\/div>\n<p class=\"alt-font font-italic my-2 small text-info\">Edi\u00e7\u00e3o: Gra\u00e7a Adjuto<\/p>\n<\/div>\n<\/div>\n<div class=\"theiaPostSlider_footer _footer\"><\/div>\n<p><a href=\"http:\/\/agenciabrasil.ebc.com.br\/politica\/noticia\/2020-03\/governo-define-atividade-da-imprensa-como-essencial\">Fonte: EBC Pol\u00edtica<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acordo com o texto, dever\u00e3o ser resguardados o exerc\u00edcio pleno e o funcionamento de &hellip;<\/p>\n","protected":false},"author":4,"featured_media":23877,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-23876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"O presidente Jair Bolsonaro definiu como essenciais as atividades e servi\u00e7os da imprensa como medida de enfrentamento \u00e0 pandemia de covid-19. O decreto foi publicado ontem (22) em edi\u00e7\u00e3o extra do Di\u00e1rio Oficial da Uni\u00e3o .","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=23876"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23876\/revisions"}],"predecessor-version":[{"id":23878,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/23876\/revisions\/23878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/23877"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=23876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=23876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=23876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}