{"id":24918,"date":"2020-05-12T10:06:51","date_gmt":"2020-05-12T14:06:51","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=24918"},"modified":"2020-05-12T10:06:51","modified_gmt":"2020-05-12T14:06:51","slug":"mp-de-contas-investiga-gastos-de-r-11-milhao-na-reforma-dos-casaroes-da-orla-do-porto","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/mp-de-contas-investiga-gastos-de-r-11-milhao-na-reforma-dos-casaroes-da-orla-do-porto\/","title":{"rendered":"MP de Contas investiga gastos de R$ 1,1 milh\u00e3o na reforma dos \u2018casar\u00f5es\u2019 da Orla do Porto"},"content":{"rendered":"<p>O Minist\u00e9rio P\u00fablico de Contas de Mato Grosso iniciou um Procedimento Apurat\u00f3rio Preliminar (PAP) com o objetivo de esclarecer supostas irregularidades praticadas na contrata\u00e7\u00e3o emergencial de empresa especializada em engenharia para a execu\u00e7\u00e3o dos servi\u00e7os de obra e reforma da estrutura decorativa em formato de casar\u00f5es na Orla do Porto, em Cuiab\u00e1, no valor total de R$ 1.151.791,16.<\/p>\n<p>O procedimento foi instaurado atrav\u00e9s da Portaria n\u00b0 12\/2020 assinado pelo Procurador de Contas Gustavo Coelho Deschamps e publicado no dia 8 de maio no Di\u00e1rio Oficial de Contas. De acordo com o Procurador, as informa\u00e7\u00f5es recebidas d\u00e3o conta de que as obra na decora\u00e7\u00e3o da Orla do Porto v\u00eam passando por processos intermin\u00e1veis de revitaliza\u00e7\u00e3o desde 2018. \u201cConsiderando o dever de observ\u00e2ncia \u00e0 Lei de Acesso \u00e0 Informa\u00e7\u00e3o e a aus\u00eancia de informa\u00e7\u00f5es ou documentos no portal da transpar\u00eancia do munic\u00edpio de Cuiab\u00e1, relativos ao referido procedimento, tomamos essas medidas para esclarecer o que realmente est\u00e1 ocorrendo com essa obra\u201d, disse Deschamps.<\/p>\n<p>O Procurador de Contas Gustavo Deschamps determinou a notifica\u00e7\u00e3o do Prefeito de Cuiab\u00e1, bem como do Secret\u00e1rio Municipal de Servi\u00e7os Urbanos para apresentarem considera\u00e7\u00f5es aos apontamentos feitos. Os notificados dever\u00e3o enviar documentos que comprovem a regularidade, economicidade e natureza dos recursos, assim como a \u00edntegra do procedimento administrativo realizado para a contrata\u00e7\u00e3o da obra. O Minist\u00e9rio P\u00fablico Estadual tamb\u00e9m foi oficiado para que tome ci\u00eancia dos fatos. O prazo para o envio dos documentos ao MPC-MT \u00e9 de 10 dias.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 <a href=\"https:\/\/odocumento.com.br\/\">Odocumento<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio P\u00fablico de Contas de Mato Grosso iniciou um Procedimento Apurat\u00f3rio Preliminar (PAP) com &hellip;<\/p>\n","protected":false},"author":4,"featured_media":24919,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-24918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"O Procurador de Contas Gustavo Coelho Deschamps, que abriu o inqu\u00e9rito","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/24918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=24918"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/24918\/revisions"}],"predecessor-version":[{"id":24920,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/24918\/revisions\/24920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/24919"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=24918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=24918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=24918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}