{"id":25008,"date":"2020-05-15T10:34:52","date_gmt":"2020-05-15T14:34:52","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=25008"},"modified":"2020-05-15T10:34:52","modified_gmt":"2020-05-15T14:34:52","slug":"sem-eventos-tradicionais-varzea-grande-faz-153-anos-nesta-sexta-feira-e-chega-perto-dos-300-mil-habitantes","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/sem-eventos-tradicionais-varzea-grande-faz-153-anos-nesta-sexta-feira-e-chega-perto-dos-300-mil-habitantes\/","title":{"rendered":"Sem eventos tradicionais, V\u00e1rzea Grande faz 153 anos nesta sexta-feira, e chega perto dos 300 mil habitantes"},"content":{"rendered":"<p>Nem a tradicional romaria de Nossa Senhora da Guia, nem eventos pol\u00edticos, desfile c\u00edvico como acontecia am anos anteriores. Nesse clima,\u00a0 a cidade completa nesta sext-feira (15) 153 anos de hist\u00f3ria.<\/p>\n<p>Decreto da prefeita Lucimar Campos, atendendo a recomend\u00e7\u00f5es das autoridades m\u00e9dicas, suspendeu todas s manifesta\u00e7\u00f5es com aglomera\u00e7\u00f5es. Em virte da pandemi da Covid-19, n\u00e3o haver\u00e1, sequer funcionamento de lojas e de bares, restaurantes, resumindo-se penas aos ervi\u00e7os essenciais e ao transporte p\u00fablico.<\/p>\n<p>V\u00e1rzea Grande tem tr\u00eas\u00a0 \u00a0mortes registrads pel Covid-219 e 66 est\u00e3o contaminados, conforme ddos da Secretaria Estadual de Sa\u00fade.<\/p>\n<p><strong>Veja hist\u00f3rico<\/strong><\/p>\n<p>V\u00e1rzea Grande pertence \u00e0 Regi\u00e3o Metropolitana do Vale do Rio Cuiab\u00e1 e as regi\u00f5es geografica Intermedi\u00e1ria e imediata de Cuiab\u00e1. Situada \u00e0 margem direita do Rio Cuiab\u00e1, est\u00e1 a 7 km a leste da capital mato-grossense e ocupa uma \u00e1rea de 938,057 km\u00b2. \u00c9 a segunda cidade mais populosa do estado, a 7\u00ba mais populosa da regi\u00e3o Centro-Oeste e a 97\u00b0 mais populosa do pa\u00eds, sua popula\u00e7\u00e3o estimada pelo IBGE para 1\u00b0 de julho de 2019 era de 284 971 habitantes.<\/p>\n<p>A sede tem uma temperatura m\u00e9dia anual de 25,9 \u00b0C e tendo como vegeta\u00e7\u00e3o predominante, uma cobertura nativa do cerrado bem como Floresta Amaz\u00f4nica. Em rela\u00e7\u00e3o \u00e0 frota automobil\u00edstica, em 2018 foram contabilizados 165 455 ve\u00edculos. Com uma taxa de urbaniza\u00e7\u00e3o da ordem de 98,46%, o munic\u00edpio contava, em 2009, com 51 estabelecimentos de sa\u00fade. O seu \u00cdndice de Desenvolvimento Humano (IDH) \u00e9 de 0,734 (2010), considerando como m\u00e9dio pelo Programa das Na\u00e7\u00f5es Unidas para o Desenvolvimento (PNUD) sendo o decimo terceiro entre os munic\u00edpios mato-grossense.<\/p>\n<p>V\u00e1rzea Grande foi fundada em 1867 no per\u00edodo da Guerra do Paraguai como um acampamento militar para o aprisionamento de cidad\u00e3os paraguaios residentes em Cuiab\u00e1 e cercania,[10] com o fim do conflito formou-se o povoado composto por soldados e prisioneiros paraguaios e vaqueiros, sendo em 4 de julho de 1874, foi inaugurada uma balsa, a primeira liga\u00e7\u00e3o da regi\u00e3o \u00e0 capital.[11] Em 1896 torna-se distrito de Cuiab\u00e1 e se emancipando com a promulga\u00e7\u00e3o da lei estadual n\u00ba 126 de 23 de setembro de 1948.[12][13] Nas d\u00e9cadas de 60, 70 e 80 houve o estimulo a Industrializa\u00e7\u00e3o, com uma pol\u00edtica de incentivos fiscais e doa\u00e7\u00f5es de \u00e1reas por parte da prefeitura e do Governo do Estado, nesse per\u00edodo ocorreu a atra\u00e7\u00e3o de ind\u00fastrias de bebidas, frigor\u00edficos e madeireiras, tornando a cidade no maior polo industrial de Mato Grosso.<\/p>\n<p>Atualmente, encontra-se sob conurba\u00e7\u00e3o com a capital Cuiab\u00e1, tendo 5 pontes (Julio Muller, Ponte Nova, Juscelino Kubitschek, S\u00e9rgio Motta e a M\u00e1rio Andreazza) como principal meio de deslocamento a cidade pelo Rio Cuiab\u00e1 e tamb\u00e9m sendo considerada \u201cporta de entrada\u201d para a Amaz\u00f4nia Legal, por estar pr\u00f3xima a Rodovia dos Imigrantes (trecho das BR-163 e BR-364) e a BR-070.[15][16] O munic\u00edpio possui o terceiro maior Produto Interno Bruto de Mato Grosso,[17] destaca-se como centro ind\u00fastrial e comercial e sendo um dos mais importantes polo atacadista[18] e tur\u00edstico[19] do estado. Abriga o Aeroporto Internacional de Cuiab\u00e1 (IATA: CGB, ICAO: SBCY), o principal aeroporto de Mato Grosso[20] e sediar\u00e1 o Parque Tecnol\u00f3gico Mato Grosso.<\/p>\n<p><em>Extra\u00eddo do Wikipedia<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por:\u00a0\u00a0<a title=\"Posts de Jorge Maciel\" href=\"https:\/\/odocumento.com.br\/author\/jorge-maciel\/\" rel=\"author\">Jorge Maciel<\/a>\u00a0 \u00a0|\u00a0 \u00a0Fonte:\u00a0 <a href=\"https:\/\/odocumento.com.br\/\">Odocumento<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nem a tradicional romaria de Nossa Senhora da Guia, nem eventos pol\u00edticos, desfile c\u00edvico como &hellip;<\/p>\n","protected":false},"author":4,"featured_media":25009,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-25008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=25008"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25008\/revisions"}],"predecessor-version":[{"id":25010,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25008\/revisions\/25010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/25009"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=25008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=25008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=25008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}