{"id":25048,"date":"2020-05-17T16:09:46","date_gmt":"2020-05-17T20:09:46","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=25048"},"modified":"2020-05-17T16:09:46","modified_gmt":"2020-05-17T20:09:46","slug":"legislativo-aprova-projeto-que-cria-renda-solidaria","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/legislativo-aprova-projeto-que-cria-renda-solidaria\/","title":{"rendered":"Legislativo aprova projeto que cria Renda Solid\u00e1ria"},"content":{"rendered":"<div>A C\u00e2mara Municipal de Cuiab\u00e1 aprovou durante sess\u00e3o extraordin\u00e1ria remota realizada no final da tarde deste s\u00e1bado, dia 16, um projeto de lei de autoria do Executivo Municipal, o qual cria o programa Renda Solid\u00e1ria.\u00a0 A medida garante o pagamento de um aux\u00edlio no valor de R$ 500 a ser pago aos feirantes em geral, carroceiros, catadores de recicl\u00e1veis, transporte escolar e ambulantes e demais comerciantes de g\u00eanero aliment\u00edcio que desenvolvam atividades em logradouros p\u00fablicos.<\/div>\n<div><\/div>\n<div>A mensagem foi aprovada por 22 votos. Para o presidente do Parlamento Municipal, vereador Misael Galv\u00e3o (PTB) este aux\u00edlio ir\u00e1 ajudar a muitas fam\u00edlias carentes neste momento de dificuldades em decorr\u00eancia das medidas de isolamento adotada pelo Executivo devido ao novo Coronav\u00edrus (Covid-19).<\/div>\n<div><\/div>\n<div>\u201cEsses profissionais est\u00e3o sem poder trabalhar por conta dos decretos de isolamento. \u00c9 um momento delicado, temos que cuidar da sa\u00fade, mas n\u00e3o podemos deixar de olhar pro nosso povo que est\u00e1 sem poder trabalhar para sustentar sua fam\u00edlia. Ent\u00e3o, esse \u00e9 um grande avan\u00e7o que buscamos junto ao Executivo e estamos aprovando hoje\u201d, disse o petebista.<\/div>\n<div><\/div>\n<div>Misael ainda frisou que ir\u00e1 tratar junto ao prefeito Emanuel Pinheiro (MDB) sobre abranger o benef\u00edcio a outras categorias, tais como m\u00fasicos, gar\u00e7ons, educadores f\u00edsicos, pequenos produtores, entre outros. \u201cVamos pedir para que o l\u00edder do prefeito, vereador Luis Claudio interceda e marque uma reuni\u00e3o com prefeito para tratar de outras categorias. S\u00e3o categorias que est\u00e3o desprotegias nesse momento de pandemia e que precisa de um olhar especial do Executivo. Esse \u00e9 o papel do Legislativo, defender a popula\u00e7\u00e3o, os mais humildes. Vamos lutar para que outras categorias sejam contempladas em um novo projeto de lei\u201d, garantiu o presidente.<\/div>\n<div><\/div>\n<div>O Renda Solid\u00e1ria trata-se de um Programa Emergencial e Tempor\u00e1rio de Transfer\u00eancia de Renda. A medida consiste em um tipo de programa social, cujo objetivo \u00e9 a concess\u00e3o de aux\u00edlio financeiro sob determinadas condicionalidades.<\/div>\n<div><\/div>\n<div>O objetivo \u00e9 atender o cidad\u00e3o n\u00e3o incluso no sistema contributivo de prote\u00e7\u00e3o social, que apresentem vulnerabilidade decorrentes de ciclos de vida e\/ou incapacidade para a vida independe e para o trabalho.<\/div>\n<div><\/div>\n<div>Para terem direito ao recurso, estes profissionais ter\u00e3o que comprovar o exerc\u00edcio da atividade mediante inscri\u00e7\u00f5es nos cadastros municipais.<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por:\u00a0 Kamila Arruda &#8211; <a href=\"http:\/\/www.camaracuiaba.mt.gov.br\/\">C\u00e2mara Municipal de Cuiab\u00e1<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara Municipal de Cuiab\u00e1 aprovou durante sess\u00e3o extraordin\u00e1ria remota realizada no final da tarde &hellip;<\/p>\n","protected":false},"author":4,"featured_media":25049,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-25048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"O projeto de lei garante um aux\u00edlio de R$ 500 para determinados profissionais","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=25048"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25048\/revisions"}],"predecessor-version":[{"id":25050,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25048\/revisions\/25050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/25049"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=25048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=25048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=25048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}