{"id":25092,"date":"2020-05-19T10:38:55","date_gmt":"2020-05-19T14:38:55","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=25092"},"modified":"2020-05-19T10:38:55","modified_gmt":"2020-05-19T14:38:55","slug":"misael-encaminha-projeto-que-cria-o-programa-renda-solidaria-para-sancao-do-prefeito","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/misael-encaminha-projeto-que-cria-o-programa-renda-solidaria-para-sancao-do-prefeito\/","title":{"rendered":"Misael encaminha projeto que cria o programa Renda Solid\u00e1ria para san\u00e7\u00e3o do prefeito"},"content":{"rendered":"<div>O presidente da C\u00e2mara de Cuiab\u00e1, vereador Misael Galv\u00e3o (PTB), assinou na manh\u00e3 desta segunda-feira (18) a reda\u00e7\u00e3o final do projeto que cria o programa Renda Solid\u00e1ria. A mensagem foi aprovada por unanimidade no \u00faltimo s\u00e1bado (16) durante sess\u00e3o extraordin\u00e1ria, e agora segue para san\u00e7\u00e3o do prefeito Emanuel Pinheiro (MDB).<\/div>\n<div><\/div>\n<div>\u201cApreciamos essa mensagem em regime de urg\u00eancia devido a sua import\u00e2ncia. Muitos pais de fam\u00edlias est\u00e3o sem poder trabalhar por conta da pandemia. Este projeto beneficia algumas categorias e deve auxiliar a passar por este momento dif\u00edcil. Aprovamos no s\u00e1bado e j\u00e1 estamos encaminhando ao Executivo hoje para que o prefeito sancione o quanto antes\u201d, explicou o petebista.<\/div>\n<div><\/div>\n<div>A mat\u00e9ria, de autoria do Executivo Municipal foi aprovada com uma emenda aditiva. Proposta pelo vereador Lilo Pinheiro (PDT), a emenda garante que o Legislativo Cuiabano tenha um representante na Comiss\u00e3o que ir\u00e1 coordenar o Programa.<\/div>\n<div>Em suma, o programa permite a destina\u00e7\u00e3o do aux\u00edlio financeiro tempor\u00e1rio no valor de R$ 500 a ser pago aos feirantes em geral, carroceiros, catadores de recicl\u00e1veis, transporte escolar, ambulantes e demais comerciantes de g\u00eanero aliment\u00edcio que desenvolvam atividades em logradouros p\u00fablicos.<\/div>\n<div><\/div>\n<div>No total, cerca de 1.600 trabalhadores aut\u00f4nomos, inscritos no cadastro da Prefeitura de Cuiab\u00e1, devem ser beneficiados com a medida, uma vez que, para terem direito ao recurso, estes profissionais ter\u00e3o que comprovar o exerc\u00edcio da atividade mediante inscri\u00e7\u00f5es nos cadastros municipais.<\/div>\n<div><\/div>\n<div>O Renda Solid\u00e1ria trata-se de um Programa Emergencial e Tempor\u00e1rio de Transfer\u00eancia de Renda. A medida consiste em um tipo de programa social, cujo objetivo \u00e9 a concess\u00e3o de aux\u00edlio financeiro sob determinadas condicionalidades.<\/div>\n<div><\/div>\n<div>O objetivo \u00e9 atender o cidad\u00e3o n\u00e3o incluso no sistema contributivo de prote\u00e7\u00e3o social, que apresentem vulnerabilidade decorrentes de ciclos de vida e\/ou incapacidade para a vida independe e para o trabalho.<\/div>\n<div><\/div>\n<div>Com a aprova\u00e7\u00e3o da mensagem o Executivo fica autorizado a transferir um total de R$ 2.530.500 de seu or\u00e7amento para subsidiar o programa pelo per\u00edodo de 90 dias. Ou seja, os profissionais que preencherem os crit\u00e9rios, dever\u00e3o receber tr\u00eas parcelas de R$ 500.<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por:\u00a0 Kamila Arruda | Fonte:\u00a0 <a href=\"http:\/\/www.camaracuiaba.mt.gov.br\/\">C\u00e2mara Municipal de Cuiab\u00e1<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente da C\u00e2mara de Cuiab\u00e1, vereador Misael Galv\u00e3o (PTB), assinou na manh\u00e3 desta segunda-feira &hellip;<\/p>\n","protected":false},"author":4,"featured_media":25093,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,59,77],"tags":[],"class_list":["post-25092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news","category-destaque","category-estudo"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=25092"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25092\/revisions"}],"predecessor-version":[{"id":25094,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25092\/revisions\/25094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/25093"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=25092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=25092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=25092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}